{"id":6165,"date":"2014-11-21T18:23:44","date_gmt":"2014-11-21T18:23:44","guid":{"rendered":"https:\/\/wissen.science-and-fun.de\/kochen\/?p=6165"},"modified":"2014-11-20T19:03:54","modified_gmt":"2014-11-20T19:03:54","slug":"acras-de-morue-stockfisch-baellchen","status":"publish","type":"post","link":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/11\/21\/acras-de-morue-stockfisch-baellchen\/","title":{"rendered":"Acras de morue \/ Stockfisch-B\u00e4llchen"},"content":{"rendered":"<p><strong>Zutaten<\/strong><br \/>\n350 g  Stockfisch<br \/>\n1 Zwiebel; Viertel<br \/>\n3 EL Petersilie; gehackt<br \/>\n1 Chilischote, gr\u00fcn; entkernt<br \/>\n1\/4 TL Piment<br \/>\n1\/4 TL Pfeffer, schwarz; (I)<br \/>\n150 g  Mehl<br \/>\n1 Ei<br \/>\n1\/2 TL Salz<br \/>\n1\/2 TL Pfeffer, schwarz; (II)<br \/>\n100 ml  Milch; etwa<br \/>\n\u00d6l zum Ausbacken oder Kokosfett<\/p>\n<p><strong>Zubereitung<\/strong><br \/>\nFisch 24 Stunden w\u00e4ssern, dann mit dem Wasser zum Kochen bringen und 15 Minuten auf kleiner Flamme simmern lassen.<br \/>\nFisch von Haut und Gr\u00e4ten befreien (es sollen ca. 250 g Fischfleisch bleiben) und in St\u00fccke schneiden.<br \/>\nFischst\u00fccke mit Zwiebel, Petersilie, Chili, Piment, Pfeffer (I) und 4-5 Essl\u00f6ffel des Fischkochwassers p\u00fcrieren. In eine Sch\u00fcssel geben.<br \/>\nMehl mit Salz, Pfeffer (II), Ei und Milch zu einem sehr dickfl\u00fcssigen Teig verr\u00fchren und 30 Minuten stehen lassen. Dann mit<br \/>\ndem Fischp\u00fcree vermengen. Die Masse soll sehr z\u00e4h sein, eventuell noch etwas Mehl unterr\u00fchren.<br \/>\nFett in einem Topf erhitzen. Fischmasse Teel\u00f6ffelweise hineingleiten lassen, rundum goldbraun ausbacken.<\/p>\n<p>Acras reicht man als Snack zum Aperitif.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zutaten 350 g Stockfisch 1 Zwiebel; Viertel 3 EL Petersilie; gehackt 1 Chilischote, gr\u00fcn; entkernt 1\/4 TL Piment 1\/4 TL Pfeffer, schwarz; (I) 150 g Mehl 1 Ei 1\/2 TL Salz 1\/2 TL Pfeffer, schwarz; (II) 100 ml Milch; etwa \u00d6l zum Ausbacken oder Kokosfett Zubereitung Fisch 24 Stunden w\u00e4ssern, dann mit dem Wasser zum &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/11\/21\/acras-de-morue-stockfisch-baellchen\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[39],"tags":[755],"class_list":["post-6165","post","type-post","status-publish","format-standard","hentry","category-snack","tag-stockfisch","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acras de morue \/ Stockfisch-B\u00e4llchen<\/title>\n<meta name=\"description\" content=\"Acras de morue, ein leckerer Fisch-Snack\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/11\/21\/acras-de-morue-stockfisch-baellchen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acras de morue \/ Stockfisch-B\u00e4llchen\" \/>\n<meta property=\"og:description\" content=\"Acras de morue, ein leckerer Fisch-Snack\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/11\/21\/acras-de-morue-stockfisch-baellchen\/\" \/>\n<meta property=\"og:site_name\" content=\"Steffen&#039;s Haushaltsblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-21T18:23:44+00:00\" \/>\n<meta name=\"author\" content=\"Steffen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steffen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2014\\\/11\\\/21\\\/acras-de-morue-stockfisch-baellchen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2014\\\/11\\\/21\\\/acras-de-morue-stockfisch-baellchen\\\/\"},\"author\":{\"name\":\"Steffen\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"headline\":\"Acras de morue \\\/ Stockfisch-B\u00e4llchen\",\"datePublished\":\"2014-11-21T18:23:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2014\\\/11\\\/21\\\/acras-de-morue-stockfisch-baellchen\\\/\"},\"wordCount\":158,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"keywords\":[\"Stockfisch\"],\"articleSection\":[\"Snack\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2014\\\/11\\\/21\\\/acras-de-morue-stockfisch-baellchen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2014\\\/11\\\/21\\\/acras-de-morue-stockfisch-baellchen\\\/\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2014\\\/11\\\/21\\\/acras-de-morue-stockfisch-baellchen\\\/\",\"name\":\"Acras de morue \\\/ Stockfisch-B\u00e4llchen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\"},\"datePublished\":\"2014-11-21T18:23:44+00:00\",\"description\":\"Acras de morue, ein leckerer Fisch-Snack\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2014\\\/11\\\/21\\\/acras-de-morue-stockfisch-baellchen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2014\\\/11\\\/21\\\/acras-de-morue-stockfisch-baellchen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2014\\\/11\\\/21\\\/acras-de-morue-stockfisch-baellchen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acras de morue \\\/ Stockfisch-B\u00e4llchen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\",\"name\":\"Steffen&#039;s Haushaltsblog\",\"description\":\"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\\\/ki_kunst \",\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\",\"name\":\"Steffen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"caption\":\"Steffen\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/sthomas.de\",\"https:\\\/\\\/www.facebook.com\\\/steffen.thomas1\",\"https:\\\/\\\/x.com\\\/steto123\"],\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/author\\\/wp_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acras de morue \/ Stockfisch-B\u00e4llchen","description":"Acras de morue, ein leckerer Fisch-Snack","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/11\/21\/acras-de-morue-stockfisch-baellchen\/","og_locale":"de_DE","og_type":"article","og_title":"Acras de morue \/ Stockfisch-B\u00e4llchen","og_description":"Acras de morue, ein leckerer Fisch-Snack","og_url":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/11\/21\/acras-de-morue-stockfisch-baellchen\/","og_site_name":"Steffen&#039;s Haushaltsblog","article_publisher":"https:\/\/www.facebook.com\/steffen.thomas1","article_author":"https:\/\/www.facebook.com\/steffen.thomas1","article_published_time":"2014-11-21T18:23:44+00:00","author":"Steffen","twitter_misc":{"Verfasst von":"Steffen","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/11\/21\/acras-de-morue-stockfisch-baellchen\/#article","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/11\/21\/acras-de-morue-stockfisch-baellchen\/"},"author":{"name":"Steffen","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"headline":"Acras de morue \/ Stockfisch-B\u00e4llchen","datePublished":"2014-11-21T18:23:44+00:00","mainEntityOfPage":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/11\/21\/acras-de-morue-stockfisch-baellchen\/"},"wordCount":158,"commentCount":0,"publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"keywords":["Stockfisch"],"articleSection":["Snack"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2014\/11\/21\/acras-de-morue-stockfisch-baellchen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/11\/21\/acras-de-morue-stockfisch-baellchen\/","url":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/11\/21\/acras-de-morue-stockfisch-baellchen\/","name":"Acras de morue \/ Stockfisch-B\u00e4llchen","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website"},"datePublished":"2014-11-21T18:23:44+00:00","description":"Acras de morue, ein leckerer Fisch-Snack","breadcrumb":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/11\/21\/acras-de-morue-stockfisch-baellchen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2014\/11\/21\/acras-de-morue-stockfisch-baellchen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/11\/21\/acras-de-morue-stockfisch-baellchen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wissen.science-and-fun.de\/kochen\/"},{"@type":"ListItem","position":2,"name":"Acras de morue \/ Stockfisch-B\u00e4llchen"}]},{"@type":"WebSite","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website","url":"https:\/\/wissen.science-and-fun.de\/kochen\/","name":"Steffen&#039;s Haushaltsblog","description":"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\/ki_kunst ","publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wissen.science-and-fun.de\/kochen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8","name":"Steffen","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","caption":"Steffen"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g"},"sameAs":["https:\/\/sthomas.de","https:\/\/www.facebook.com\/steffen.thomas1","https:\/\/x.com\/steto123"],"url":"https:\/\/wissen.science-and-fun.de\/kochen\/author\/wp_admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p1tRoY-1Br","jetpack-related-posts":[{"id":3445,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/01\/05\/fischballchen-nigeria\/","url_meta":{"origin":6165,"position":0},"title":"Fischb\u00e4llchen (Nigeria)","author":"Steffen","date":"5. Januar 2012","format":false,"excerpt":"Zutaten 175 g Kabeljaufilet 2 EL Butter 2 EL Mehl 1\/3 l Milch Zitronensaft 0,2 TL Pfefferpaste 1 Eier Paniermehl 2\/3 Bund Petersilie 1\/3 Tasse Erdnuss\u00f6l Zubereitung Den Fisch in reichlich Wasser bei mittlerer Hitze 10 Minuten kochen. Abtropfen lassen und zur Seite stellen. Butter erhitzen. Mehl einr\u00fchren und hellgelb\u2026","rel":"","context":"In &quot;Fisch&quot;","block_context":{"text":"Fisch","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/fisch-2\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":375,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/10\/panierte-fischtaschen\/","url_meta":{"origin":6165,"position":1},"title":"Panierte Fischtaschen","author":"Steffen","date":"10. April 2011","format":false,"excerpt":"Zutaten: 4 gro\u00dfe Fischfilets Saft von 1 Zitrone Salz Pfeffer 100 g gekochter Schinken 150 g Emmentaler 1 Ei 2 EL Milch 6 EL Paniermehl Bratfett Zubereitung: Fischfilets waschen, trockentupfen, in Zitronensaft 5 Minuten marinieren, mit Salz und Pfeffer w\u00fcrzen. Schinken und Emmentaler in Streifen schneiden. Die Filets damit belegen\u2026","rel":"","context":"In &quot;Fisch&quot;","block_context":{"text":"Fisch","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/fisch\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2788,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2023\/09\/14\/fisch-in-kurbiskernsauce\/","url_meta":{"origin":6165,"position":2},"title":"Fisch in K\u00fcrbiskernsauce","author":"Steffen","date":"14. September 2023","format":false,"excerpt":"Fisch in K\u00fcrbiskernsauce 350 g Ger\u00e4ucherte Heringe4 Okras ((Gombobohne))1 Tomaten1 Zwiebeln; gehackt1 Knoblauchzehen; gehackt133 g K\u00fcrbiskerne1\/3 TL Pfefferpaste2\/3 Bund Petersilie1\/3 TL Palm\u00f6l Den Fisch in kleine St\u00fccke zerteilen und in leicht gesalzenem Wasser 6 Minuten garen. Die Okras kleinschneiden und zugeben.\u00d6l erhitzen und die gew\u00fcrfelten Tomaten, Zwiebeln sowie Knoblauch darin\u2026","rel":"","context":"In &quot;Fisch&quot;","block_context":{"text":"Fisch","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/fisch-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/wissen.science-and-fun.de\/kochen\/files\/2011\/09\/2023-09-28-16-30-35-2-Fish_in_pumpkin_seed_sauce_photorealistic_highly_intricated_award_winning_midjourneystyle_food_porn-617170500-scale8.50-dpm_2_a-dreamshaper_8.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/wissen.science-and-fun.de\/kochen\/files\/2011\/09\/2023-09-28-16-30-35-2-Fish_in_pumpkin_seed_sauce_photorealistic_highly_intricated_award_winning_midjourneystyle_food_porn-617170500-scale8.50-dpm_2_a-dreamshaper_8.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/wissen.science-and-fun.de\/kochen\/files\/2011\/09\/2023-09-28-16-30-35-2-Fish_in_pumpkin_seed_sauce_photorealistic_highly_intricated_award_winning_midjourneystyle_food_porn-617170500-scale8.50-dpm_2_a-dreamshaper_8.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/wissen.science-and-fun.de\/kochen\/files\/2011\/09\/2023-09-28-16-30-35-2-Fish_in_pumpkin_seed_sauce_photorealistic_highly_intricated_award_winning_midjourneystyle_food_porn-617170500-scale8.50-dpm_2_a-dreamshaper_8.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/wissen.science-and-fun.de\/kochen\/files\/2011\/09\/2023-09-28-16-30-35-2-Fish_in_pumpkin_seed_sauce_photorealistic_highly_intricated_award_winning_midjourneystyle_food_porn-617170500-scale8.50-dpm_2_a-dreamshaper_8.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/wissen.science-and-fun.de\/kochen\/files\/2011\/09\/2023-09-28-16-30-35-2-Fish_in_pumpkin_seed_sauce_photorealistic_highly_intricated_award_winning_midjourneystyle_food_porn-617170500-scale8.50-dpm_2_a-dreamshaper_8.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":3516,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/01\/14\/fischsuppe-ii\/","url_meta":{"origin":6165,"position":3},"title":"Fischsuppe II","author":"Steffen","date":"14. Januar 2012","format":false,"excerpt":"Zutaten 1 Zwiebel, gehackt 1 Knoblauchzehe, zerkleinert 1 Bund Suppengr\u00fcn, zerkleinert 1 TL Kaltgepresstes \u00d6l 200 ml Gem\u00fcsebr\u00fche 1 kleine Bund Petersilie 250 g Tomaten, enth\u00e4utet und gew\u00fcrfelt 100 g Goldbarschfilet, gew\u00fcrfelt Salz, Pfeffer 1 EL Zitronensaft 1 EL Creme fra\u00eeche Zubereitung Suppengr\u00fcn im \u00d6l anbraten, Br\u00fche zugeben. Die H\u00e4lfte\u2026","rel":"","context":"In &quot;Fisch&quot;","block_context":{"text":"Fisch","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/fisch-2\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3429,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/01\/02\/fisch-in-senfsauce\/","url_meta":{"origin":6165,"position":4},"title":"Fisch in Senfsauce","author":"Steffen","date":"2. Januar 2012","format":false,"excerpt":"Zutaten 400 g Kabeljaufilet 1 Zitrone; Saft 8 EL Senf Milch Mehl 4 EL Butter 1\/2 Tasse Mehl; (1) 1\/2 Tasse Milch; (1) 1 Tasse Fischbr\u00fche 1\/2 TL Pfefferpaste 2 Karotten 1\/2 Sellerieknolle 1 Stange Lauch 1\/2 Tasse Erdnuss\u00f6l Zubereitung Den Fisch in Scheiben schneiden. Zitronensaft mit der H\u00e4lfte des\u2026","rel":"","context":"In &quot;Fisch&quot;","block_context":{"text":"Fisch","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/fisch\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":961,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/24\/gefullte-zucchini\/","url_meta":{"origin":6165,"position":5},"title":"Gef\u00fcllte Zucchini","author":"Steffen","date":"24. April 2011","format":false,"excerpt":"Zutaten: 1 Br\u00f6tchen vom Vortag 4 mittelgro\u00dfe Zucchini 1 kleine Zwiebel 1 Bund Petersilie 300 g gemischtes Hackfleisch 1 Ei 1 Tl mittelscharfer Senf edels\u00fc\u00dfes Paprikapulver geriebene Muskatnuss Salz und Pfeffer 1 Knoblauchzehe 1 kleine Dose Tomate 1 Tl zerriebener Oregano 100 g geriebener Emmentaler Zubereitung: Das Br\u00f6tchen in Wasser\u2026","rel":"","context":"In &quot;Gem\u00fcse &amp; Obst&quot;","block_context":{"text":"Gem\u00fcse &amp; Obst","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/gemuse\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/6165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/comments?post=6165"}],"version-history":[{"count":1,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/6165\/revisions"}],"predecessor-version":[{"id":6166,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/6165\/revisions\/6166"}],"wp:attachment":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/media?parent=6165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/categories?post=6165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/tags?post=6165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}