{"id":5550,"date":"2014-02-13T20:30:10","date_gmt":"2014-02-13T20:30:10","guid":{"rendered":"https:\/\/wissen.science-and-fun.de\/kochen\/?p=5550"},"modified":"2014-01-01T20:42:11","modified_gmt":"2014-01-01T20:42:11","slug":"peking-ente-mit-mandarin-pfannkuchen","status":"publish","type":"post","link":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/02\/13\/peking-ente-mit-mandarin-pfannkuchen\/","title":{"rendered":"Peking Ente mit Mandarin Pfannkuchen"},"content":{"rendered":"<p><strong>Zutaten<\/strong><br \/>\n1 Bauernente, k\u00fcchenfertig (ca. 2.5 kg)<br \/>\n<em>Glasur<\/em><br \/>\n4 EL Honig<br \/>\n4 EL Dunkle Sojasosse<br \/>\n75 ml trockener Sherry<br \/>\n1\/2 TL Frische Ingwerwurzel gerieben<br \/>\n1\/2 TL Salz<br \/>\n<em>Pfannkuchenteig<\/em><br \/>\n300 g Mehl<br \/>\n1\/4 l kochendes Wasser<br \/>\n2 EL Erdnuss\u00f6l<br \/>\n<em>au\u00dferdem<\/em><br \/>\nPflaumen-Dip s\u00fcss-scharf<br \/>\nHoisinsauce<br \/>\n1 Bund Fr\u00fchlingszwiebeln<br \/>\n1 Gurke<\/p>\n<p><strong>Zubereitung<\/strong><br \/>\nDie Ente innen und au\u00dfen waschen und trocken tupfen. In einem gro\u00dfen Topf Wasser zum Kochen bringen und die Ente 5 Sekunden blanchieren. Am Hals \u00fcber Nacht zum Trocknen aufh\u00e4ngen.<br \/>\nDen Honig mit der Sojasauce, dem Sherry, dem Ingwer und dem Salz zu einer Glasur verr\u00fchren und die ganze Ente innen und au\u00dfen damit einreiben.<br \/>\nAm Hals ca. 3 Stunden an einen luftigen Platz zum Trocknen h\u00e4ngen; man kann mit einem Ventilator nachhelfen. Diese Prozedur eventuell nochmals wiederholen, die Ente sollte wie lackiert aussehen.<br \/>\nW\u00e4hrend die Ente gebraten wird kann man die Pfannkuchen, den Pflaumen Dip und das Gem\u00fcse zubereiten.<br \/>\nDie Fr\u00fchlingszwiebeln putzen, waschen und die H\u00e4lfte in schr\u00e4ge ca. 3 cm lange St\u00fccke, den Rest in Pinsel (= die Wurzeln knapp abschneiden, so dass sie unten noch zusammengehalten und nicht auseinander fallen. Dann in 5 cm lange St\u00fccke schneiden. Das andere Ende nun mit einem scharfen Messer erst quer, dann l\u00e4ngs bis ca. 2 cm \u00fcber dem Wurzelansatz einschneiden) schneiden, die Pinsel in kaltes Wasser legen.<br \/>\nDie Gurke sch\u00e4len, halbieren und die Kerne entfernen, dann in ca. 1\/2 cm dicke Scheiben schneiden und beiseite stellen.<br \/>\nDen Backofen auf 180 \u00b0C vorheizen und die Ente mit der Brust nach oben auf einen Bratrost legen und diesen auf die mittlere Ofenschiene schieben.<br \/>\nIn die Fettpfanne etwas hei\u00dfes Wasser geben, die Ente darf aber mit dem Wasser nicht in Ber\u00fchrung kommen. 90 bis 120 Minuten garen.<br \/>\nNach der H\u00e4lfte der Garzeit die Temperatur auf 160 \u00b0C zur\u00fcckschalten, die Ente wenden, damit sie von allen Seiten sch\u00f6n knusprig braun wird.<br \/>\nDie Ente ist gar, wenn man mit einer Gabel hinein sticht und kein blutiger Saft mehr austritt.<br \/>\nNach dem Garen 15 Minuten ruhen lassen.<br \/>\nDie Haut und das Fleisch von den Knochen l\u00f6sen und getrennt in mundgerechte St\u00fccke schneiden, auf einer vorgew\u00e4rmten Platte servieren.<br \/>\nF\u00fcr den Pfannkuchenteig das Mehl in eine Sch\u00fcssel sieben, das hei\u00dfe Wasser dar\u00fcber gie\u00dfen und den Teig solange kneten, bis er locker und glatt ist.<br \/>\nMit einem K\u00fcchentuch abdecken und 30 Minuten ruhen lassen, auf einem bemehlten Brett ca. 1\/2 cm dick ausrollen und mit einem F\u00f6rmchen oder Wasserglas, ca. 6 cm Durchmesser, Pl\u00e4tzchen ausstechen.<br \/>\nJedes zweite Pl\u00e4tzchen mit \u00d6l bestreichen und ein unbestrichenes darauf legen, dann mit der Nudelrolle von der Mitte her ausrollen, bis der Pfannkuchen ca. 15 cm Durchmesser hat. Mit den anderen Teigpl\u00e4tzchen ebenso verfahren.<br \/>\nEine Pfanne erhitzen und die Pfannkuchen ohne Fett auf beiden Seiten hellbraun backen, dann wieder vorsichtig auseinanderziehen und erst zur H\u00e4lfte, dann auf ein Viertel falten und warm stellen.<br \/>\nNun die Pfannkuchen auf einen Teller legen, den Fr\u00fchlingszwiebelpinsel in die Hoisinsauce tauchen, den Pfannkuchen auseinanderfalten und damit bestreichen, zuerst wird die Haut gegessen und dann das Fleisch. Ein St\u00fcckchen Haut, Fr\u00fchlingszwiebelringe und Gurkenstreifen dazulegen, den Pfannkuchen aufrollen, in den Pflaumen Dip stippen und mit den Fingern essen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zutaten 1 Bauernente, k\u00fcchenfertig (ca. 2.5 kg) Glasur 4 EL Honig 4 EL Dunkle Sojasosse 75 ml trockener Sherry 1\/2 TL Frische Ingwerwurzel gerieben 1\/2 TL Salz Pfannkuchenteig 300 g Mehl 1\/4 l kochendes Wasser 2 EL Erdnuss\u00f6l au\u00dferdem Pflaumen-Dip s\u00fcss-scharf Hoisinsauce 1 Bund Fr\u00fchlingszwiebeln 1 Gurke Zubereitung Die Ente innen und au\u00dfen waschen und &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/02\/13\/peking-ente-mit-mandarin-pfannkuchen\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,43,6],"tags":[44],"class_list":["post-5550","post","type-post","status-publish","format-standard","hentry","category-asiatisch","category-geflugel","category-hauptgerichte","tag-ente","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Peking Ente mit Mandarin Pfannkuchen<\/title>\n<meta name=\"description\" content=\"- Peking Ente mit Mandarin Pfannkuchen\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/02\/13\/peking-ente-mit-mandarin-pfannkuchen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peking Ente mit Mandarin Pfannkuchen\" \/>\n<meta property=\"og:description\" content=\"- Peking Ente mit Mandarin Pfannkuchen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/02\/13\/peking-ente-mit-mandarin-pfannkuchen\/\" \/>\n<meta property=\"og:site_name\" content=\"Steffen&#039;s Haushaltsblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:published_time\" content=\"2014-02-13T20:30:10+00:00\" \/>\n<meta name=\"author\" content=\"Steffen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steffen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2014\\\/02\\\/13\\\/peking-ente-mit-mandarin-pfannkuchen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2014\\\/02\\\/13\\\/peking-ente-mit-mandarin-pfannkuchen\\\/\"},\"author\":{\"name\":\"Steffen\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"headline\":\"Peking Ente mit Mandarin Pfannkuchen\",\"datePublished\":\"2014-02-13T20:30:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2014\\\/02\\\/13\\\/peking-ente-mit-mandarin-pfannkuchen\\\/\"},\"wordCount\":534,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"keywords\":[\"Ente\"],\"articleSection\":[\"Asiatisch\",\"Gefl\u00fcgel\",\"Hauptgerichte\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2014\\\/02\\\/13\\\/peking-ente-mit-mandarin-pfannkuchen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2014\\\/02\\\/13\\\/peking-ente-mit-mandarin-pfannkuchen\\\/\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2014\\\/02\\\/13\\\/peking-ente-mit-mandarin-pfannkuchen\\\/\",\"name\":\"Peking Ente mit Mandarin Pfannkuchen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\"},\"datePublished\":\"2014-02-13T20:30:10+00:00\",\"description\":\"- Peking Ente mit Mandarin Pfannkuchen\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2014\\\/02\\\/13\\\/peking-ente-mit-mandarin-pfannkuchen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2014\\\/02\\\/13\\\/peking-ente-mit-mandarin-pfannkuchen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2014\\\/02\\\/13\\\/peking-ente-mit-mandarin-pfannkuchen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Peking Ente mit Mandarin Pfannkuchen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\",\"name\":\"Steffen&#039;s Haushaltsblog\",\"description\":\"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\\\/ki_kunst \",\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\",\"name\":\"Steffen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"caption\":\"Steffen\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/sthomas.de\",\"https:\\\/\\\/www.facebook.com\\\/steffen.thomas1\",\"https:\\\/\\\/x.com\\\/steto123\"],\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/author\\\/wp_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peking Ente mit Mandarin Pfannkuchen","description":"- Peking Ente mit Mandarin Pfannkuchen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/02\/13\/peking-ente-mit-mandarin-pfannkuchen\/","og_locale":"de_DE","og_type":"article","og_title":"Peking Ente mit Mandarin Pfannkuchen","og_description":"- Peking Ente mit Mandarin Pfannkuchen","og_url":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/02\/13\/peking-ente-mit-mandarin-pfannkuchen\/","og_site_name":"Steffen&#039;s Haushaltsblog","article_publisher":"https:\/\/www.facebook.com\/steffen.thomas1","article_author":"https:\/\/www.facebook.com\/steffen.thomas1","article_published_time":"2014-02-13T20:30:10+00:00","author":"Steffen","twitter_misc":{"Verfasst von":"Steffen","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/02\/13\/peking-ente-mit-mandarin-pfannkuchen\/#article","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/02\/13\/peking-ente-mit-mandarin-pfannkuchen\/"},"author":{"name":"Steffen","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"headline":"Peking Ente mit Mandarin Pfannkuchen","datePublished":"2014-02-13T20:30:10+00:00","mainEntityOfPage":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/02\/13\/peking-ente-mit-mandarin-pfannkuchen\/"},"wordCount":534,"commentCount":0,"publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"keywords":["Ente"],"articleSection":["Asiatisch","Gefl\u00fcgel","Hauptgerichte"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2014\/02\/13\/peking-ente-mit-mandarin-pfannkuchen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/02\/13\/peking-ente-mit-mandarin-pfannkuchen\/","url":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/02\/13\/peking-ente-mit-mandarin-pfannkuchen\/","name":"Peking Ente mit Mandarin Pfannkuchen","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website"},"datePublished":"2014-02-13T20:30:10+00:00","description":"- Peking Ente mit Mandarin Pfannkuchen","breadcrumb":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/02\/13\/peking-ente-mit-mandarin-pfannkuchen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2014\/02\/13\/peking-ente-mit-mandarin-pfannkuchen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/02\/13\/peking-ente-mit-mandarin-pfannkuchen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wissen.science-and-fun.de\/kochen\/"},{"@type":"ListItem","position":2,"name":"Peking Ente mit Mandarin Pfannkuchen"}]},{"@type":"WebSite","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website","url":"https:\/\/wissen.science-and-fun.de\/kochen\/","name":"Steffen&#039;s Haushaltsblog","description":"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\/ki_kunst ","publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wissen.science-and-fun.de\/kochen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8","name":"Steffen","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","caption":"Steffen"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g"},"sameAs":["https:\/\/sthomas.de","https:\/\/www.facebook.com\/steffen.thomas1","https:\/\/x.com\/steto123"],"url":"https:\/\/wissen.science-and-fun.de\/kochen\/author\/wp_admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p1tRoY-1rw","jetpack-related-posts":[{"id":3328,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/27\/ente-mit-fruchten\/","url_meta":{"origin":5550,"position":0},"title":"Ente mit Fr\u00fcchten","author":"Steffen","date":"27. Dezember 2011","format":false,"excerpt":"Zutaten 600 g Entenbrust 3 EL Dunkle Sojasauce 1 EL Trockerner Sherry; - oder Reiswein 1 TL Gemahlener Ingwer 2 TL brauner Zucker 1 Priese Salz 1 Knoblauchzehe 4 EL Sesam\u00f6l 2 Schalotten 1 Staudensellerie 2 Dosen Ananasscheiben 1\/2 Honigmelone 50 g Lychees;frisch oder - aus der Dose 2 EL\u2026","rel":"","context":"In &quot;Asiatisch&quot;","block_context":{"text":"Asiatisch","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/asiatisch\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5628,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/03\/17\/pikantes-entenfleisch\/","url_meta":{"origin":5550,"position":1},"title":"Pikantes Entenfleisch","author":"Steffen","date":"17. M\u00e4rz 2014","format":false,"excerpt":"Zutaten 700 g Entenbrustfilet 5 g Mu-Err-Pilze, getrocknet 1 kleiner Chinakohl 1 Rote Paprikaschote 200 g M\u00f6hren 1 frische rote Chilischote 20 g Frischer Ingwer 1\/4 l H\u00fchnerbr\u00fche 6 EL Sojasauce 4 EL Reiswein oder trockener Sherry 3 TL Zucker 1 TL Salz 1 EL Speisest\u00e4rke 1 TL \u00d6l 100\u2026","rel":"","context":"In &quot;Asiatisch&quot;","block_context":{"text":"Asiatisch","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/asiatisch\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3334,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/27\/ente-mit-tausend-gewurzen\/","url_meta":{"origin":5550,"position":2},"title":"Ente Mit Tausend-Gew\u00fcrzen","author":"Steffen","date":"27. Dezember 2011","format":false,"excerpt":"Zutaten 2\/3 Ente; k\u00fcchenfertig - a ca. 2 kg) 0,2 Getrocknete Tangerinenschale 2\/3 frische Ingwerwurzel 2 Schalotten 1 Ganze Sternanis 4 EL Gelbe Bohnensauce 3,5 EL Hoisinsauce 2\/3 EL Sesampaste 2\/3 EL F\u00fcnf-Gew\u00fcrz-Pulver 1 TL Ingwerpulver 1 TL Salz 1 EL brauner Zucker 2\/3 EL Gin 4 Fr\u00fchlingszwiebeln 370 g\u2026","rel":"","context":"In &quot;Asiatisch&quot;","block_context":{"text":"Asiatisch","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/asiatisch\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4288,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/09\/08\/gebratene-entenbrust-in-salatblattern\/","url_meta":{"origin":5550,"position":3},"title":"Gebratene Entenbrust in Salatbl\u00e4ttern","author":"Steffen","date":"8. September 2012","format":false,"excerpt":"Zutaten 2 Entenbr\u00fcste ohne Knochen Salz Zucker 3 El Sojasauce 3 El Sherry 1 El Sesam\u00f6l 1 Tl Speisest\u00e4rke 2 El neutrales \u00d6l 50 g gesch\u00e4lte Mandeln 1 Tl feingehackter Ingwer 1 Tl feingehackter Knoblauch 4 Fr\u00fchlingszwiebeln in Ringe geschnitten 1 El Austernsauce Salatbl\u00e4tter 4 El Apfelessig 2 El Wasser\u2026","rel":"","context":"In &quot;Gefl\u00fcgel&quot;","block_context":{"text":"Gefl\u00fcgel","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/geflugel\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1136,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/29\/mariniertes-hahnchen\/","url_meta":{"origin":5550,"position":4},"title":"Mariniertes H\u00e4hnchen","author":"Steffen","date":"29. April 2011","format":false,"excerpt":"Zutaten: 1 H\u00e4hnchen (ca. 1300 -1400 g) F\u00fcr die Marinade: 3 EL Sojasauce je 2 EL Sherry und Oliven\u00f6l 1 EL Wasser 1 EL Honig 1\/2 TL Salz 1\/4 TL gemahlener wei\u00dfer Pfeffer 1 auf Salz zerriebene Knoblauchzehe etwas geriebener frischer Ingwer 2 Fr\u00fchlingszwiebeln Zubereitung: Das H\u00e4hnchen unter kaltem Wasser\u2026","rel":"","context":"In &quot;Gefl\u00fcgel&quot;","block_context":{"text":"Gefl\u00fcgel","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/geflugel\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3300,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/27\/hsiang-su-ya-szechuan-ente\/","url_meta":{"origin":5550,"position":5},"title":"Hsiang-Su-Ya (Szechuan-Ente)","author":"Steffen","date":"27. Dezember 2011","format":false,"excerpt":"Zutaten 1 Ente; 2 bis 2,5 kg schwer 2 EL Salz 1 EL Szechuan-Pfefferk\u00f6rner mit dem K\u00fcchenbeil oder im M\u00f6rser zerstossen 4 Scheiben Ingwerwurzel; frisch oder konserviert, etwa 2,5 cm im Durchmesser und 1\/2 cm dick 2 Fr\u00fchlingszwiebeln; mit gr\u00fcnen Spitzen, in 5 cm lange St\u00fccke geschnitten 2 EL Sojasauce\u2026","rel":"","context":"In &quot;Gefl\u00fcgel&quot;","block_context":{"text":"Gefl\u00fcgel","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/geflugel\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/5550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/comments?post=5550"}],"version-history":[{"count":1,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/5550\/revisions"}],"predecessor-version":[{"id":5551,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/5550\/revisions\/5551"}],"wp:attachment":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/media?parent=5550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/categories?post=5550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/tags?post=5550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}