{"id":4728,"date":"2012-12-15T20:59:34","date_gmt":"2012-12-15T20:59:34","guid":{"rendered":"https:\/\/wissen.science-and-fun.de\/kochen\/?p=4728"},"modified":"2012-12-15T20:59:34","modified_gmt":"2012-12-15T20:59:34","slug":"nudeln-mit-schinken-und-erbsen","status":"publish","type":"post","link":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/12\/15\/nudeln-mit-schinken-und-erbsen\/","title":{"rendered":"Nudeln mit Schinken und Erbsen"},"content":{"rendered":"<p><strong>Zutaten<\/strong><br \/>\n400 g Teigwaren; (H\u00f6rnchen oder kleingebrochene Makkaroni)<br \/>\n300 g Junge Erbsen<br \/>\n100 g gekochter Schinken<br \/>\n50 g Emmentaler<br \/>\n50 g Parmesank\u00e4se; gerieben frisch gerieben!<br \/>\n1 kleine Zwiebel<br \/>\nFleischbr\u00fche<br \/>\n60 g Butter<br \/>\nSalz und Pfeffer<\/p>\n<p><strong>Zubereitung<\/strong><br \/>\nIn einer Kasserolle Butter erhitzen, die fein gehackte Zwiebel darin and\u00fcnsten, die Erbsen dazusch\u00fctten, salzen, pfeffern, bei m\u00e4ssigem Feuer garen. Ab und zu den Topf vom Feuer nehmen und vorsichtig sch\u00fctteln, damit die Erbsen nicht anbrennen.<br \/>\nIn einem anderen Topf den in Streifen geschnittenen Schinken mit der restlichen Butter anr\u00f6sten, mit den Erbsen vermischen, mit einigen L\u00f6ffeln Fleischbr\u00fche auff\u00fcllen und kurz durchziehen lassen.<br \/>\nDie Nudeln inzwischen nicht zu weich kochen, abtropfen lassen und in eine feuerfeste Sch\u00fcssel geben. Mit den Erbsen vermischen und ganz kurz in den Ofen geben, damit alle Fl\u00fcssigkeit verdunstet.<br \/>\nMit W\u00fcrfeln von Schweizerk\u00e4se und dem Reibk\u00e4se vermischen und schnell auftragen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zutaten 400 g Teigwaren; (H\u00f6rnchen oder kleingebrochene Makkaroni) 300 g Junge Erbsen 100 g gekochter Schinken 50 g Emmentaler 50 g Parmesank\u00e4se; gerieben frisch gerieben! 1 kleine Zwiebel Fleischbr\u00fche 60 g Butter Salz und Pfeffer Zubereitung In einer Kasserolle Butter erhitzen, die fein gehackte Zwiebel darin and\u00fcnsten, die Erbsen dazusch\u00fctten, salzen, pfeffern, bei m\u00e4ssigem Feuer &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/12\/15\/nudeln-mit-schinken-und-erbsen\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6,7],"tags":[9,70],"class_list":["post-4728","post","type-post","status-publish","format-standard","hentry","category-hauptgerichte","category-nudeln-und-co","tag-nudeln","tag-schinken","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nudeln mit Schinken und Erbsen<\/title>\n<meta name=\"description\" content=\"- Nudeln mit Schinken und Erbsen\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/12\/15\/nudeln-mit-schinken-und-erbsen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nudeln mit Schinken und Erbsen\" \/>\n<meta property=\"og:description\" content=\"- Nudeln mit Schinken und Erbsen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/12\/15\/nudeln-mit-schinken-und-erbsen\/\" \/>\n<meta property=\"og:site_name\" content=\"Steffen&#039;s Haushaltsblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:published_time\" content=\"2012-12-15T20:59:34+00:00\" \/>\n<meta name=\"author\" content=\"Steffen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steffen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/12\\\/15\\\/nudeln-mit-schinken-und-erbsen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/12\\\/15\\\/nudeln-mit-schinken-und-erbsen\\\/\"},\"author\":{\"name\":\"Steffen\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"headline\":\"Nudeln mit Schinken und Erbsen\",\"datePublished\":\"2012-12-15T20:59:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/12\\\/15\\\/nudeln-mit-schinken-und-erbsen\\\/\"},\"wordCount\":154,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"keywords\":[\"Nudeln\",\"Schinken\"],\"articleSection\":[\"Hauptgerichte\",\"Nudeln und Co.\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/12\\\/15\\\/nudeln-mit-schinken-und-erbsen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/12\\\/15\\\/nudeln-mit-schinken-und-erbsen\\\/\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/12\\\/15\\\/nudeln-mit-schinken-und-erbsen\\\/\",\"name\":\"Nudeln mit Schinken und Erbsen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\"},\"datePublished\":\"2012-12-15T20:59:34+00:00\",\"description\":\"- Nudeln mit Schinken und Erbsen\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/12\\\/15\\\/nudeln-mit-schinken-und-erbsen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/12\\\/15\\\/nudeln-mit-schinken-und-erbsen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/12\\\/15\\\/nudeln-mit-schinken-und-erbsen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nudeln mit Schinken und Erbsen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\",\"name\":\"Steffen&#039;s Haushaltsblog\",\"description\":\"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\\\/ki_kunst \",\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\",\"name\":\"Steffen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"caption\":\"Steffen\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/sthomas.de\",\"https:\\\/\\\/www.facebook.com\\\/steffen.thomas1\",\"https:\\\/\\\/x.com\\\/steto123\"],\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/author\\\/wp_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nudeln mit Schinken und Erbsen","description":"- Nudeln mit Schinken und Erbsen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/12\/15\/nudeln-mit-schinken-und-erbsen\/","og_locale":"de_DE","og_type":"article","og_title":"Nudeln mit Schinken und Erbsen","og_description":"- Nudeln mit Schinken und Erbsen","og_url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/12\/15\/nudeln-mit-schinken-und-erbsen\/","og_site_name":"Steffen&#039;s Haushaltsblog","article_publisher":"https:\/\/www.facebook.com\/steffen.thomas1","article_author":"https:\/\/www.facebook.com\/steffen.thomas1","article_published_time":"2012-12-15T20:59:34+00:00","author":"Steffen","twitter_misc":{"Verfasst von":"Steffen","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/12\/15\/nudeln-mit-schinken-und-erbsen\/#article","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/12\/15\/nudeln-mit-schinken-und-erbsen\/"},"author":{"name":"Steffen","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"headline":"Nudeln mit Schinken und Erbsen","datePublished":"2012-12-15T20:59:34+00:00","mainEntityOfPage":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/12\/15\/nudeln-mit-schinken-und-erbsen\/"},"wordCount":154,"commentCount":0,"publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"keywords":["Nudeln","Schinken"],"articleSection":["Hauptgerichte","Nudeln und Co."],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2012\/12\/15\/nudeln-mit-schinken-und-erbsen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/12\/15\/nudeln-mit-schinken-und-erbsen\/","url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/12\/15\/nudeln-mit-schinken-und-erbsen\/","name":"Nudeln mit Schinken und Erbsen","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website"},"datePublished":"2012-12-15T20:59:34+00:00","description":"- Nudeln mit Schinken und Erbsen","breadcrumb":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/12\/15\/nudeln-mit-schinken-und-erbsen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2012\/12\/15\/nudeln-mit-schinken-und-erbsen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/12\/15\/nudeln-mit-schinken-und-erbsen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wissen.science-and-fun.de\/kochen\/"},{"@type":"ListItem","position":2,"name":"Nudeln mit Schinken und Erbsen"}]},{"@type":"WebSite","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website","url":"https:\/\/wissen.science-and-fun.de\/kochen\/","name":"Steffen&#039;s Haushaltsblog","description":"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\/ki_kunst ","publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wissen.science-and-fun.de\/kochen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8","name":"Steffen","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","caption":"Steffen"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g"},"sameAs":["https:\/\/sthomas.de","https:\/\/www.facebook.com\/steffen.thomas1","https:\/\/x.com\/steto123"],"url":"https:\/\/wissen.science-and-fun.de\/kochen\/author\/wp_admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p1tRoY-1eg","jetpack-related-posts":[{"id":963,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/24\/warmer-nudelsalat-mit-hahnchenbrust\/","url_meta":{"origin":4728,"position":0},"title":"Warmer Nudelsalat mit H\u00e4hnchenbrust","author":"Steffen","date":"24. April 2011","format":false,"excerpt":"Zutaten: 1 rote Zwiebel 1 Knoblauchzehe 200 g Champignons 2 El Oliven\u00f6l Saft von 1\/2 Zitrone 100 g Erbsen, frisch oder TK 400 g verschiedenfarbige Fusilli Salz 15 Kirschtomaten 200 g gegartes H\u00e4hnchenbrustfleisch 2 El gehackter frischer Dill oder 2 TL getrocknete Dillspitzen 50 g geriebener Parmesan Dillzweige zum Garnieren\u2026","rel":"","context":"In &quot;Salat&quot;","block_context":{"text":"Salat","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/salat\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5508,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/01\/24\/nudelsalat-klassisch\/","url_meta":{"origin":4728,"position":1},"title":"Nudelsalat, klassisch","author":"Steffen","date":"24. Januar 2014","format":false,"excerpt":"Zutaten 250 g kurze Nudeln 3 Eier 150 g TK-Erbsen 100 g M\u00f6hren 3 Gew\u00fcrzgurken 150 g gekochter Schinken 2 Dose Sahne-Dickmilch a 175g 2 EL Gurkenwasser 2 EL Ketchup Salz, Pfeffer, Zucker Zubereitung Nudeln in Salzwasser kochen, abschrecken. Die Eier 8 min hart kochen, abschrecken und pellen. Erbsen auftauen.\u2026","rel":"","context":"In &quot;Beilagen&quot;","block_context":{"text":"Beilagen","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/beilagen\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3345,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/27\/erbsensuppe-frankfurter-art\/","url_meta":{"origin":4728,"position":2},"title":"Erbsensuppe (Frankfurter Art)","author":"Steffen","date":"27. Dezember 2011","format":false,"excerpt":"Zutaten 700 g Erbsen (tiefgefroren) 2 Schalotten 1\/4 l Fleischbr\u00fche 1\/2 l Milch Salz 100 g Gekochter Schinken 4 Frankfurter W\u00fcrstchen 1 Bund Petersilie Zubereitung Erbsen und Schalotten mit hei\u00dfer Br\u00fche im Mixer p\u00fcrieren. In einem Topf die Milch mit dem Schneebesen unterr\u00fchren. Salzen und aufkochen lassen. Schinken in feine\u2026","rel":"","context":"In &quot;Suppe&quot;","block_context":{"text":"Suppe","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/suppe\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":6965,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2019\/06\/19\/amsterdamer-fleischtopf\/","url_meta":{"origin":4728,"position":3},"title":"Amsterdamer Fleischtopf","author":"Steffen","date":"19. Juni 2019","format":false,"excerpt":"Amsterdamer Fleischtopf 300 Gramm Schweinefilet100 Gramm Gekochter Schinken150 Gramm Geriebenen K\u00e4se250 Gramm Bandnudeln125 ml Sahne125 ml Fleischbr\u00fcheButterMehlRosmarinSalzPfeffer Nudeln kochen, das Fleisch in Scheiben schneiden. Mit Salz, Pfeffer und Rosmarin einreiben und in Mehl wenden. In hei\u00dfer Butter von allen Seiten anbraten. Fleisch herausnehmen und in dem Bratenfett Sahne und Fleischbr\u00fche\u2026","rel":"","context":"In &quot;Auflauf&quot;","block_context":{"text":"Auflauf","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/auflauf\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5496,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/01\/18\/nudeln-mit-schinken-und-kaese\/","url_meta":{"origin":4728,"position":4},"title":"Nudeln mit Schinken und K\u00e4se","author":"Steffen","date":"18. Januar 2014","format":false,"excerpt":"Zutaten 250 g gekochter Schinken 200 g Butter oder Margarine 250 ml S\u00fc\u00dfe Sahne 500 g Nudeln 200 g Geriebener K\u00e4se Salbeibl\u00e4tter Zubereitung Die Schinkenstreifen werden in 100 g Butter gebraten, mit s\u00fc\u00dfer Sahne \u00fcbergossen, mit Pfeffer gew\u00fcrzt und auf kleiner Flamme ein wenig gekocht. Die Nudeln werden in reichlich\u2026","rel":"","context":"In &quot;Hauptgerichte&quot;","block_context":{"text":"Hauptgerichte","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1991,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/06\/12\/schweinelende-in-blatterteig\/","url_meta":{"origin":4728,"position":5},"title":"Schweinelende in Bl\u00e4tterteig","author":"Steffen","date":"12. Juni 2011","format":false,"excerpt":"Zutaten 300 g Schweinefilet 3 grosse Zwiebeln gesch\u00e4lt fein gehackt 3 Champignons geputzt fein gehackt 1 B\u00fcschel Blattpetersilie 1 Zweig Majoran 1 EL Weissbrot; frisch gerieben 2 Eigelb 2 EL Milch 200 g Bl\u00e4tterteig in Platten (TK) 200 g Karotten 150 g Erbsen, enth\u00fclst Butter Oliven\u00f6l Pfeffer Salz Zubereitung Das\u2026","rel":"","context":"In &quot;Hauptgerichte&quot;","block_context":{"text":"Hauptgerichte","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/4728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/comments?post=4728"}],"version-history":[{"count":1,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/4728\/revisions"}],"predecessor-version":[{"id":4729,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/4728\/revisions\/4729"}],"wp:attachment":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/media?parent=4728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/categories?post=4728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/tags?post=4728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}