{"id":4683,"date":"2012-11-30T20:51:21","date_gmt":"2012-11-30T20:51:21","guid":{"rendered":"https:\/\/wissen.science-and-fun.de\/kochen\/?p=4683"},"modified":"2012-11-30T20:51:21","modified_gmt":"2012-11-30T20:51:21","slug":"knuspriger-gansebraten","status":"publish","type":"post","link":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/11\/30\/knuspriger-gansebraten\/","title":{"rendered":"Knuspriger G\u00e4nsebraten"},"content":{"rendered":"<p><strong>Zutaten<\/strong><br \/>\n1 K\u00fcchenfertige Gans (3,5 &#8211; 4 kg)<br \/>\nPfeffer &#038; Salz<br \/>\n3 TL Getrockneter Thymian<br \/>\n3 \u00c4pfel (ca. 300 g)<br \/>\n3 Zwiebeln<br \/>\n100 Gramm  Cranberries, frisch oder tiefgek\u00fchlt<br \/>\n100 Gramm  K\u00fcchenfertige Maronen (Dose oder Glas)<br \/>\n750 ml  H\u00fchner-Kraftbouillon<br \/>\n125 ml  Rotwein<br \/>\nEvtl. Saucenbinder, dunkel<br \/>\n<em>Kl\u00f6\u00dfe<\/em><br \/>\n500 Gramm  Kartoffeln<br \/>\n2 Eier<br \/>\nMuskat<br \/>\nSalz<br \/>\nGrie\u00df oder Kartoffelmehl zum Binden<\/p>\n<p><strong>Zubereitung<\/strong><br \/>\nGans waschen und mit K\u00fcchenpapier trocken tupfen. Das Gefl\u00fcgel innen mit Salz, Pfeffer und Thymian einreiben, au\u00dfen nur pfeffern und salzen.<br \/>\n\u00c4pfel und Zwiebeln sch\u00e4len und in mittelgro\u00dfe W\u00fcrfel schneiden. Eine H\u00e4lfte davon mit Cranberries und Maronen mischen und in die Gans f\u00fcllen.<br \/>\nVon der H\u00fchner-Kraftbouillon 500 ml in einen Br\u00e4ter gie\u00dfen. Gans mit der Brustseite nach unten hineinlegen und im vorgeheizten Backofen bei 200 Grad auf der untersten Schiene 1,5 &#8211; 2 Stunden braten. Danach die Gans wenden, restliche Apfel- und Zwiebelst\u00fccke zuf\u00fcgen und das Gefl\u00fcgel nochmal 1,5 &#8211; 1 Stunde garen.<\/p>\n<p>Gans aus dem Br\u00e4ter nehmen und warm stellen. Bratensatz entfetten,<br \/>\nrestliche H\u00fchner-Kraftbouillon und Rotwein dazugie\u00dfen. Sauce mit dem<br \/>\nP\u00fcrierstab fein zermahlen.<\/p>\n<p>Zum Schluss mit dunklem Saucenbinder oder St\u00e4rkemehl binden und mit<br \/>\nSalz abschmecken.<\/p>\n<p>Die Kl\u00f6\u00dfe:<\/p>\n<p>Die H\u00e4lfte der Kartoffeln in der Schale kochen und anschlie\u00dfend<br \/>\nsch\u00e4len. Die gesch\u00e4lten Kartoffeln vorsichtig durch eine<br \/>\nKartoffelpresse dr\u00fccken.<\/p>\n<p>Die restlichen Kartoffeln sch\u00e4len und reiben. Die geriebenen<br \/>\nKartoffeln mit den H\u00e4nden gut ausdr\u00fccken.<\/p>\n<p>Die gekochten und durchgedr\u00fcckten Kartoffeln mit den rohen,<br \/>\nausgedr\u00fcckten Kartoffeln in eine Sch\u00fcssel geben. Eier hineingeben<br \/>\nund alles gut mischen. Kartoffelteig mit Muskat und Salz abschmecken.<br \/>\nWenn der Teig nicht fest genug ist, mit etwas Kartoffelmehl binden.<\/p>\n<p>Mit bemehlten H\u00e4nden aus dem Kartoffelteig Kl\u00f6\u00dfe formen und in<br \/>\nsiedendes Wasser geben. Wenn die Kl\u00f6\u00dfe nach einiger Zeit an der<br \/>\nWasseroberfl\u00e4che schwimmen, sind sie fertig.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zutaten 1 K\u00fcchenfertige Gans (3,5 &#8211; 4 kg) Pfeffer &#038; Salz 3 TL Getrockneter Thymian 3 \u00c4pfel (ca. 300 g) 3 Zwiebeln 100 Gramm Cranberries, frisch oder tiefgek\u00fchlt 100 Gramm K\u00fcchenfertige Maronen (Dose oder Glas) 750 ml H\u00fchner-Kraftbouillon 125 ml Rotwein Evtl. Saucenbinder, dunkel Kl\u00f6\u00dfe 500 Gramm Kartoffeln 2 Eier Muskat Salz Grie\u00df oder Kartoffelmehl &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/11\/30\/knuspriger-gansebraten\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[43,6],"tags":[207],"class_list":["post-4683","post","type-post","status-publish","format-standard","hentry","category-geflugel","category-hauptgerichte","tag-gans","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Knuspriger G\u00e4nsebraten<\/title>\n<meta name=\"description\" content=\"- Knuspriger G\u00e4nsebraten\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/11\/30\/knuspriger-gansebraten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Knuspriger G\u00e4nsebraten\" \/>\n<meta property=\"og:description\" content=\"- Knuspriger G\u00e4nsebraten\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/11\/30\/knuspriger-gansebraten\/\" \/>\n<meta property=\"og:site_name\" content=\"Steffen&#039;s Haushaltsblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-30T20:51:21+00:00\" \/>\n<meta name=\"author\" content=\"Steffen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steffen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/11\\\/30\\\/knuspriger-gansebraten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/11\\\/30\\\/knuspriger-gansebraten\\\/\"},\"author\":{\"name\":\"Steffen\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"headline\":\"Knuspriger G\u00e4nsebraten\",\"datePublished\":\"2012-11-30T20:51:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/11\\\/30\\\/knuspriger-gansebraten\\\/\"},\"wordCount\":305,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"keywords\":[\"Gans\"],\"articleSection\":[\"Gefl\u00fcgel\",\"Hauptgerichte\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/11\\\/30\\\/knuspriger-gansebraten\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/11\\\/30\\\/knuspriger-gansebraten\\\/\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/11\\\/30\\\/knuspriger-gansebraten\\\/\",\"name\":\"Knuspriger G\u00e4nsebraten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\"},\"datePublished\":\"2012-11-30T20:51:21+00:00\",\"description\":\"- Knuspriger G\u00e4nsebraten\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/11\\\/30\\\/knuspriger-gansebraten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/11\\\/30\\\/knuspriger-gansebraten\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/11\\\/30\\\/knuspriger-gansebraten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Knuspriger G\u00e4nsebraten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\",\"name\":\"Steffen&#039;s Haushaltsblog\",\"description\":\"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\\\/ki_kunst \",\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\",\"name\":\"Steffen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"caption\":\"Steffen\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/sthomas.de\",\"https:\\\/\\\/www.facebook.com\\\/steffen.thomas1\",\"https:\\\/\\\/x.com\\\/steto123\"],\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/author\\\/wp_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Knuspriger G\u00e4nsebraten","description":"- Knuspriger G\u00e4nsebraten","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/11\/30\/knuspriger-gansebraten\/","og_locale":"de_DE","og_type":"article","og_title":"Knuspriger G\u00e4nsebraten","og_description":"- Knuspriger G\u00e4nsebraten","og_url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/11\/30\/knuspriger-gansebraten\/","og_site_name":"Steffen&#039;s Haushaltsblog","article_publisher":"https:\/\/www.facebook.com\/steffen.thomas1","article_author":"https:\/\/www.facebook.com\/steffen.thomas1","article_published_time":"2012-11-30T20:51:21+00:00","author":"Steffen","twitter_misc":{"Verfasst von":"Steffen","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/11\/30\/knuspriger-gansebraten\/#article","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/11\/30\/knuspriger-gansebraten\/"},"author":{"name":"Steffen","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"headline":"Knuspriger G\u00e4nsebraten","datePublished":"2012-11-30T20:51:21+00:00","mainEntityOfPage":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/11\/30\/knuspriger-gansebraten\/"},"wordCount":305,"commentCount":0,"publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"keywords":["Gans"],"articleSection":["Gefl\u00fcgel","Hauptgerichte"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2012\/11\/30\/knuspriger-gansebraten\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/11\/30\/knuspriger-gansebraten\/","url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/11\/30\/knuspriger-gansebraten\/","name":"Knuspriger G\u00e4nsebraten","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website"},"datePublished":"2012-11-30T20:51:21+00:00","description":"- Knuspriger G\u00e4nsebraten","breadcrumb":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/11\/30\/knuspriger-gansebraten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2012\/11\/30\/knuspriger-gansebraten\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/11\/30\/knuspriger-gansebraten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wissen.science-and-fun.de\/kochen\/"},{"@type":"ListItem","position":2,"name":"Knuspriger G\u00e4nsebraten"}]},{"@type":"WebSite","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website","url":"https:\/\/wissen.science-and-fun.de\/kochen\/","name":"Steffen&#039;s Haushaltsblog","description":"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\/ki_kunst ","publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wissen.science-and-fun.de\/kochen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8","name":"Steffen","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","caption":"Steffen"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g"},"sameAs":["https:\/\/sthomas.de","https:\/\/www.facebook.com\/steffen.thomas1","https:\/\/x.com\/steto123"],"url":"https:\/\/wissen.science-and-fun.de\/kochen\/author\/wp_admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p1tRoY-1dx","jetpack-related-posts":[{"id":2986,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/11\/03\/gans-mit-maronen\/","url_meta":{"origin":4683,"position":0},"title":"Gans mit Maronen","author":"Steffen","date":"3. November 2011","format":false,"excerpt":"Zutaten 1 frische Gans 3-3.5kg G\u00e4nseklein u. Innereien Beifu\u00df frischer Majoran Pfeffer Salz Zwiebel, mittelgro\u00df 100 g \u00a0Sellerie 100 g \u00a0M\u00f6hren 100 g \u00a0Lauch F\u00fcllung\u00a0 50 g \u00a0gerauchten Schweinebauch 50 g \u00a0kleingehackte Zwiebeln 500 g \u00a0Rosenkohl \u00a0500 g \u00a0Maronen, gesch\u00e4lt 80 g \u00a0Zucker 0,1 l \u00a0trockener Rotwein 0,1 l \u00a0Bratensaft\u2026","rel":"","context":"In &quot;Gefl\u00fcgel&quot;","block_context":{"text":"Gefl\u00fcgel","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/geflugel\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4686,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/12\/01\/martinigans-mit-rotkraut-und-linsen\/","url_meta":{"origin":4683,"position":1},"title":"Martinigans mit Rotkraut und Linsen","author":"Steffen","date":"1. Dezember 2012","format":false,"excerpt":"Zutaten 1 Junggans (ca. 3 kg) 2 \u00c4pfel 2 Orangen Salz Gerebelter Majoran 500 ml Gef\u00fcgelfond 100 ml Orangegensaft 80 ml Grand Marnier Linsen 160 Gramm Tellerlinsen (in Wasser eingeweicht) 2 Zwiebeln 100 Gramm Bauchspeck 125 ml Orangensaft 2 EL Balsamico-Essig Salz, Pfeffer Butter 3 EL Glattes Mehl 4 EL\u2026","rel":"","context":"In &quot;Gefl\u00fcgel&quot;","block_context":{"text":"Gefl\u00fcgel","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/geflugel\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":750,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/19\/gansebrust-mit-linsengemuse\/","url_meta":{"origin":4683,"position":2},"title":"G\u00e4nsebrust mit Linsengem\u00fcse","author":"Steffen","date":"19. April 2011","format":false,"excerpt":"Zutaten: 1 Bund Suppengr\u00fcn 2 El. \u00d6l 400 Gramm Gr\u00fcne Linsen 1 kleine Dose Tomaten (400g) 500 ml Gem\u00fcsebr\u00fche 1\/2 Tl. getrockneter Thymian Cayennepfeffer 1 G\u00e4nsebrust (etwa 400g) Salz, wei\u00dfer Pfeffer 2 El. Orangenlik\u00f6r 1 Bund Basilikum 1 El. Aceto Balsamico Zubereitung: Zuerst das Suppengr\u00fcn waschen, putzen, klein w\u00fcrfeln und\u2026","rel":"","context":"In &quot;Gefl\u00fcgel&quot;","block_context":{"text":"Gefl\u00fcgel","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/geflugel\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":741,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/18\/gefullte-gansebrust-mit-birnen\/","url_meta":{"origin":4683,"position":3},"title":"Gef\u00fcllte G\u00e4nsebrust mit Birnen","author":"Steffen","date":"18. April 2011","format":false,"excerpt":"Zutaten: 400 g Birnen (2 St\u00fcck) 100 g Zwiebeln 3 El. \u00d6l 100 g Gorgonzola Salz, Pfeffer, Muskatnuss 2 G\u00e4nsebr\u00fcste 100 g M\u00f6hren 1 El. Tomatenmark 600 ml G\u00e4nsefond Rosmarin 1 El. Saucenbinder 50 g Creme fraiche 500 g Schalotten 200 ml Wei\u00dfwein 1 Bund Estragon 1\/2 El. Honig, fl\u00fcssiger\u2026","rel":"","context":"In &quot;Gefl\u00fcgel&quot;","block_context":{"text":"Gefl\u00fcgel","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/geflugel\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3337,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/27\/ente-mit-trauben\/","url_meta":{"origin":4683,"position":4},"title":"Ente mit Trauben","author":"Steffen","date":"27. Dezember 2011","format":false,"excerpt":"Zutaten 0,5 Ente, k\u00fcchenfertig, ca. 2 kg Salz, Pfeffer 160 g Zwiebeln 160 g \u00c4pfel 80 g blaue Weintrauben 2 Zimtstangen 2 Zweige Thymian 0,5 Zitrone (Schale und Saft) 40 ml Cream Sherry 60 ml Gefl\u00fcgelfond Zubereitung 1. Ente mit Salz und Pfeffer einreiben. Auf einem Blech im Backofen auf\u2026","rel":"","context":"In &quot;Gefl\u00fcgel&quot;","block_context":{"text":"Gefl\u00fcgel","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/geflugel\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4681,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/11\/30\/gansebraten-und-2-fullungen\/","url_meta":{"origin":4683,"position":5},"title":"G\u00e4nsebraten und 2 F\u00fcllungen","author":"Steffen","date":"30. November 2012","format":false,"excerpt":"Zutaten 1 Gans, ca. 3 kg schwer etwas Salz, Pfeffer 150 g Suppengem\u00fcse, gew\u00fcrfelt 3 Zweige Majoran 1 EL Tomatenmark 250 ml Gaense- oder Gefluegelfond Fruchtige F\u00fcllung: 2 \u00c4pfel 1 Zwiebel 2 EL Pinienkerne, geroestet 50 g Backpflaumen ohne Stein 50 g getrocknete Aprikosen 50 g getrocknete Birnen 1 EL\u2026","rel":"","context":"In &quot;Gefl\u00fcgel&quot;","block_context":{"text":"Gefl\u00fcgel","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/geflugel\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/4683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/comments?post=4683"}],"version-history":[{"count":1,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/4683\/revisions"}],"predecessor-version":[{"id":4684,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/4683\/revisions\/4684"}],"wp:attachment":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/media?parent=4683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/categories?post=4683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/tags?post=4683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}