{"id":4309,"date":"2012-09-13T19:36:21","date_gmt":"2012-09-13T19:36:21","guid":{"rendered":"https:\/\/wissen.science-and-fun.de\/kochen\/?p=4309"},"modified":"2012-09-13T19:36:21","modified_gmt":"2012-09-13T19:36:21","slug":"gebratenes-hahnchen-scharf-gewurzt","status":"publish","type":"post","link":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/09\/13\/gebratenes-hahnchen-scharf-gewurzt\/","title":{"rendered":"Gebratenes H\u00e4hnchen, scharf gew\u00fcrzt"},"content":{"rendered":"<p><strong>Zutaten<\/strong><br \/>\n1000 g H\u00e4hnchen<br \/>\n4 Knoblauchzehen gehackt<br \/>\n1 Zwiebel gehackt<br \/>\n1 El Ingwer gehackt<br \/>\n1\/2 Tl Salz<br \/>\n1 Zitrone den Saft davon<br \/>\n1\/2 Tasse Wasser<br \/>\n1\/2 Tl Kurkuma-Pulver Gelbwurz<br \/>\n5 Rote Chilies zerstossen<br \/>\n1\/2 Tasse \u00d6l<br \/>\n<strong>Zubereitung<\/strong><br \/>\nDas \u00d6l erhitzen und die Zwiebel mit dem Knoblauch darin glasig d\u00fcnsten. Das ganze H\u00e4hnchen hineingeben und von allen Seiten bei schwacher Hitze gut braun braten. Den Ingwer und das Salz gleichm\u00e4ssig dar\u00fcber verstreuen, zudecken und langsam 40-60 Min. k\u00f6cheln (von Zeit zu Zeit umdrehen). Den Zitronensaft mit dem Wasser mischen und zu dem H\u00e4hnchen geben. Nun werden Kurkuma-Pulver und die zerstossenen Chilies dazugegeben und alles zusammen weitergekocht, bis das H\u00e4hnchen gar ist (ca. weitere 15 Minuten). Aus der Pfanne nehmen, sch\u00f6n dekorieren und heiss mit Reis servieren.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zutaten 1000 g H\u00e4hnchen 4 Knoblauchzehen gehackt 1 Zwiebel gehackt 1 El Ingwer gehackt 1\/2 Tl Salz 1 Zitrone den Saft davon 1\/2 Tasse Wasser 1\/2 Tl Kurkuma-Pulver Gelbwurz 5 Rote Chilies zerstossen 1\/2 Tasse \u00d6l Zubereitung Das \u00d6l erhitzen und die Zwiebel mit dem Knoblauch darin glasig d\u00fcnsten. Das ganze H\u00e4hnchen hineingeben und von &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/09\/13\/gebratenes-hahnchen-scharf-gewurzt\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,43,6],"tags":[76],"class_list":["post-4309","post","type-post","status-publish","format-standard","hentry","category-asiatisch","category-geflugel","category-hauptgerichte","tag-huhn","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gebratenes H\u00e4hnchen, scharf gew\u00fcrzt<\/title>\n<meta name=\"description\" content=\"- Gebratenes H\u00e4hnchen, scharf gew\u00fcrzt\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/09\/13\/gebratenes-hahnchen-scharf-gewurzt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gebratenes H\u00e4hnchen, scharf gew\u00fcrzt\" \/>\n<meta property=\"og:description\" content=\"- Gebratenes H\u00e4hnchen, scharf gew\u00fcrzt\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/09\/13\/gebratenes-hahnchen-scharf-gewurzt\/\" \/>\n<meta property=\"og:site_name\" content=\"Steffen&#039;s Haushaltsblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:published_time\" content=\"2012-09-13T19:36:21+00:00\" \/>\n<meta name=\"author\" content=\"Steffen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steffen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/09\\\/13\\\/gebratenes-hahnchen-scharf-gewurzt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/09\\\/13\\\/gebratenes-hahnchen-scharf-gewurzt\\\/\"},\"author\":{\"name\":\"Steffen\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"headline\":\"Gebratenes H\u00e4hnchen, scharf gew\u00fcrzt\",\"datePublished\":\"2012-09-13T19:36:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/09\\\/13\\\/gebratenes-hahnchen-scharf-gewurzt\\\/\"},\"wordCount\":129,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"keywords\":[\"Huhn\"],\"articleSection\":[\"Asiatisch\",\"Gefl\u00fcgel\",\"Hauptgerichte\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/09\\\/13\\\/gebratenes-hahnchen-scharf-gewurzt\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/09\\\/13\\\/gebratenes-hahnchen-scharf-gewurzt\\\/\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/09\\\/13\\\/gebratenes-hahnchen-scharf-gewurzt\\\/\",\"name\":\"Gebratenes H\u00e4hnchen, scharf gew\u00fcrzt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\"},\"datePublished\":\"2012-09-13T19:36:21+00:00\",\"description\":\"- Gebratenes H\u00e4hnchen, scharf gew\u00fcrzt\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/09\\\/13\\\/gebratenes-hahnchen-scharf-gewurzt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/09\\\/13\\\/gebratenes-hahnchen-scharf-gewurzt\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/09\\\/13\\\/gebratenes-hahnchen-scharf-gewurzt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gebratenes H\u00e4hnchen, scharf gew\u00fcrzt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\",\"name\":\"Steffen&#039;s Haushaltsblog\",\"description\":\"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\\\/ki_kunst \",\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\",\"name\":\"Steffen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"caption\":\"Steffen\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/sthomas.de\",\"https:\\\/\\\/www.facebook.com\\\/steffen.thomas1\",\"https:\\\/\\\/x.com\\\/steto123\"],\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/author\\\/wp_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gebratenes H\u00e4hnchen, scharf gew\u00fcrzt","description":"- Gebratenes H\u00e4hnchen, scharf gew\u00fcrzt","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/09\/13\/gebratenes-hahnchen-scharf-gewurzt\/","og_locale":"de_DE","og_type":"article","og_title":"Gebratenes H\u00e4hnchen, scharf gew\u00fcrzt","og_description":"- Gebratenes H\u00e4hnchen, scharf gew\u00fcrzt","og_url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/09\/13\/gebratenes-hahnchen-scharf-gewurzt\/","og_site_name":"Steffen&#039;s Haushaltsblog","article_publisher":"https:\/\/www.facebook.com\/steffen.thomas1","article_author":"https:\/\/www.facebook.com\/steffen.thomas1","article_published_time":"2012-09-13T19:36:21+00:00","author":"Steffen","twitter_misc":{"Verfasst von":"Steffen","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/09\/13\/gebratenes-hahnchen-scharf-gewurzt\/#article","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/09\/13\/gebratenes-hahnchen-scharf-gewurzt\/"},"author":{"name":"Steffen","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"headline":"Gebratenes H\u00e4hnchen, scharf gew\u00fcrzt","datePublished":"2012-09-13T19:36:21+00:00","mainEntityOfPage":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/09\/13\/gebratenes-hahnchen-scharf-gewurzt\/"},"wordCount":129,"commentCount":0,"publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"keywords":["Huhn"],"articleSection":["Asiatisch","Gefl\u00fcgel","Hauptgerichte"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2012\/09\/13\/gebratenes-hahnchen-scharf-gewurzt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/09\/13\/gebratenes-hahnchen-scharf-gewurzt\/","url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/09\/13\/gebratenes-hahnchen-scharf-gewurzt\/","name":"Gebratenes H\u00e4hnchen, scharf gew\u00fcrzt","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website"},"datePublished":"2012-09-13T19:36:21+00:00","description":"- Gebratenes H\u00e4hnchen, scharf gew\u00fcrzt","breadcrumb":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/09\/13\/gebratenes-hahnchen-scharf-gewurzt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2012\/09\/13\/gebratenes-hahnchen-scharf-gewurzt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/09\/13\/gebratenes-hahnchen-scharf-gewurzt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wissen.science-and-fun.de\/kochen\/"},{"@type":"ListItem","position":2,"name":"Gebratenes H\u00e4hnchen, scharf gew\u00fcrzt"}]},{"@type":"WebSite","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website","url":"https:\/\/wissen.science-and-fun.de\/kochen\/","name":"Steffen&#039;s Haushaltsblog","description":"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\/ki_kunst ","publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wissen.science-and-fun.de\/kochen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8","name":"Steffen","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","caption":"Steffen"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g"},"sameAs":["https:\/\/sthomas.de","https:\/\/www.facebook.com\/steffen.thomas1","https:\/\/x.com\/steto123"],"url":"https:\/\/wissen.science-and-fun.de\/kochen\/author\/wp_admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p1tRoY-17v","jetpack-related-posts":[{"id":2910,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/10\/19\/chicken-kurma\/","url_meta":{"origin":4309,"position":0},"title":"Chicken Kurma","author":"Steffen","date":"19. Oktober 2011","format":false,"excerpt":"Zutaten 1 H\u00e4hnchen a ca. 3 Pfund 2 Rote Chilies in Scheiben 2 Gr\u00fcne Chilies in Scheiben 1 grosse Zwiebel in Scheiben 1 Knoblauchzehe gehackt 2 cm Ingwer gerieben 1 Zitrone Saft 1 Packung Cocosnuss-Pulver 2 Tasse Wasser 1 TL Salz 3 EL Coriander K\u00f6rner 2 EL Pfefferk\u00f6rner 2 EL\u2026","rel":"","context":"In &quot;Asiatisch&quot;","block_context":{"text":"Asiatisch","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/asiatisch\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":765,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/20\/scharfes-hahnchencurry\/","url_meta":{"origin":4309,"position":1},"title":"Scharfes H\u00e4hnchencurry","author":"Steffen","date":"20. April 2011","format":false,"excerpt":"Zutaten: 1 gro\u00dfes H\u00e4hnchen 4 EL Zitronensaft 2 dicke Gem\u00fcsezwiebeln 30 g frischer Ingwer 4 EL Butter oder \u00d6l 1 EL grob zersto\u00dfene Chilischoten Salz 1 Tl geschroteter schwarzer Pfeffer 1 Tl Kurkumapulver 250 ml H\u00fchnerbr\u00fche oder Wasser 4 hartgekochte Eier Zubereitung: Das H\u00e4hnchen waschen und mit Knochen in 8\u2026","rel":"","context":"In &quot;Gefl\u00fcgel&quot;","block_context":{"text":"Gefl\u00fcgel","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/geflugel\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4741,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/12\/22\/opor-ayam-milder-huhner-curry\/","url_meta":{"origin":4309,"position":2},"title":"Opor Ayam (Milder H\u00fchner-Curry)","author":"Steffen","date":"22. Dezember 2012","format":false,"excerpt":"Zutaten 1000 g H\u00e4hnchen grosse St\u00fccke 8 Gr\u00fcne Chilies 1 Packung Kokosnuss-Pulver 1,5 Tassen Wasser 2 TL Glutamat nach Wunsch 1 Lorbeerblatt 3 TL Salz 4 EL \u00d6l 1 Zwiebel 4 Knoblauchzehen 2 TL Koriander-Samen 6 Kerzenn\u00fcsse Zubereitung 2\/3 des Kokosnuss-Pulvers mit 1\/3 des Wasser zum 1. \"Santan\" (dick) vermischen.\u2026","rel":"","context":"In &quot;Gefl\u00fcgel&quot;","block_context":{"text":"Gefl\u00fcgel","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/geflugel\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3993,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/02\/hahnchen-curry-mit-kartoffeln\/","url_meta":{"origin":4309,"position":3},"title":"H\u00e4hnchen-Curry mit Kartoffeln","author":"Steffen","date":"2. M\u00e4rz 2012","format":false,"excerpt":"Zutaten 1 H\u00e4hnchen a ca. 1-1,5kg 300 g Kartoffeln 4 mittlere Zwiebel 2 TL Chili Pulver o. nach Geschmack 1 TL Kurkuma Gelbwurz 3 EL Wasser (1) 1 EL Salz 2 TL Monosodium Glutamat nach Wunsch 1 TL Curry Pulver oder nach Geschmack 1 Packung Cocosnuss-Pulver auch Flocken sind m\u00f6glich\u2026","rel":"","context":"In &quot;Asiatisch&quot;","block_context":{"text":"Asiatisch","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/asiatisch\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4377,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/09\/22\/hahnchen-curry-mit-kartoffeln-2\/","url_meta":{"origin":4309,"position":4},"title":"H\u00e4hnchen-Curry mit Kartoffeln","author":"Steffen","date":"22. September 2012","format":false,"excerpt":"Zutaten 1 H\u00e4hnchen; a ca.1-1,5kg 300 g Kartoffeln 4 mittlere Zwiebel 2 TL Chilli Pulver - odernach Geschmack 1 TL Kurkuma; Gelbwurz 3 EL Wasser; (1) 1 EL Salz 2 TL Monosodium Glutamat - nach Wunsch 1 TL Curry Pulver - oder nach Geschmack 1 Packung Cocosnuss-Pulver - auch Flocken\u2026","rel":"","context":"In &quot;Gefl\u00fcgel&quot;","block_context":{"text":"Gefl\u00fcgel","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/geflugel\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":6050,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/09\/13\/trockener-huehner-curry\/","url_meta":{"origin":4309,"position":5},"title":"Trockener H\u00fchner-Curry","author":"Steffen","date":"13. September 2014","format":false,"excerpt":"Zutaten 1,5 kg H\u00e4hnchen, in mundgerechten St\u00fccke 1 Zitrone Saft 4 EL \u00d6l Salz nach Geschmack 2 Stiele Lemongras 3 mittlere Zwiebeln 1 Knoblauchzehe 2 cm Ingwer 1 TL Senf K\u00f6rner 1 TL Chilipulver oder nach Geschmack 1 TL Kurkuma Gelbwurz Zubereitung Gew\u00fcrzmischung, Chili und Kurkuma in dem hei\u00dfen \u00d6l\u2026","rel":"","context":"In &quot;Asiatisch&quot;","block_context":{"text":"Asiatisch","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/asiatisch\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/4309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/comments?post=4309"}],"version-history":[{"count":1,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/4309\/revisions"}],"predecessor-version":[{"id":4310,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/4309\/revisions\/4310"}],"wp:attachment":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/media?parent=4309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/categories?post=4309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/tags?post=4309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}