{"id":4163,"date":"2012-03-16T21:56:44","date_gmt":"2012-03-16T21:56:44","guid":{"rendered":"https:\/\/wissen.science-and-fun.de\/kochen\/?p=4163"},"modified":"2012-03-16T21:56:44","modified_gmt":"2012-03-16T21:56:44","slug":"paprikasalat","status":"publish","type":"post","link":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/paprikasalat\/","title":{"rendered":"Paprikasalat"},"content":{"rendered":"<p><strong>Zutaten<\/strong><br \/>\n250 g Staudensellerie<br \/>\n250 g Zucchini<br \/>\n2 gr\u00fcne Paprikaschoten<br \/>\n3 EL Wei\u00dfweinessig<br \/>\n1 Prise Zucker<br \/>\n9 EL \u00d6l<br \/>\n1 Bund glatte Petersilie<br \/>\n1 Bund Dill<br \/>\n2 Packungen Schafsk\u00e4se (\u00e0 200 g)<br \/>\nSalz, Pfeffer, frisch gemahlen<\/p>\n<p><strong>Zubereitung<\/strong><br \/>\nStaudensellerie waschen, dabei das Gr\u00fcn zur Seite legen. Staudensellerie in d\u00fcnne Scheiben schneiden. Zucchini waschen, l\u00e4ngs halbieren und in Scheiben schneiden. Paprika waschen, vierteln, in Streifen schneiden und mit Sellerie und Zucchini mischen. Essig mit Salz, Pfeffer, Zucker und \u00d6l anr\u00fchren. Selleriegr\u00fcn und Kr\u00e4uter hacken und unterr\u00fchren. Marinade \u00fcber den Salat gie\u00dfen und 30 Minuten durchziehen lassen. Schafsk\u00e4se w\u00fcrfeln und vor dem Servieren \u00fcber den Salat streuen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zutaten 250 g Staudensellerie 250 g Zucchini 2 gr\u00fcne Paprikaschoten 3 EL Wei\u00dfweinessig 1 Prise Zucker 9 EL \u00d6l 1 Bund glatte Petersilie 1 Bund Dill 2 Packungen Schafsk\u00e4se (\u00e0 200 g) Salz, Pfeffer, frisch gemahlen Zubereitung Staudensellerie waschen, dabei das Gr\u00fcn zur Seite legen. Staudensellerie in d\u00fcnne Scheiben schneiden. Zucchini waschen, l\u00e4ngs halbieren und &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/paprikasalat\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[18,3],"tags":[208],"class_list":["post-4163","post","type-post","status-publish","format-standard","hentry","category-gemuse","category-salat","tag-paprika","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paprikasalat<\/title>\n<meta name=\"description\" content=\"- Paprikasalat\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/paprikasalat\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paprikasalat\" \/>\n<meta property=\"og:description\" content=\"- Paprikasalat\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/paprikasalat\/\" \/>\n<meta property=\"og:site_name\" content=\"Steffen&#039;s Haushaltsblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:published_time\" content=\"2012-03-16T21:56:44+00:00\" \/>\n<meta name=\"author\" content=\"Steffen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steffen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/03\\\/16\\\/paprikasalat\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/03\\\/16\\\/paprikasalat\\\/\"},\"author\":{\"name\":\"Steffen\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"headline\":\"Paprikasalat\",\"datePublished\":\"2012-03-16T21:56:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/03\\\/16\\\/paprikasalat\\\/\"},\"wordCount\":106,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"keywords\":[\"Paprika\"],\"articleSection\":[\"Gem\u00fcse &amp; Obst\",\"Salat\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/03\\\/16\\\/paprikasalat\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/03\\\/16\\\/paprikasalat\\\/\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/03\\\/16\\\/paprikasalat\\\/\",\"name\":\"Paprikasalat\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\"},\"datePublished\":\"2012-03-16T21:56:44+00:00\",\"description\":\"- Paprikasalat\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/03\\\/16\\\/paprikasalat\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/03\\\/16\\\/paprikasalat\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/03\\\/16\\\/paprikasalat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paprikasalat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\",\"name\":\"Steffen&#039;s Haushaltsblog\",\"description\":\"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\\\/ki_kunst \",\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\",\"name\":\"Steffen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"caption\":\"Steffen\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/sthomas.de\",\"https:\\\/\\\/www.facebook.com\\\/steffen.thomas1\",\"https:\\\/\\\/x.com\\\/steto123\"],\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/author\\\/wp_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paprikasalat","description":"- Paprikasalat","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/paprikasalat\/","og_locale":"de_DE","og_type":"article","og_title":"Paprikasalat","og_description":"- Paprikasalat","og_url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/paprikasalat\/","og_site_name":"Steffen&#039;s Haushaltsblog","article_publisher":"https:\/\/www.facebook.com\/steffen.thomas1","article_author":"https:\/\/www.facebook.com\/steffen.thomas1","article_published_time":"2012-03-16T21:56:44+00:00","author":"Steffen","twitter_misc":{"Verfasst von":"Steffen","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/paprikasalat\/#article","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/paprikasalat\/"},"author":{"name":"Steffen","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"headline":"Paprikasalat","datePublished":"2012-03-16T21:56:44+00:00","mainEntityOfPage":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/paprikasalat\/"},"wordCount":106,"commentCount":0,"publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"keywords":["Paprika"],"articleSection":["Gem\u00fcse &amp; Obst","Salat"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/paprikasalat\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/paprikasalat\/","url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/paprikasalat\/","name":"Paprikasalat","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website"},"datePublished":"2012-03-16T21:56:44+00:00","description":"- Paprikasalat","breadcrumb":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/paprikasalat\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/paprikasalat\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/paprikasalat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wissen.science-and-fun.de\/kochen\/"},{"@type":"ListItem","position":2,"name":"Paprikasalat"}]},{"@type":"WebSite","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website","url":"https:\/\/wissen.science-and-fun.de\/kochen\/","name":"Steffen&#039;s Haushaltsblog","description":"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\/ki_kunst ","publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wissen.science-and-fun.de\/kochen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8","name":"Steffen","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","caption":"Steffen"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g"},"sameAs":["https:\/\/sthomas.de","https:\/\/www.facebook.com\/steffen.thomas1","https:\/\/x.com\/steto123"],"url":"https:\/\/wissen.science-and-fun.de\/kochen\/author\/wp_admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p1tRoY-159","jetpack-related-posts":[{"id":1132,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/29\/geflugel-reissalat\/","url_meta":{"origin":4163,"position":0},"title":"Gefl\u00fcgel-Reissalat","author":"Steffen","date":"29. April 2011","format":false,"excerpt":"Zutaten: 250 g Reis Salzwasser 1 gebratenes H\u00e4hnchen (1200 g) 2 kleine Zwiebeln 1 EL Currypulver 2 EL Weinessig 3 EL \u00d6l 1 Gew\u00fcrzgurke 1 Stengel Staudensellerie 1\/2 Glas eingelegter Paprika, rot 250 g Mayonnaise 2 EL Creme fraiche etwas Salz und gemahlener Pfeffer Zubereitung: Den Reis im sprudelnden Salzwasser\u2026","rel":"","context":"In &quot;Salat&quot;","block_context":{"text":"Salat","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/salat\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5101,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2013\/02\/17\/bunter-gemusesalat\/","url_meta":{"origin":4163,"position":1},"title":"Bunter Gem\u00fcsesalat","author":"Steffen","date":"17. Februar 2013","format":false,"excerpt":"Zutaten 80 g gr\u00fcne Bohnen 1 Fenchelknolle 1 Kohlrabi 2 Karotten 2 Stangen Staudensellerie 1 Schalotte 5 EL Oliven\u00f6l 1 EL Sojasauce 1 EL Balsamico-Essig 1 TL Zucker 10 Cocktailtomaten 1\/2 Bund Schnittlauch 1\/2 Bund Blattpetersilie 1\/2 Bund Estragon 1\/2 Bund Pimpinelle Salz, Pfeffer Zubereitung Die Bohnen putzen, in Salzwasser\u2026","rel":"","context":"In &quot;Salat&quot;","block_context":{"text":"Salat","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/salat\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4899,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2013\/01\/16\/kohlrabisalat-mit-walnussen\/","url_meta":{"origin":4163,"position":2},"title":"Kohlrabisalat mit Waln\u00fcssen","author":"Steffen","date":"16. Januar 2013","format":false,"excerpt":"Zutaten 2 Kohlrabi 200 g Staudensellerie 2 \u00c4pfel 4 EL Zitronensaft 4 EL Apfelsaft 1 Priese Zucker (1) Salz Pfeffer 1 EL Joghurt-Salatsauce 150 g Vollmilchjoghurt 1 Priese Zucker; (2) 50 g Walnusskerne Zubereitung Kohlrabi und Sellerie putzen, zartes Gr\u00fcn zur Seite legen. Kohlrabi, \u00c4pfel und Sellerie mit dem Schnitzelwerk\u2026","rel":"","context":"In &quot;Salat&quot;","block_context":{"text":"Salat","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/salat\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2971,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/10\/24\/curry-garnelen\/","url_meta":{"origin":4163,"position":3},"title":"Curry-Garnelen","author":"Steffen","date":"24. Oktober 2011","format":false,"excerpt":"Zutaten 500 g rohe, ungesch\u00e4lte Riesengarnelen 2 EL Zitronensaft 10 g getrocknete Mu-Err-Pilze 1 Stange Porree (250 g) 300 g Staudensellerie 2 Zwiebeln 150 g Bambussch\u00f6\u00dflinge in Streifen 150 g Zuckererbsen 2 rote Chilischoten 150 g Mango-Bohnen-Sprossen 1 St\u00fcck Ingwer (30 g) 3 EL Sesam\u00f6l 2 EL Curry 100 ml\u2026","rel":"","context":"In &quot;Asiatisch&quot;","block_context":{"text":"Asiatisch","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/asiatisch\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5490,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/01\/15\/nizza-salat\/","url_meta":{"origin":4163,"position":4},"title":"Nizza-Salat","author":"Steffen","date":"15. Januar 2014","format":false,"excerpt":"Zutaten 200 g Pellkartoffeln 4 Tomaten 2 Hartgekochte Eier 1 gr\u00fcne Paprikaschote 1 Zwiebel 1 Kopfsalat 1 Dose Thunfisch in \u00d6l 10 Oliven 1 Knoblauchzehe 3 EL Essig 6 EL \u00d6l 1\/2 EL Senf Salz, Pfeffer Zucker 1 Bund glatte Petersilie Zubereitung Kartoffeln in Scheiben, Tomaten und Eier in Achtel,\u2026","rel":"","context":"In &quot;Salat&quot;","block_context":{"text":"Salat","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/salat\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5104,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2013\/02\/18\/hackbraten-mit-kohlrabi-pfifferling-salat\/","url_meta":{"origin":4163,"position":5},"title":"Hackbraten mit Kohlrabi-Pfifferling Salat","author":"Steffen","date":"18. Februar 2013","format":false,"excerpt":"Zutaten Hackbraten 70 g Wei\u00dfbrot (ohne Rinde) 100 ml Milch 1 kleine Zwiebel 1\/2 kleine Zucchino 1\/2 Rote Paprikaschote 10 g Getrocknete Trompetenpilze 2 EL \u00d6l 1\/2 Gehackte Knoblauchzehe 100 g Kalbsbr\u00e4t 1-2 EL Sahne 150 g H\u00e4hnchenschenkelfleisch, (ohne Haut und Knochen) 350 g Schweinehackfleisch 2 Eier 1 TL Scharfer\u2026","rel":"","context":"In &quot;Hauptgerichte&quot;","block_context":{"text":"Hauptgerichte","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/4163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/comments?post=4163"}],"version-history":[{"count":1,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/4163\/revisions"}],"predecessor-version":[{"id":4164,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/4163\/revisions\/4164"}],"wp:attachment":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/media?parent=4163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/categories?post=4163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/tags?post=4163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}