{"id":4154,"date":"2012-03-16T21:11:09","date_gmt":"2012-03-16T21:11:09","guid":{"rendered":"https:\/\/wissen.science-and-fun.de\/kochen\/?p=4154"},"modified":"2012-03-16T21:13:38","modified_gmt":"2012-03-16T21:13:38","slug":"pei-ching-kao-ya-peking-ente","status":"publish","type":"post","link":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/pei-ching-kao-ya-peking-ente\/","title":{"rendered":"Pei-ching-k&#8217;ao-ya (Peking-Ente)"},"content":{"rendered":"<p><strong>Zutaten<\/strong><br \/>\n2\/3 Ente; pro Ente ca. 2,5 kg<br \/>\n1 l Wasser<br \/>\n40 g Honig<br \/>\n2 Scheiben Ingwerwurzel; gesch\u00e4lt, frisch oder konserviert, pro Scheibe etwa 2 1\/2 cm Durchmesser und 3 mm dick<br \/>\n1 Fr\u00fchlingszwiebeln mit gr\u00fcnen Spitzen in 5 cm lange St\u00fccke geschnitten<br \/>\n<em>Sauce<\/em><br \/>\n0,2 Tasse Hoisin-Sauce<br \/>\n2\/3 EL Wasser<br \/>\n2\/3 TL Sesamsamen\u00f6l<br \/>\n1 TL Zucker<\/p>\n<p>8 Fr\u00fchlingszwiebeln<br \/>\n1 Rezept Mandarin-Pfannkuchen<\/p>\n<p><strong>Zubereitung<\/strong><br \/>\n<em>Vorbereitung: Die Ente unter fliessendem kaltem Wasser waschen und innen und aussen mit K\u00fcchenkrepp abtupfen. Das eine Ende eines 50 cm langen weissen Bindfadens um den Halslappen binden. Wenn der Halslappen abgeschnitten ist, zieht man den Faden unter den Fl\u00fcgeln durch. Um die Haut zu trocknen, h\u00e4ngt man das Tier 3 Stunden an einen k\u00fchlen, luftigen Ort oder 2 Stunden vor einem Ventilator auf.<br \/>\nIn einen Wok von 30 cm Durchmesser oder eine grosse, feuerfeste Kasserolle 1,5 l Wasser, Honig, Ingwerwurzel und zerschnittene Fr\u00fchlingszwiebeln geben und \u00fcber grosser Flamme aufkochen. Die Ente am Faden haltend in die kochende Fl\u00fcssigkeit tauchen. Mit dem Faden in der einen und einem L\u00f6ffel in der anderen Hand die Ente von einer Seite auf die andere drehen, bis die Haut \u00fcberall von der Fl\u00fcssigkeit benetzt ist. Die Ente herausnehmen (die Fl\u00fcssigkeit fortgiessen), wieder k\u00fchl und luftig aufh\u00e4ngen und zum Abtropfen eine Sch\u00fcssel darunter stellen. Vor dem Ventilator trocknet die Ente in 1 Stunde, ohne Ventilator in 2 bis 3 Stunden.<br \/>\nF\u00fcr die Sauce Wasser, Hoisin-Sauce, Sesamsamen\u00f6l und Zucker in einer kleinen Pfanne vermengen und r\u00fchren, bis sich der Zucker aufgel\u00f6st hat. Aufkochen, auf niedrigste Temperatur schalten und ohne Deckel 3 Minuten langsam kochen. In einer kleinen Sch\u00fcssel abk\u00fchlen lassen.<br \/>\nF\u00fcr die Fr\u00fchlingszwiebelstr\u00e4usschen schneidet man die Fr\u00fchlingszwiebeln in 7,5cm lange St\u00fccke und entfernt die Wurzeln. Jeden Stengel senkrecht von beiden Enden her viermal kreuzweise 2,5cm tief einschneiden, in Eiswasser legen und in den K\u00fchlschrank stellen, bis sich die eingeschnittenen Enden nach aussen aufrollen.<br \/>\n<em>Zubereitung: Den Ofen auf 200 Grad vorheizen. Die Ente herunternehmen und die lose Halshaut abschneiden. In einen Br\u00e4ter, der gerade gross genug ist, um die Ente bequem zu fassen, legt man sie mit der Brust nach oben auf einen Einsatz. Die Ente in der Mitte des Backofens 1 Stunde lang braten. Dann die Temperatur auf 150 Grad herunterschalten, die Ente auf die Brust drehen und weitere 30 Minuten braten. Nun wieder auf 200 Grad schalten, die Ente auf den R\u00fccken legen und abschliessend noch 30 Minuten braten. Auf ein Tranchierbrett legen.<br \/>\nMit einem kleinen, scharfen Messer und den Fingern die knusprige Haut von Brust, Seiten und R\u00fccken der Ente abnehmen. In 5 x 7,5 cm grosse Rechtecke schneiden und auf eine vorgew\u00e4rmte Platte legen. Fl\u00fcgel, Keulen und alles Fleisch der Ente von Brust und Knochen abschneiden. Das Fleisch in 6 cm lange und 1 cm breite St\u00fcckchen tranchieren und mit Fl\u00fcgeln und Keulen auf einer zweiten vorgew\u00e4rmten Platte anrichten.<br \/>\nBeim Servieren stellt man die Platten mit der Ente, den warmen Pfannkuchen, Sauce und Fr\u00fchlingszwiebelstr\u00e4usschen in die Mitte des Tisches. Traditionsgem\u00e4ss legt sich jeder Gast einen Pfannkuchen flach auf den Teller, taucht ein Fr\u00fchlingszwiebelstr\u00e4usschen in die Sauce und bestreicht damit den Pfannkuchen. Dann kommt das Str\u00e4usschen mit einem St\u00fcckchen Haut und einem obenauf gelegten St\u00fcck Fleisch in die Mitte des Pfannkuchens. Der Pfannkuchen wird \u00fcber diese F\u00fcllung geschlagen und zu einem Zylinder aufgerollt, den man bequem in die Hand nehmen und essen kann. Peking-Ente ist als Hauptgang ausreichend f\u00fcr sechs Personen. Als Bestandteil einer chinesischen Mahlzeit ausreichend f\u00fcr acht bis zehn Personen. Bei \u00fcber sechs Personen sind mehr Fr\u00fchlingszwiebelstr\u00e4usschen und Pfannkuchen erforderlich.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zutaten 2\/3 Ente; pro Ente ca. 2,5 kg 1 l Wasser 40 g Honig 2 Scheiben Ingwerwurzel; gesch\u00e4lt, frisch oder konserviert, pro Scheibe etwa 2 1\/2 cm Durchmesser und 3 mm dick 1 Fr\u00fchlingszwiebeln mit gr\u00fcnen Spitzen in 5 cm lange St\u00fccke geschnitten Sauce 0,2 Tasse Hoisin-Sauce 2\/3 EL Wasser 2\/3 TL Sesamsamen\u00f6l 1 TL &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/pei-ching-kao-ya-peking-ente\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,43,6],"tags":[44],"class_list":["post-4154","post","type-post","status-publish","format-standard","hentry","category-asiatisch","category-geflugel","category-hauptgerichte","tag-ente","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pei-ching-k&#039;ao-ya (Peking-Ente)<\/title>\n<meta name=\"description\" content=\"- Pei-ching-k&#039;ao-ya (Peking-Ente)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/pei-ching-kao-ya-peking-ente\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pei-ching-k&#039;ao-ya (Peking-Ente)\" \/>\n<meta property=\"og:description\" content=\"- Pei-ching-k&#039;ao-ya (Peking-Ente)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/pei-ching-kao-ya-peking-ente\/\" \/>\n<meta property=\"og:site_name\" content=\"Steffen&#039;s Haushaltsblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:published_time\" content=\"2012-03-16T21:11:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-03-16T21:13:38+00:00\" \/>\n<meta name=\"author\" content=\"Steffen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steffen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/03\\\/16\\\/pei-ching-kao-ya-peking-ente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/03\\\/16\\\/pei-ching-kao-ya-peking-ente\\\/\"},\"author\":{\"name\":\"Steffen\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"headline\":\"Pei-ching-k&#8217;ao-ya (Peking-Ente)\",\"datePublished\":\"2012-03-16T21:11:09+00:00\",\"dateModified\":\"2012-03-16T21:13:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/03\\\/16\\\/pei-ching-kao-ya-peking-ente\\\/\"},\"wordCount\":599,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"keywords\":[\"Ente\"],\"articleSection\":[\"Asiatisch\",\"Gefl\u00fcgel\",\"Hauptgerichte\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/03\\\/16\\\/pei-ching-kao-ya-peking-ente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/03\\\/16\\\/pei-ching-kao-ya-peking-ente\\\/\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/03\\\/16\\\/pei-ching-kao-ya-peking-ente\\\/\",\"name\":\"Pei-ching-k'ao-ya (Peking-Ente)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\"},\"datePublished\":\"2012-03-16T21:11:09+00:00\",\"dateModified\":\"2012-03-16T21:13:38+00:00\",\"description\":\"- Pei-ching-k'ao-ya (Peking-Ente)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/03\\\/16\\\/pei-ching-kao-ya-peking-ente\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/03\\\/16\\\/pei-ching-kao-ya-peking-ente\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2012\\\/03\\\/16\\\/pei-ching-kao-ya-peking-ente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pei-ching-k&#8217;ao-ya (Peking-Ente)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\",\"name\":\"Steffen&#039;s Haushaltsblog\",\"description\":\"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\\\/ki_kunst \",\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\",\"name\":\"Steffen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"caption\":\"Steffen\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/sthomas.de\",\"https:\\\/\\\/www.facebook.com\\\/steffen.thomas1\",\"https:\\\/\\\/x.com\\\/steto123\"],\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/author\\\/wp_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pei-ching-k'ao-ya (Peking-Ente)","description":"- Pei-ching-k'ao-ya (Peking-Ente)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/pei-ching-kao-ya-peking-ente\/","og_locale":"de_DE","og_type":"article","og_title":"Pei-ching-k'ao-ya (Peking-Ente)","og_description":"- Pei-ching-k'ao-ya (Peking-Ente)","og_url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/pei-ching-kao-ya-peking-ente\/","og_site_name":"Steffen&#039;s Haushaltsblog","article_publisher":"https:\/\/www.facebook.com\/steffen.thomas1","article_author":"https:\/\/www.facebook.com\/steffen.thomas1","article_published_time":"2012-03-16T21:11:09+00:00","article_modified_time":"2012-03-16T21:13:38+00:00","author":"Steffen","twitter_misc":{"Verfasst von":"Steffen","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/pei-ching-kao-ya-peking-ente\/#article","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/pei-ching-kao-ya-peking-ente\/"},"author":{"name":"Steffen","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"headline":"Pei-ching-k&#8217;ao-ya (Peking-Ente)","datePublished":"2012-03-16T21:11:09+00:00","dateModified":"2012-03-16T21:13:38+00:00","mainEntityOfPage":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/pei-ching-kao-ya-peking-ente\/"},"wordCount":599,"commentCount":0,"publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"keywords":["Ente"],"articleSection":["Asiatisch","Gefl\u00fcgel","Hauptgerichte"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/pei-ching-kao-ya-peking-ente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/pei-ching-kao-ya-peking-ente\/","url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/pei-ching-kao-ya-peking-ente\/","name":"Pei-ching-k'ao-ya (Peking-Ente)","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website"},"datePublished":"2012-03-16T21:11:09+00:00","dateModified":"2012-03-16T21:13:38+00:00","description":"- Pei-ching-k'ao-ya (Peking-Ente)","breadcrumb":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/pei-ching-kao-ya-peking-ente\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/pei-ching-kao-ya-peking-ente\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/16\/pei-ching-kao-ya-peking-ente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wissen.science-and-fun.de\/kochen\/"},{"@type":"ListItem","position":2,"name":"Pei-ching-k&#8217;ao-ya (Peking-Ente)"}]},{"@type":"WebSite","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website","url":"https:\/\/wissen.science-and-fun.de\/kochen\/","name":"Steffen&#039;s Haushaltsblog","description":"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\/ki_kunst ","publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wissen.science-and-fun.de\/kochen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8","name":"Steffen","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","caption":"Steffen"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g"},"sameAs":["https:\/\/sthomas.de","https:\/\/www.facebook.com\/steffen.thomas1","https:\/\/x.com\/steto123"],"url":"https:\/\/wissen.science-and-fun.de\/kochen\/author\/wp_admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p1tRoY-150","jetpack-related-posts":[{"id":3300,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/27\/hsiang-su-ya-szechuan-ente\/","url_meta":{"origin":4154,"position":0},"title":"Hsiang-Su-Ya (Szechuan-Ente)","author":"Steffen","date":"27. Dezember 2011","format":false,"excerpt":"Zutaten 1 Ente; 2 bis 2,5 kg schwer 2 EL Salz 1 EL Szechuan-Pfefferk\u00f6rner mit dem K\u00fcchenbeil oder im M\u00f6rser zerstossen 4 Scheiben Ingwerwurzel; frisch oder konserviert, etwa 2,5 cm im Durchmesser und 1\/2 cm dick 2 Fr\u00fchlingszwiebeln; mit gr\u00fcnen Spitzen, in 5 cm lange St\u00fccke geschnitten 2 EL Sojasauce\u2026","rel":"","context":"In &quot;Gefl\u00fcgel&quot;","block_context":{"text":"Gefl\u00fcgel","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/geflugel\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5550,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/02\/13\/peking-ente-mit-mandarin-pfannkuchen\/","url_meta":{"origin":4154,"position":1},"title":"Peking Ente mit Mandarin Pfannkuchen","author":"Steffen","date":"13. Februar 2014","format":false,"excerpt":"Zutaten 1 Bauernente, k\u00fcchenfertig (ca. 2.5 kg) Glasur 4 EL Honig 4 EL Dunkle Sojasosse 75 ml trockener Sherry 1\/2 TL Frische Ingwerwurzel gerieben 1\/2 TL Salz Pfannkuchenteig 300 g Mehl 1\/4 l kochendes Wasser 2 EL Erdnuss\u00f6l au\u00dferdem Pflaumen-Dip s\u00fcss-scharf Hoisinsauce 1 Bund Fr\u00fchlingszwiebeln 1 Gurke Zubereitung Die Ente\u2026","rel":"","context":"In &quot;Asiatisch&quot;","block_context":{"text":"Asiatisch","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/asiatisch\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3330,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/27\/ente-mit-mandarinenpfannkuchen\/","url_meta":{"origin":4154,"position":2},"title":"Ente mit Mandarinenpfannkuchen","author":"Steffen","date":"27. Dezember 2011","format":false,"excerpt":"Zutaten 1 Ente (k\u00fcchenfertig), etwa 1,7 kg 3 l kochendes Wasser 1 EL Honig 125 ml heisses Wasser 1 Schmorgurke 12 Fr\u00fchlingszwiebeln 2 EL Hoisin-Sauce Mandarinpfannkuchen 310 g Weizenmehl 2 EL Feiner Zucker 250 ml kochendes Wasser 1 EL Sesam\u00f6l Zubereitung Die Ente waschen, Hals und alle gr\u00f6\u00dferen Fettpartien im\u2026","rel":"","context":"In &quot;Asiatisch&quot;","block_context":{"text":"Asiatisch","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/asiatisch\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3334,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/27\/ente-mit-tausend-gewurzen\/","url_meta":{"origin":4154,"position":3},"title":"Ente Mit Tausend-Gew\u00fcrzen","author":"Steffen","date":"27. Dezember 2011","format":false,"excerpt":"Zutaten 2\/3 Ente; k\u00fcchenfertig - a ca. 2 kg) 0,2 Getrocknete Tangerinenschale 2\/3 frische Ingwerwurzel 2 Schalotten 1 Ganze Sternanis 4 EL Gelbe Bohnensauce 3,5 EL Hoisinsauce 2\/3 EL Sesampaste 2\/3 EL F\u00fcnf-Gew\u00fcrz-Pulver 1 TL Ingwerpulver 1 TL Salz 1 EL brauner Zucker 2\/3 EL Gin 4 Fr\u00fchlingszwiebeln 370 g\u2026","rel":"","context":"In &quot;Asiatisch&quot;","block_context":{"text":"Asiatisch","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/asiatisch\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":601,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/15\/ente-nach-anita-wong\/","url_meta":{"origin":4154,"position":4},"title":"Ente nach Anita Wong","author":"Steffen","date":"15. April 2011","format":false,"excerpt":"Zutaten: 1 Ente mit Innereien, ca. 2,25 kg 4 EL Pflanzen\u00f6l 2 Koblauchzehen, gehackt 2 1\/2 cm St\u00fcck Ingwerwurzel, gesch\u00e4lt und d\u00fcnn geschnitten 3 EL Bohnenpaste 2 EL helle Sojaso\u00dfe 1 EL dunkle Sojaso\u00dfe 1 EL Zucker 1\/2 TL F\u00fcnf-Gew\u00fcrze-Pulver 3 Sternanissamen 450 ml Entenfond Salz Klein geschnittene Fr\u00fchlingszwiebeln zum\u2026","rel":"","context":"In &quot;Gefl\u00fcgel&quot;","block_context":{"text":"Gefl\u00fcgel","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/geflugel\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4288,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/09\/08\/gebratene-entenbrust-in-salatblattern\/","url_meta":{"origin":4154,"position":5},"title":"Gebratene Entenbrust in Salatbl\u00e4ttern","author":"Steffen","date":"8. September 2012","format":false,"excerpt":"Zutaten 2 Entenbr\u00fcste ohne Knochen Salz Zucker 3 El Sojasauce 3 El Sherry 1 El Sesam\u00f6l 1 Tl Speisest\u00e4rke 2 El neutrales \u00d6l 50 g gesch\u00e4lte Mandeln 1 Tl feingehackter Ingwer 1 Tl feingehackter Knoblauch 4 Fr\u00fchlingszwiebeln in Ringe geschnitten 1 El Austernsauce Salatbl\u00e4tter 4 El Apfelessig 2 El Wasser\u2026","rel":"","context":"In &quot;Gefl\u00fcgel&quot;","block_context":{"text":"Gefl\u00fcgel","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/geflugel\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/4154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/comments?post=4154"}],"version-history":[{"count":2,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/4154\/revisions"}],"predecessor-version":[{"id":4156,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/4154\/revisions\/4156"}],"wp:attachment":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/media?parent=4154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/categories?post=4154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/tags?post=4154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}