{"id":3321,"date":"2011-12-27T14:53:40","date_gmt":"2011-12-27T14:53:40","guid":{"rendered":"https:\/\/wissen.science-and-fun.de\/kochen\/?p=3321"},"modified":"2011-12-27T14:53:40","modified_gmt":"2011-12-27T14:53:40","slug":"ente-mit-gruner-pfeffersauce","status":"publish","type":"post","link":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/27\/ente-mit-gruner-pfeffersauce\/","title":{"rendered":"Ente mit Gr\u00fcner Pfeffersauce"},"content":{"rendered":"<p><strong>Zutaten<\/strong><br \/>\n2 Enten \u00e0 1 kg<br \/>\n1 Essl\u00f6ffel gr\u00fcne Pfefferk\u00f6rner<br \/>\n2 Schalotten<br \/>\n60 g Butter<br \/>\n4 Essl\u00f6ffel Cognac<br \/>\n1 Glas trockener Wei\u00dfwein<br \/>\n1 gestrichener Essl\u00f6ffel Speisest\u00e4rke<br \/>\n100 g saure Sahne<br \/>\nSalz <\/p>\n<p><strong>Zubereitung<\/strong><br \/>\nEnten bei 210 Grad (Gas Stufe 7) ohne Zugabe von Fett 30 Minuten braten, dabei zweimal wenden, damit sie gleichm\u00e4\u00dfig br\u00e4unen. Sofort zerlegen und Fleischsaft auffangen. Zuerst Keulen, dann Fl\u00fcgel austrennen, Haut von den Filets entfernen und Filets in Streifen schneiden, warmstellen, ohne dass das Fleisch dabei weitergart. Das Fleisch sollte rosa und blutig gebraten sein. Das Entengerippe grob zerkleinern, alles Fett entfernen und mit den Schalottenscheiben in 1 Essl\u00f6ffel Butter and\u00fcnsten. Sobald die Butter brutzelt, Wei\u00dfwein und Cognac zugie\u00dfen, Deckel aufsetzen, 20 &#8211; 25 Minuten bei starker Hitze schmoren.<br \/>\nDurch ein Passiersieb streichen, Saft auffangen, Siebsatz durchdr\u00fccken, um soviel Saft wie m\u00f6glich auszupressen, wenn n\u00f6tig Siebsatz mit 2 Essl\u00f6ffeln hei\u00dfem Wasser verd\u00fcnnen. Sauce etwas ruhen lassen, bis sich das Fett an der Oberfl\u00e4che sammelt, dann Fett absch\u00f6pfen. Gr\u00fcnen Pfeffer grob zersto\u00dfen, mit 4 &#8211; 5 Essl\u00f6ffeln saurer<br \/>\nSahne und der in etwas kaltem Wasser aufgel\u00f6sten Speisest\u00e4rke in die Sauce geben. 10 &#8211; 15 Minuten k\u00f6cheln, wenn n\u00f6tig absch\u00e4umen, dann salzen. Entenbruststreifen mit dem Fleischsaft in den gereinigten Schmortopf zur\u00fcckgeben, mit der kochenden Sauce \u00fcbergie\u00dfen, Deckel aufsetzen und warmhalten. Entenkeulen unter dem Grill knusprig braten. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zutaten 2 Enten \u00e0 1 kg 1 Essl\u00f6ffel gr\u00fcne Pfefferk\u00f6rner 2 Schalotten 60 g Butter 4 Essl\u00f6ffel Cognac 1 Glas trockener Wei\u00dfwein 1 gestrichener Essl\u00f6ffel Speisest\u00e4rke 100 g saure Sahne Salz Zubereitung Enten bei 210 Grad (Gas Stufe 7) ohne Zugabe von Fett 30 Minuten braten, dabei zweimal wenden, damit sie gleichm\u00e4\u00dfig br\u00e4unen. Sofort zerlegen &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/27\/ente-mit-gruner-pfeffersauce\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[43,6],"tags":[44],"class_list":["post-3321","post","type-post","status-publish","format-standard","hentry","category-geflugel","category-hauptgerichte","tag-ente","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ente mit Gr\u00fcner Pfeffersauce<\/title>\n<meta name=\"description\" content=\"- Ente mit Gr\u00fcner Pfeffersauce\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/27\/ente-mit-gruner-pfeffersauce\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ente mit Gr\u00fcner Pfeffersauce\" \/>\n<meta property=\"og:description\" content=\"- Ente mit Gr\u00fcner Pfeffersauce\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/27\/ente-mit-gruner-pfeffersauce\/\" \/>\n<meta property=\"og:site_name\" content=\"Steffen&#039;s Haushaltsblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:published_time\" content=\"2011-12-27T14:53:40+00:00\" \/>\n<meta name=\"author\" content=\"Steffen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steffen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/12\\\/27\\\/ente-mit-gruner-pfeffersauce\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/12\\\/27\\\/ente-mit-gruner-pfeffersauce\\\/\"},\"author\":{\"name\":\"Steffen\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"headline\":\"Ente mit Gr\u00fcner Pfeffersauce\",\"datePublished\":\"2011-12-27T14:53:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/12\\\/27\\\/ente-mit-gruner-pfeffersauce\\\/\"},\"wordCount\":233,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"keywords\":[\"Ente\"],\"articleSection\":[\"Gefl\u00fcgel\",\"Hauptgerichte\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/12\\\/27\\\/ente-mit-gruner-pfeffersauce\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/12\\\/27\\\/ente-mit-gruner-pfeffersauce\\\/\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/12\\\/27\\\/ente-mit-gruner-pfeffersauce\\\/\",\"name\":\"Ente mit Gr\u00fcner Pfeffersauce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\"},\"datePublished\":\"2011-12-27T14:53:40+00:00\",\"description\":\"- Ente mit Gr\u00fcner Pfeffersauce\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/12\\\/27\\\/ente-mit-gruner-pfeffersauce\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/12\\\/27\\\/ente-mit-gruner-pfeffersauce\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/12\\\/27\\\/ente-mit-gruner-pfeffersauce\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ente mit Gr\u00fcner Pfeffersauce\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\",\"name\":\"Steffen&#039;s Haushaltsblog\",\"description\":\"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\\\/ki_kunst \",\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\",\"name\":\"Steffen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"caption\":\"Steffen\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/sthomas.de\",\"https:\\\/\\\/www.facebook.com\\\/steffen.thomas1\",\"https:\\\/\\\/x.com\\\/steto123\"],\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/author\\\/wp_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ente mit Gr\u00fcner Pfeffersauce","description":"- Ente mit Gr\u00fcner Pfeffersauce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/27\/ente-mit-gruner-pfeffersauce\/","og_locale":"de_DE","og_type":"article","og_title":"Ente mit Gr\u00fcner Pfeffersauce","og_description":"- Ente mit Gr\u00fcner Pfeffersauce","og_url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/27\/ente-mit-gruner-pfeffersauce\/","og_site_name":"Steffen&#039;s Haushaltsblog","article_publisher":"https:\/\/www.facebook.com\/steffen.thomas1","article_author":"https:\/\/www.facebook.com\/steffen.thomas1","article_published_time":"2011-12-27T14:53:40+00:00","author":"Steffen","twitter_misc":{"Verfasst von":"Steffen","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/27\/ente-mit-gruner-pfeffersauce\/#article","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/27\/ente-mit-gruner-pfeffersauce\/"},"author":{"name":"Steffen","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"headline":"Ente mit Gr\u00fcner Pfeffersauce","datePublished":"2011-12-27T14:53:40+00:00","mainEntityOfPage":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/27\/ente-mit-gruner-pfeffersauce\/"},"wordCount":233,"commentCount":0,"publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"keywords":["Ente"],"articleSection":["Gefl\u00fcgel","Hauptgerichte"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/27\/ente-mit-gruner-pfeffersauce\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/27\/ente-mit-gruner-pfeffersauce\/","url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/27\/ente-mit-gruner-pfeffersauce\/","name":"Ente mit Gr\u00fcner Pfeffersauce","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website"},"datePublished":"2011-12-27T14:53:40+00:00","description":"- Ente mit Gr\u00fcner Pfeffersauce","breadcrumb":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/27\/ente-mit-gruner-pfeffersauce\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/27\/ente-mit-gruner-pfeffersauce\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/27\/ente-mit-gruner-pfeffersauce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wissen.science-and-fun.de\/kochen\/"},{"@type":"ListItem","position":2,"name":"Ente mit Gr\u00fcner Pfeffersauce"}]},{"@type":"WebSite","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website","url":"https:\/\/wissen.science-and-fun.de\/kochen\/","name":"Steffen&#039;s Haushaltsblog","description":"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\/ki_kunst ","publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wissen.science-and-fun.de\/kochen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8","name":"Steffen","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","caption":"Steffen"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g"},"sameAs":["https:\/\/sthomas.de","https:\/\/www.facebook.com\/steffen.thomas1","https:\/\/x.com\/steto123"],"url":"https:\/\/wissen.science-and-fun.de\/kochen\/author\/wp_admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p1tRoY-Rz","jetpack-related-posts":[{"id":3494,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/01\/08\/lauwarmer-linsensalat-mit-entenbrust\/","url_meta":{"origin":3321,"position":0},"title":"Lauwarmer Linsensalat mit Entenbrust","author":"Steffen","date":"8. Januar 2012","format":false,"excerpt":"Zutaten 1 ausgel\u00f6ste Entenbrust (350 g) Salz Pfeffer f.a.d.M. 2 Schalotten 2 EL \u00d6l 200 g rote Linsen 1 l Gem\u00fcsebr\u00fche (Instant) 2 Lorbeerbl\u00e4tter 1 Messerspitze Nelkenpulver 4-5 Salbeibl\u00e4tter 250 g Spinat Muskat Zitronensaft 1 EL Butter 1 EL Zucker Saft einer Orange 1-2 EL Wei\u00dfweinessig 2 cl Orangenlik\u00f6r Zubereitung\u2026","rel":"","context":"In &quot;Salat&quot;","block_context":{"text":"Salat","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/salat\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3316,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/27\/gebratene-junge-ente-an-rubchen\/","url_meta":{"origin":3321,"position":1},"title":"Gebratene junge Ente an R\u00fcbchen","author":"Steffen","date":"27. Dezember 2011","format":false,"excerpt":"Zutaten 1 junge Ente mit 500-800 g Gewicht, mit Parueren (Fleischreste, gibt der Metzger mit) 7 g Butter 25 g M\u00f6hren 25 g Metzgerzwiebeln 1\/2 Knoblauchzehe 1 Kr\u00e4uterstr\u00e4usschen Bouquet garni 50 ml Weisswein Kalbsfond oder Wasser 500 g R\u00fcbchen 100 g Perlzwiebeln 20 g Butter Petersilie Salz, Pfeffer Zucker Zubereitung\u2026","rel":"","context":"In &quot;Gefl\u00fcgel&quot;","block_context":{"text":"Gefl\u00fcgel","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/geflugel\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1999,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/06\/12\/schweinelendchen-nach-winzerart\/","url_meta":{"origin":3321,"position":2},"title":"Schweinelendchen nach Winzerart","author":"Steffen","date":"12. Juni 2011","format":false,"excerpt":"Zutaten 1 Schweinsfilet Butterfett 1 Schalotte (gehackt) 100 Gramm Gekochter Schinken (feine Streifen) 100 Gramm Champignons (bl\u00e4ttrig) 200 Gramm Wei\u00dfe Trauben ohne Kerne 1\/4 Liter Wei\u00dfwein (Riesling) Salz Pfeffer 20 ml Cognac 100 ml Sahne Petersilie (gehackt) Zubereitung Das Filet von H\u00e4uten und Fett befreien. In dicke Scheiben schneiden und\u2026","rel":"","context":"In &quot;Hauptgerichte&quot;","block_context":{"text":"Hauptgerichte","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1817,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/23\/kalbsfilet-mit-spargel\/","url_meta":{"origin":3321,"position":3},"title":"Kalbsfilet mit Spargel","author":"Steffen","date":"23. Mai 2011","format":false,"excerpt":"Zutaten 600 Gramm Kalbsfilet (4 Scheiben) Fett zum Braten Pfeffer & Salz 400 Gramm Gekochter gr\u00fcner Spargel 2 EL Butter 24 Hummerkrabbenschw\u00e4nze (tiefgek\u00fchlt) Salzwasser Sauce 75 Gramm Butter 1 Eigelb 1 EL Wei\u00dfwein 1,5 Bund Petersilie 1 TL Tomatenmark Pfeffer, Salz Zitronensaft Zubereitung Zuerst die Sauce zubereiten. 1. Dazu die\u2026","rel":"","context":"In &quot;Hauptgerichte&quot;","block_context":{"text":"Hauptgerichte","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4041,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/05\/lammragout\/","url_meta":{"origin":3321,"position":4},"title":"Lammragout","author":"Steffen","date":"5. M\u00e4rz 2012","format":false,"excerpt":"Zutaten 200 g M\u00f6hren 1 Stange Lauch 100 g Sojasprossen 150 g Basmatireis Salz 100 g Butter zum D\u00fcnsten und Braten 80 g Cashewn\u00fcsse 600 g Lammfleisch, ohne Knochen aus der Keule \u00d6l, zum Braten Pfeffer, aus der M\u00fchle 3 Schalotten, feingew\u00fcrfelt 100 ml Weisswein 2 EL Weisswein, f\u00fcr den\u2026","rel":"","context":"In &quot;Hauptgerichte&quot;","block_context":{"text":"Hauptgerichte","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3283,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/26\/elsasser-gewurztraminer-ente\/","url_meta":{"origin":3321,"position":5},"title":"Els\u00e4sser Gew\u00fcrztraminer-Ente","author":"Steffen","date":"26. Dezember 2011","format":false,"excerpt":"Zutaten 2\/3 Ente; a etwa 2,2 kg - mit Innereien 30 g Korinthen Schwarzer Pfeffer 0.2 l Gew\u00fcrztraminer 1 Entenbrustfilets; a 325 g 100 g kleine Zwiebeln 70 g Walnusskerne 2 Scheiben Weizentoastbrot 4 EL Schlagsahne 1 Eier Salz 1 EL Dunkles Saucenbindemittel 1\/3 l Wasser Zubereitung Die Leber und\u2026","rel":"","context":"In &quot;Gefl\u00fcgel&quot;","block_context":{"text":"Gefl\u00fcgel","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/geflugel\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/3321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/comments?post=3321"}],"version-history":[{"count":1,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/3321\/revisions"}],"predecessor-version":[{"id":3322,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/3321\/revisions\/3322"}],"wp:attachment":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/media?parent=3321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/categories?post=3321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/tags?post=3321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}