{"id":2744,"date":"2011-08-30T18:38:55","date_gmt":"2011-08-30T18:38:55","guid":{"rendered":"https:\/\/wissen.science-and-fun.de\/kochen\/?p=2744"},"modified":"2011-08-30T18:38:55","modified_gmt":"2011-08-30T18:38:55","slug":"cafe-royal","status":"publish","type":"post","link":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/08\/30\/cafe-royal\/","title":{"rendered":"Caf\u00e9 Royal"},"content":{"rendered":"<p><strong>Zutaten<\/strong><br \/>\n1 Tasse Caff\u00e8 Creme<br \/>\n1 St\u00fcck W\u00fcrfelzucker<\/p>\n<p><strong>Zubereitung<\/strong><br \/>\nEine Tasse Cafe Creme, \u00fcber der auf einem L\u00f6ffel ein St\u00fcck W\u00fcrfelzucker flambiert wird. Den hei\u00dfen Zucker l\u00e4\u00dft man in den Kaffee tropfen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zutaten 1 Tasse Caff\u00e8 Creme 1 St\u00fcck W\u00fcrfelzucker Zubereitung Eine Tasse Cafe Creme, \u00fcber der auf einem L\u00f6ffel ein St\u00fcck W\u00fcrfelzucker flambiert wird. Den hei\u00dfen Zucker l\u00e4\u00dft man in den Kaffee tropfen.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[285],"tags":[130],"class_list":["post-2744","post","type-post","status-publish","format-standard","hentry","category-getranke","tag-kaffee","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caf\u00e9 Royal<\/title>\n<meta name=\"description\" content=\"- Caf\u00e9 Royal\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/08\/30\/cafe-royal\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caf\u00e9 Royal\" \/>\n<meta property=\"og:description\" content=\"- Caf\u00e9 Royal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/08\/30\/cafe-royal\/\" \/>\n<meta property=\"og:site_name\" content=\"Steffen&#039;s Haushaltsblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:published_time\" content=\"2011-08-30T18:38:55+00:00\" \/>\n<meta name=\"author\" content=\"Steffen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steffen\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/08\\\/30\\\/cafe-royal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/08\\\/30\\\/cafe-royal\\\/\"},\"author\":{\"name\":\"Steffen\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"headline\":\"Caf\u00e9 Royal\",\"datePublished\":\"2011-08-30T18:38:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/08\\\/30\\\/cafe-royal\\\/\"},\"wordCount\":39,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"keywords\":[\"Kaffee\"],\"articleSection\":[\"Getr\u00e4nke\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/08\\\/30\\\/cafe-royal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/08\\\/30\\\/cafe-royal\\\/\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/08\\\/30\\\/cafe-royal\\\/\",\"name\":\"Caf\u00e9 Royal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\"},\"datePublished\":\"2011-08-30T18:38:55+00:00\",\"description\":\"- Caf\u00e9 Royal\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/08\\\/30\\\/cafe-royal\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/08\\\/30\\\/cafe-royal\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/08\\\/30\\\/cafe-royal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caf\u00e9 Royal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\",\"name\":\"Steffen&#039;s Haushaltsblog\",\"description\":\"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\\\/ki_kunst \",\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\",\"name\":\"Steffen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"caption\":\"Steffen\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/sthomas.de\",\"https:\\\/\\\/www.facebook.com\\\/steffen.thomas1\",\"https:\\\/\\\/x.com\\\/steto123\"],\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/author\\\/wp_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caf\u00e9 Royal","description":"- Caf\u00e9 Royal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/08\/30\/cafe-royal\/","og_locale":"de_DE","og_type":"article","og_title":"Caf\u00e9 Royal","og_description":"- Caf\u00e9 Royal","og_url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/08\/30\/cafe-royal\/","og_site_name":"Steffen&#039;s Haushaltsblog","article_publisher":"https:\/\/www.facebook.com\/steffen.thomas1","article_author":"https:\/\/www.facebook.com\/steffen.thomas1","article_published_time":"2011-08-30T18:38:55+00:00","author":"Steffen","twitter_misc":{"Verfasst von":"Steffen"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/08\/30\/cafe-royal\/#article","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/08\/30\/cafe-royal\/"},"author":{"name":"Steffen","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"headline":"Caf\u00e9 Royal","datePublished":"2011-08-30T18:38:55+00:00","mainEntityOfPage":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/08\/30\/cafe-royal\/"},"wordCount":39,"commentCount":0,"publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"keywords":["Kaffee"],"articleSection":["Getr\u00e4nke"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2011\/08\/30\/cafe-royal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/08\/30\/cafe-royal\/","url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/08\/30\/cafe-royal\/","name":"Caf\u00e9 Royal","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website"},"datePublished":"2011-08-30T18:38:55+00:00","description":"- Caf\u00e9 Royal","breadcrumb":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/08\/30\/cafe-royal\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2011\/08\/30\/cafe-royal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/08\/30\/cafe-royal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wissen.science-and-fun.de\/kochen\/"},{"@type":"ListItem","position":2,"name":"Caf\u00e9 Royal"}]},{"@type":"WebSite","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website","url":"https:\/\/wissen.science-and-fun.de\/kochen\/","name":"Steffen&#039;s Haushaltsblog","description":"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\/ki_kunst ","publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wissen.science-and-fun.de\/kochen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8","name":"Steffen","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","caption":"Steffen"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g"},"sameAs":["https:\/\/sthomas.de","https:\/\/www.facebook.com\/steffen.thomas1","https:\/\/x.com\/steto123"],"url":"https:\/\/wissen.science-and-fun.de\/kochen\/author\/wp_admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p1tRoY-Ig","jetpack-related-posts":[{"id":2732,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/08\/26\/cafe-brulot\/","url_meta":{"origin":2744,"position":0},"title":"Caf\u00e9 Brulot","author":"Steffen","date":"26. August 2011","format":false,"excerpt":"Zutaten 1-2 Fingerh\u00fcte Weinbrand W\u00fcrfelzucker Kaffee Schlagsahne Zubereitung Einen Fingerhut Weinbrand (oder zwei) mit W\u00fcrfelzucker in einer vorgew\u00e4rmten Tasse anz\u00fcnden, mit Kaffee abl\u00f6schen und mit Schlagsahne abdecken.","rel":"","context":"In &quot;Getr\u00e4nke&quot;","block_context":{"text":"Getr\u00e4nke","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/getranke\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3179,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/12\/21\/eierlikor-kaffee\/","url_meta":{"origin":2744,"position":1},"title":"Eierlik\u00f6r Kaffee","author":"Steffen","date":"21. Dezember 2011","format":false,"excerpt":"Zutaten 1 Tasse Caff\u00e8 Creme 1cl Eierlik\u00f6r Schlagobers (Schlagsahne) Kakaopulver Zubereitung Einer Tasse Cafe Creme geben Sie 1cl Eierlik\u00f6r hinzu und verr\u00fchren das Ganze. Schlagobers drauf und mit Kakaopulver best\u00e4uben.","rel":"","context":"In &quot;alkoholische Getr\u00e4nke&quot;","block_context":{"text":"alkoholische Getr\u00e4nke","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/getranke\/alkoholische-getranke\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4849,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2013\/01\/08\/mokka-french\/","url_meta":{"origin":2744,"position":2},"title":"Mokka French","author":"Steffen","date":"8. Januar 2013","format":false,"excerpt":"Zutaten 3 cl Armagnac 1 EL Zitronensaft (frisch gepre\u00dft) 4 St\u00fccke W\u00fcrfelzucker 1 Tasse hei\u00dfer Mokka Zubereitung Mokka br\u00fchen und die restlichen Zutaten zuf\u00fcgen.","rel":"","context":"In &quot;Getr\u00e4nke&quot;","block_context":{"text":"Getr\u00e4nke","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/getranke\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2237,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/07\/24\/after-eight\/","url_meta":{"origin":2744,"position":3},"title":"After Eight","author":"Steffen","date":"24. Juli 2011","format":false,"excerpt":"Zutaten 2 cl Cr\u00e8me de Menthe gr\u00fcn 2 cl Cr\u00e8me de Cacao braun 1 Tasse Heisser Kaffee Brauner Zucker Schlagsahne Zubereitung Die Lik\u00f6re im R\u00fchrglas vermischen und in eine vorgew\u00e4rmte Cocktailschale geben. Den nach Geschmack mit braunem Zucker ges\u00fcssten Kaffee zugie\u00dfen, leicht r\u00fchren und eine Sahnehaube darauf setzen. Zum Schlu\u00df\u2026","rel":"","context":"In &quot;alkoholische Getr\u00e4nke&quot;","block_context":{"text":"alkoholische Getr\u00e4nke","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/getranke\/alkoholische-getranke\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2247,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/07\/24\/alfonso\/","url_meta":{"origin":2744,"position":4},"title":"Alfonso","author":"Steffen","date":"24. Juli 2011","format":false,"excerpt":"Zutaten 4 cl Dubonnet 1 St\u00fcck W\u00fcrfelzucker 8 cl Sekt Angostura Eisw\u00fcrfel Zitronen Zubereitung Eine Zitronenscheibe oder ein St\u00fcck Zitronenschale direkt \u00fcber dem Drink ausdr\u00fccken und danach in das Glas geben. Den W\u00fcrfelzucker in einen Sektkelch geben, mit einigen Spritzern Angostura tr\u00e4nken und zerdr\u00fccken. Zwei bis drei Eisw\u00fcrfel dazugeben. Den\u2026","rel":"","context":"In &quot;alkoholische Getr\u00e4nke&quot;","block_context":{"text":"alkoholische Getr\u00e4nke","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/getranke\/alkoholische-getranke\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2272,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/07\/30\/american-grog\/","url_meta":{"origin":2744,"position":5},"title":"American Grog","author":"Steffen","date":"30. Juli 2011","format":false,"excerpt":"Zutaten 4 cl Jamaica-Rum 73 vol.% 2 cl Zitronensaft 2 St\u00fccke W\u00fcrfelzucker 1 Zimtstange 3 Gew\u00fcrznelken Zubereitung Rum, Zitronensaft und Zucker zusammen erhitzen, in ein vorgew\u00e4rmtes, hitzebest\u00e4ndiges Glas geben. Mit hei\u00dfem Wasser auff\u00fcllen und Zimt, Nelken und Zitronenscheibe dazugeben. Statt mit Wasser kann der \"American Grog\" auch mit hei\u00dfem Tee\u2026","rel":"","context":"In &quot;alkoholische Getr\u00e4nke&quot;","block_context":{"text":"alkoholische Getr\u00e4nke","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/getranke\/alkoholische-getranke\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/2744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/comments?post=2744"}],"version-history":[{"count":1,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/2744\/revisions"}],"predecessor-version":[{"id":2745,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/2744\/revisions\/2745"}],"wp:attachment":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/media?parent=2744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/categories?post=2744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/tags?post=2744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}