{"id":2108,"date":"2011-07-14T19:31:38","date_gmt":"2011-07-14T19:31:38","guid":{"rendered":"https:\/\/wissen.science-and-fun.de\/kochen\/?p=2108"},"modified":"2011-07-14T19:31:38","modified_gmt":"2011-07-14T19:31:38","slug":"gefulltes-hahnchenschnitzel","status":"publish","type":"post","link":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/07\/14\/gefulltes-hahnchenschnitzel\/","title":{"rendered":"Gef\u00fclltes H\u00e4hnchenschnitzel"},"content":{"rendered":"<p><strong>Zutaten<\/strong><br \/>\n1 H\u00e4hnchenbrustfilet<br \/>\n4 Steinchampignons, gehackt und kurz angebraten<br \/>\n1 EL Estragon, fein geschnitten<br \/>\n2 EL Tomaten, gew\u00fcrfelt<br \/>\n50 g  Cr\u00e8me double<br \/>\n1 Schalotte, fein geschnitten<br \/>\n1 EL Sherry<br \/>\netwas Bouillon<br \/>\netwas Butter<br \/>\nSalz, Pfeffer, Zucker <\/p>\n<p><strong>Zubereitung<\/strong><br \/>\nIn das H\u00e4hnchenbrustfilet eine tiefe Tasche schneiden. Die Pilze hacken, kurz anbraten aus der Pfanne nehmen und mit der H\u00e4lfte des Estragons vermengen, salzen, pfeffern und in die H\u00e4hnchenbrust f\u00fcllen. Die H\u00e4hnchenbrust salzen, pfeffern und in Butter rundherum goldbraun braten. Dann im Backofen noch ca. 5<br \/>\nMinuten (je nach Gr\u00f6sse) nachgaren lassen. In der Zwischenzeit die Schalotte mit etwas Zucker in der Pfanne anbraten, mit Sherry, Cr\u00e8me double und wenig Bouillon abl\u00f6schen und kr\u00e4ftig einkochen. Dann Estragon und Tomatenw\u00fcrfel untermischen und abschmecken. Die Sauce zur H\u00e4hnchenbrust servieren. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zutaten 1 H\u00e4hnchenbrustfilet 4 Steinchampignons, gehackt und kurz angebraten 1 EL Estragon, fein geschnitten 2 EL Tomaten, gew\u00fcrfelt 50 g Cr\u00e8me double 1 Schalotte, fein geschnitten 1 EL Sherry etwas Bouillon etwas Butter Salz, Pfeffer, Zucker Zubereitung In das H\u00e4hnchenbrustfilet eine tiefe Tasche schneiden. Die Pilze hacken, kurz anbraten aus der Pfanne nehmen und mit &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/07\/14\/gefulltes-hahnchenschnitzel\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[43,6,56],"tags":[379],"class_list":["post-2108","post","type-post","status-publish","format-standard","hentry","category-geflugel","category-hauptgerichte","category-singles","tag-hahnchen","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gef\u00fclltes H\u00e4hnchenschnitzel<\/title>\n<meta name=\"description\" content=\"- Gef\u00fclltes H\u00e4hnchenschnitzel\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/07\/14\/gefulltes-hahnchenschnitzel\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gef\u00fclltes H\u00e4hnchenschnitzel\" \/>\n<meta property=\"og:description\" content=\"- Gef\u00fclltes H\u00e4hnchenschnitzel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/07\/14\/gefulltes-hahnchenschnitzel\/\" \/>\n<meta property=\"og:site_name\" content=\"Steffen&#039;s Haushaltsblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:published_time\" content=\"2011-07-14T19:31:38+00:00\" \/>\n<meta name=\"author\" content=\"Steffen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steffen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/07\\\/14\\\/gefulltes-hahnchenschnitzel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/07\\\/14\\\/gefulltes-hahnchenschnitzel\\\/\"},\"author\":{\"name\":\"Steffen\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"headline\":\"Gef\u00fclltes H\u00e4hnchenschnitzel\",\"datePublished\":\"2011-07-14T19:31:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/07\\\/14\\\/gefulltes-hahnchenschnitzel\\\/\"},\"wordCount\":134,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"keywords\":[\"H\u00e4hnchen\"],\"articleSection\":[\"Gefl\u00fcgel\",\"Hauptgerichte\",\"Singles\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/07\\\/14\\\/gefulltes-hahnchenschnitzel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/07\\\/14\\\/gefulltes-hahnchenschnitzel\\\/\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/07\\\/14\\\/gefulltes-hahnchenschnitzel\\\/\",\"name\":\"Gef\u00fclltes H\u00e4hnchenschnitzel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\"},\"datePublished\":\"2011-07-14T19:31:38+00:00\",\"description\":\"- Gef\u00fclltes H\u00e4hnchenschnitzel\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/07\\\/14\\\/gefulltes-hahnchenschnitzel\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/07\\\/14\\\/gefulltes-hahnchenschnitzel\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/07\\\/14\\\/gefulltes-hahnchenschnitzel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gef\u00fclltes H\u00e4hnchenschnitzel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\",\"name\":\"Steffen&#039;s Haushaltsblog\",\"description\":\"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\\\/ki_kunst \",\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\",\"name\":\"Steffen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"caption\":\"Steffen\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/sthomas.de\",\"https:\\\/\\\/www.facebook.com\\\/steffen.thomas1\",\"https:\\\/\\\/x.com\\\/steto123\"],\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/author\\\/wp_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gef\u00fclltes H\u00e4hnchenschnitzel","description":"- Gef\u00fclltes H\u00e4hnchenschnitzel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/07\/14\/gefulltes-hahnchenschnitzel\/","og_locale":"de_DE","og_type":"article","og_title":"Gef\u00fclltes H\u00e4hnchenschnitzel","og_description":"- Gef\u00fclltes H\u00e4hnchenschnitzel","og_url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/07\/14\/gefulltes-hahnchenschnitzel\/","og_site_name":"Steffen&#039;s Haushaltsblog","article_publisher":"https:\/\/www.facebook.com\/steffen.thomas1","article_author":"https:\/\/www.facebook.com\/steffen.thomas1","article_published_time":"2011-07-14T19:31:38+00:00","author":"Steffen","twitter_misc":{"Verfasst von":"Steffen","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/07\/14\/gefulltes-hahnchenschnitzel\/#article","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/07\/14\/gefulltes-hahnchenschnitzel\/"},"author":{"name":"Steffen","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"headline":"Gef\u00fclltes H\u00e4hnchenschnitzel","datePublished":"2011-07-14T19:31:38+00:00","mainEntityOfPage":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/07\/14\/gefulltes-hahnchenschnitzel\/"},"wordCount":134,"commentCount":0,"publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"keywords":["H\u00e4hnchen"],"articleSection":["Gefl\u00fcgel","Hauptgerichte","Singles"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2011\/07\/14\/gefulltes-hahnchenschnitzel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/07\/14\/gefulltes-hahnchenschnitzel\/","url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/07\/14\/gefulltes-hahnchenschnitzel\/","name":"Gef\u00fclltes H\u00e4hnchenschnitzel","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website"},"datePublished":"2011-07-14T19:31:38+00:00","description":"- Gef\u00fclltes H\u00e4hnchenschnitzel","breadcrumb":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/07\/14\/gefulltes-hahnchenschnitzel\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2011\/07\/14\/gefulltes-hahnchenschnitzel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/07\/14\/gefulltes-hahnchenschnitzel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wissen.science-and-fun.de\/kochen\/"},{"@type":"ListItem","position":2,"name":"Gef\u00fclltes H\u00e4hnchenschnitzel"}]},{"@type":"WebSite","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website","url":"https:\/\/wissen.science-and-fun.de\/kochen\/","name":"Steffen&#039;s Haushaltsblog","description":"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\/ki_kunst ","publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wissen.science-and-fun.de\/kochen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8","name":"Steffen","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","caption":"Steffen"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g"},"sameAs":["https:\/\/sthomas.de","https:\/\/www.facebook.com\/steffen.thomas1","https:\/\/x.com\/steto123"],"url":"https:\/\/wissen.science-and-fun.de\/kochen\/author\/wp_admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p1tRoY-y0","jetpack-related-posts":[{"id":3986,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/03\/02\/hahnchenbrust-mit-cashewkernen-brokkoli-und-mohren\/","url_meta":{"origin":2108,"position":0},"title":"H\u00e4hnchenbrust mit Cashewkernen, Brokkoli und M\u00f6hren","author":"Steffen","date":"2. M\u00e4rz 2012","format":false,"excerpt":"Zutaten 2 H\u00e4hnchenbrustfilet a 120g 1 TL Speisest\u00e4rke 2 TL Sesam\u00f6l 1 Zwiebel 300 g Brokkoli 2 mittlere M\u00f6hren 1 Frische rote Chilischote 3 EL \u00d6l, geschmacksneutral 100 g Cashewkerne 1\/2 TL Zucker Salz Pfeffer 1 EL Ingwer, feingehackt 1 EL Knoblauch, feingehackt 1 EL Sojasauce 2 EL Reiswein oder\u2026","rel":"","context":"In &quot;Asiatisch&quot;","block_context":{"text":"Asiatisch","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/asiatisch\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1722,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/14\/gebratener-spargel-mit-erdbeeren\/","url_meta":{"origin":2108,"position":1},"title":"Gebratener Spargel mit Erdbeeren","author":"Steffen","date":"14. Mai 2011","format":false,"excerpt":"Zutaten 300 g Weisser Spargel 300 g Gr\u00fcner Spargel 2 H\u00e4hnchenbrustfilets je etwa 100 g 2 EL Kokosraspel 100 g Erdbeeren 2 EL \u00d6l zum Anbraten 100 ml Kokosmilch 1 Prise Salz 1 Prise Zucker 2 EL Butterschmalz 2 St\u00e4ngel frische Minze Zitronensaft Zitronenpfeffer Zubereitung Den weissen Spargel sch\u00e4len, vom\u2026","rel":"","context":"In &quot;Gem\u00fcse &amp; Obst&quot;","block_context":{"text":"Gem\u00fcse &amp; Obst","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/gemuse\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5296,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2013\/03\/06\/curryreis-mit-hahnchenbrust\/","url_meta":{"origin":2108,"position":2},"title":"Curryreis mit H\u00e4hnchenbrust","author":"Steffen","date":"6. M\u00e4rz 2013","format":false,"excerpt":"Zutaten 500 g H\u00e4hnchenbrustfilet (ohne Haut) 250 g Gem\u00fcsezwiebel 2 Knoblauchzehen 50 g Ingwerwurzel 1 gro\u00dfe Rote Paprikaschote 300 g Langkornreis (z. B. Basmati) 2 EL Butter 1 EL \u00d6l Pfeffer & Salz 1,5 EL Scharfes Currypulver 700 ml Gefl\u00fcgelfond 1\/2 Bund Koriandergr\u00fcn 100 g Sahnejoghurt 2 EL Limettensaft Zubereitung\u2026","rel":"","context":"In &quot;Gefl\u00fcgel&quot;","block_context":{"text":"Gefl\u00fcgel","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/geflugel\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5711,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2014\/04\/25\/reissalat-mit-haehnchenbrust\/","url_meta":{"origin":2108,"position":3},"title":"Reissalat mit H\u00e4hnchenbrust","author":"Steffen","date":"25. April 2014","format":false,"excerpt":"Zutaten 200 g Langkornreis 50 g Rosinen 2 cl Weinbrand 2 H\u00e4hnchenbr\u00fcste 2 EL \u00d6l 2 Kiwi 2 Pfirsiche 100 g Litedamer 3 EL Creme fra\u00eeche 3 EL Zitronensaft Salz, wei\u00dfer Pfeffer 1 Prise Zucker 50 g Mandelsplitter Curry Zubereitung Reis in Wasser mit je einem gestrichenen Teel\u00f6ffel Curry und\u2026","rel":"","context":"In &quot;Salat&quot;","block_context":{"text":"Salat","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/salat\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4380,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/09\/23\/hahnchenragout-mit-gorgonzola\/","url_meta":{"origin":2108,"position":4},"title":"H\u00e4hnchenragout mit Gorgonzola","author":"Steffen","date":"23. September 2012","format":false,"excerpt":"Zutaten 800 g H\u00e4hnchenbrustfilet 2 rote Zwiebeln 200 g Gorgonzola 150 ml Schlagsahne 1 gepresste Knoblauchzehe 200 g Ruccola 50 g Walnusskerne 5 EL \u00d6l Salz Pfeffer 400 ml Gefl\u00fcgelfond 2 EL heller Saucenbinder Zubereitung H\u00e4hnchenfilet in 2cm gro\u00dfe W\u00fcrfel schneiden. Zwiebeln pellen und in Streifen schneiden. Gorgonzola entrinden und\u2026","rel":"","context":"In &quot;Gefl\u00fcgel&quot;","block_context":{"text":"Gefl\u00fcgel","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/geflugel\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":972,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2024\/01\/24\/hahnchen-mexikanisch\/","url_meta":{"origin":2108,"position":5},"title":"H\u00e4hnchen mexikanisch","author":"Steffen","date":"24. Januar 2024","format":false,"excerpt":"\u00a0 H\u00e4hnchen mexikanisch 4 H\u00e4hnchenbrustfilets \u00e0 100g4 EL Mehl3 EL Oliven\u00f6l1 rote Paprikaschote1 gr\u00fcne Paprikaschote200 g Champignons2 TL mildes Chilipulver450 ml Gem\u00fcsebr\u00fche2 EL Tomatenmark50 g gef\u00fcllte gr\u00fcne Oliven2 TL Orangenzesten H\u00e4hnchenbrustfilets mit K\u00fcchenpapier trockentupfen, dann in 3 EL Mehl wenden. In einer beschichteten Pfanne 2 EL \u00d6l erhitzen. H\u00e4hnchenbr\u00fcste bei\u2026","rel":"","context":"In &quot;Gefl\u00fcgel&quot;","block_context":{"text":"Gefl\u00fcgel","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/geflugel\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/wissen.science-and-fun.de\/kochen\/files\/2011\/04\/00008-Mexican-chicken-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/2108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/comments?post=2108"}],"version-history":[{"count":1,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/2108\/revisions"}],"predecessor-version":[{"id":2109,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/2108\/revisions\/2109"}],"wp:attachment":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/media?parent=2108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/categories?post=2108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/tags?post=2108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}