{"id":2009,"date":"2011-06-12T18:36:20","date_gmt":"2011-06-12T18:36:20","guid":{"rendered":"https:\/\/wissen.science-and-fun.de\/kochen\/?p=2009"},"modified":"2011-06-12T18:36:20","modified_gmt":"2011-06-12T18:36:20","slug":"schweinelende-unter-kartoffelgratin","status":"publish","type":"post","link":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/06\/12\/schweinelende-unter-kartoffelgratin\/","title":{"rendered":"Schweinelende unter Kartoffelgratin"},"content":{"rendered":"<p><strong>Zutaten<\/strong><br \/>\n1 Schweinelende<br \/>\nKartoffeln je nach Hunger<br \/>\n200 ml  Sahne<br \/>\nGeriebenen K\u00e4se nach Belieben z.B. Gouda, Emmentaler, Greyerzer <\/p>\n<p><strong>Zubereitung<\/strong><br \/>\nLende salzen, pfeffern und in eine ausgebutterte Auflaufform legen. Kartoffeln sch\u00e4len und in gleichm\u00e4ssige Scheiben schneiden. Um und \u00fcber die Lende schichten. Salzen und mit Sahne \u00fcbergiessen. Dick mit geriebenem K\u00e4se bestreuen. Im Backofen bei ca. 200 Grad 1 und 1\/4 Stunden backen. Dazwischen mit Alufolie abdecken, damit der K\u00e4se nicht zu dunkel wird. Kann auch f\u00fcr mehrere G\u00e4ste in der Fettpfanne des Backofens<br \/>\nzubereitet werden. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zutaten 1 Schweinelende Kartoffeln je nach Hunger 200 ml Sahne Geriebenen K\u00e4se nach Belieben z.B. Gouda, Emmentaler, Greyerzer Zubereitung Lende salzen, pfeffern und in eine ausgebutterte Auflaufform legen. Kartoffeln sch\u00e4len und in gleichm\u00e4ssige Scheiben schneiden. Um und \u00fcber die Lende schichten. Salzen und mit Sahne \u00fcbergiessen. Dick mit geriebenem K\u00e4se bestreuen. Im Backofen bei ca. &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/06\/12\/schweinelende-unter-kartoffelgratin\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6,47],"tags":[363],"class_list":["post-2009","post","type-post","status-publish","format-standard","hentry","category-hauptgerichte","category-schwein","tag-schweinelende","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schweinelende unter Kartoffelgratin<\/title>\n<meta name=\"description\" content=\"- Schweinelende unter Kartoffelgratin\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/06\/12\/schweinelende-unter-kartoffelgratin\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schweinelende unter Kartoffelgratin\" \/>\n<meta property=\"og:description\" content=\"- Schweinelende unter Kartoffelgratin\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/06\/12\/schweinelende-unter-kartoffelgratin\/\" \/>\n<meta property=\"og:site_name\" content=\"Steffen&#039;s Haushaltsblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:published_time\" content=\"2011-06-12T18:36:20+00:00\" \/>\n<meta name=\"author\" content=\"Steffen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steffen\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/06\\\/12\\\/schweinelende-unter-kartoffelgratin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/06\\\/12\\\/schweinelende-unter-kartoffelgratin\\\/\"},\"author\":{\"name\":\"Steffen\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"headline\":\"Schweinelende unter Kartoffelgratin\",\"datePublished\":\"2011-06-12T18:36:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/06\\\/12\\\/schweinelende-unter-kartoffelgratin\\\/\"},\"wordCount\":91,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"keywords\":[\"Schweinelende\"],\"articleSection\":[\"Hauptgerichte\",\"Schwein\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/06\\\/12\\\/schweinelende-unter-kartoffelgratin\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/06\\\/12\\\/schweinelende-unter-kartoffelgratin\\\/\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/06\\\/12\\\/schweinelende-unter-kartoffelgratin\\\/\",\"name\":\"Schweinelende unter Kartoffelgratin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\"},\"datePublished\":\"2011-06-12T18:36:20+00:00\",\"description\":\"- Schweinelende unter Kartoffelgratin\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/06\\\/12\\\/schweinelende-unter-kartoffelgratin\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/06\\\/12\\\/schweinelende-unter-kartoffelgratin\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/06\\\/12\\\/schweinelende-unter-kartoffelgratin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schweinelende unter Kartoffelgratin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\",\"name\":\"Steffen&#039;s Haushaltsblog\",\"description\":\"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\\\/ki_kunst \",\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\",\"name\":\"Steffen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"caption\":\"Steffen\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/sthomas.de\",\"https:\\\/\\\/www.facebook.com\\\/steffen.thomas1\",\"https:\\\/\\\/x.com\\\/steto123\"],\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/author\\\/wp_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schweinelende unter Kartoffelgratin","description":"- Schweinelende unter Kartoffelgratin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/06\/12\/schweinelende-unter-kartoffelgratin\/","og_locale":"de_DE","og_type":"article","og_title":"Schweinelende unter Kartoffelgratin","og_description":"- Schweinelende unter Kartoffelgratin","og_url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/06\/12\/schweinelende-unter-kartoffelgratin\/","og_site_name":"Steffen&#039;s Haushaltsblog","article_publisher":"https:\/\/www.facebook.com\/steffen.thomas1","article_author":"https:\/\/www.facebook.com\/steffen.thomas1","article_published_time":"2011-06-12T18:36:20+00:00","author":"Steffen","twitter_misc":{"Verfasst von":"Steffen"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/06\/12\/schweinelende-unter-kartoffelgratin\/#article","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/06\/12\/schweinelende-unter-kartoffelgratin\/"},"author":{"name":"Steffen","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"headline":"Schweinelende unter Kartoffelgratin","datePublished":"2011-06-12T18:36:20+00:00","mainEntityOfPage":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/06\/12\/schweinelende-unter-kartoffelgratin\/"},"wordCount":91,"commentCount":0,"publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"keywords":["Schweinelende"],"articleSection":["Hauptgerichte","Schwein"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2011\/06\/12\/schweinelende-unter-kartoffelgratin\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/06\/12\/schweinelende-unter-kartoffelgratin\/","url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/06\/12\/schweinelende-unter-kartoffelgratin\/","name":"Schweinelende unter Kartoffelgratin","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website"},"datePublished":"2011-06-12T18:36:20+00:00","description":"- Schweinelende unter Kartoffelgratin","breadcrumb":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/06\/12\/schweinelende-unter-kartoffelgratin\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2011\/06\/12\/schweinelende-unter-kartoffelgratin\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/06\/12\/schweinelende-unter-kartoffelgratin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wissen.science-and-fun.de\/kochen\/"},{"@type":"ListItem","position":2,"name":"Schweinelende unter Kartoffelgratin"}]},{"@type":"WebSite","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website","url":"https:\/\/wissen.science-and-fun.de\/kochen\/","name":"Steffen&#039;s Haushaltsblog","description":"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\/ki_kunst ","publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wissen.science-and-fun.de\/kochen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8","name":"Steffen","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","caption":"Steffen"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g"},"sameAs":["https:\/\/sthomas.de","https:\/\/www.facebook.com\/steffen.thomas1","https:\/\/x.com\/steto123"],"url":"https:\/\/wissen.science-and-fun.de\/kochen\/author\/wp_admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p1tRoY-wp","jetpack-related-posts":[{"id":7138,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2019\/07\/06\/apfelauflauf\/","url_meta":{"origin":2009,"position":0},"title":"Apfelauflauf","author":"Steffen","date":"6. Juli 2019","format":false,"excerpt":"Bertolt Brecht zum Thema Essen:\u00a0 Erst kommt das Fressen, dann die Moral. Hier kommt ein unmoralisches Angebot: Apfelauflauf 1\/2 Bund Lauchzwiebeln20 Gramm Butter750 Gramm Kartoffeln (mehlig kochende Sorte)3 \u00c4pfel200 Gramm Champignons200 ml Sahne2 EigelbSalzPfefferMuskatnuss75 Gramm Emmentaler K\u00e4se (gerieben) Die Lauchzwiebeln in feine Ringe schneiden und in hei\u00dfer Butter bei mittlerer\u2026","rel":"","context":"In &quot;Auflauf&quot;","block_context":{"text":"Auflauf","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/auflauf\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":146,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/07\/mit-birnen-gefullte-schweinelende\/","url_meta":{"origin":2009,"position":1},"title":"Mit Birnen gef\u00fcllte Schweinelende","author":"Steffen","date":"7. April 2011","format":false,"excerpt":"Mit Birnen gef\u00fcllte Schweinelende 1,5 kg Schweinelende2 gro\u00dfe feste Birnen1 Tl Paprikapulver2 Tl Salz1\/3 Tl Pfeffer20 mittelgro\u00dfe Kartoffeln4 Zwiebeln2 Tl Salz2 Tl Knoblauchpulver1\/2 Tl Pfeffer2-3 El Margarine Ofen auf 200\u00b0C vorheizen. Birne sch\u00e4len, entkernen und in kleine St\u00fccke schneiden. Mit Paprikapulver und 1\/2 TL Salz bestreuen.Schweinelende der L\u00e4nge nach aufschneiden.Die\u2026","rel":"","context":"In &quot;Hauptgerichte&quot;","block_context":{"text":"Hauptgerichte","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":802,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/22\/hackbraten-auf-kartoffelgratin\/","url_meta":{"origin":2009,"position":2},"title":"Hackbraten auf Kartoffelgratin","author":"Steffen","date":"22. April 2011","format":false,"excerpt":"Zutaten: 1 altbackenes Br\u00f6tchen 1 Bund Petersilie 1 Ei 500 g gemischtes Hackfleisch 1\/2 TL Salz 1\/2 TL Senf Pfeffer, Muskat 200 g Gouda 1 TL provencalische Kr\u00e4uter 1kg Kartoffeln Salz, Pfeffer, Muskat 1\/8l Milch oder Sahne Zubereitung: Das Br\u00f6tchen in Wasser einweichen und anschlie\u00dfend gut ausdr\u00fccken. Die Petersilie waschen\u2026","rel":"","context":"In &quot;Hauptgerichte&quot;","block_context":{"text":"Hauptgerichte","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5275,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2013\/03\/05\/gefullte-kohlrabi-mit-spinat\/","url_meta":{"origin":2009,"position":3},"title":"Gef\u00fcllte Kohlrabi mit Spinat","author":"Steffen","date":"5. M\u00e4rz 2013","format":false,"excerpt":"Zutaten 4 Kohlrabi ohne Bl\u00e4tter (\u00e0 300 g) Salz 500 g Blattspinat 600 g Fest kochende Bio-Kartoffeln 120 g Mittelalter Gouda 3 EL \u00d6l 350 ml Schlagsahne Schwarzer Pfeffer Muskat 1,5 EL Zitronensaft Butter f\u00fcr die Form 1 Zwiebel 2-3 Knoblauchzehen 100 ml Wei\u00dfwein Zucker Zubereitung 1. Kohlrabi sch\u00e4len, in\u2026","rel":"","context":"In &quot;Gem\u00fcse &amp; Obst&quot;","block_context":{"text":"Gem\u00fcse &amp; Obst","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/gemuse\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2011,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/06\/12\/schweinelende-in-biermarinade-mit-senfbier-kummelkruste-in-dunkelbiersose\/","url_meta":{"origin":2009,"position":4},"title":"Schweinelende in Biermarinade mit Senfbier- K\u00fcmmelkruste in Dunkelbierso\u00dfe","author":"Steffen","date":"12. Juni 2011","format":false,"excerpt":"Zutaten 2 Schweinelendchen a 500 g Marinade 200 ml \u00d6l 1 Liter Pils 1 Karotte 1\/2 Stange Lauch 1\/2 Sellerie, gew\u00fcrfelt 2 Lorbeerbl\u00e4tter 6 Nelken 1 TL Wacholderbeeren 2 TL Pfefferk\u00f6rner, zerdr\u00fcckt Etwas Salz Bierkruste 400 Gramm Wei\u00dfbrot ohne Kruste, gew\u00fcrfelt 2 TL K\u00fcmmel 200 ml Dijonsenf grob 2 Eigelb\u2026","rel":"","context":"In &quot;Hauptgerichte&quot;","block_context":{"text":"Hauptgerichte","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1656,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/13\/backkartoffeln-mit-schinken\/","url_meta":{"origin":2009,"position":5},"title":"Backkartoffeln mit Schinken","author":"Steffen","date":"13. Mai 2011","format":false,"excerpt":"Zutaten 8 gro\u00dfe Pellkartoffeln 100g gekochter Schinken 2 Bund Fr\u00fchlingszwiebeln 150g saure Sahne 1 TL Senf Salz Pfeffer 8 TL geriebener K\u00e4se Zubereitung Hei\u00dfe Kartoffeln halbieren und mit einem Teel\u00f6ffel aush\u00f6hlen. Schinken in feine W\u00fcrfel, Fr\u00fchlingszwiebeln in Ringe schneiden, mit der ausgeh\u00f6hlten Kartoffelmasse, Sahne, Senf, Salz und Pfeffer verr\u00fchren und\u2026","rel":"","context":"In &quot;Auflauf&quot;","block_context":{"text":"Auflauf","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/auflauf\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/2009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/comments?post=2009"}],"version-history":[{"count":1,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/2009\/revisions"}],"predecessor-version":[{"id":2010,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/2009\/revisions\/2010"}],"wp:attachment":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/media?parent=2009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/categories?post=2009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/tags?post=2009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}