{"id":1650,"date":"2011-05-13T03:56:22","date_gmt":"2011-05-13T03:56:22","guid":{"rendered":"https:\/\/wissen.science-and-fun.de\/kochen\/?p=1650"},"modified":"2011-05-13T03:56:22","modified_gmt":"2011-05-13T03:56:22","slug":"spinat-uberbacken","status":"publish","type":"post","link":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/13\/spinat-uberbacken\/","title":{"rendered":"Spinat \u00fcberbacken"},"content":{"rendered":"<p><b>Zutaten:<\/b><br \/>\n1 kg frischer Spinat<br \/>\n250 ml s\u00fc\u00dfe Sahne<br \/>\n1 Becher Schmand<br \/>\n200 g geriebener K\u00e4se<\/p>\n<p> <br \/>\n<b>Zubereitung:<\/b> <br \/>Vorhandene Stiele entfernen, Spinat in einen Topf mit ein wenig kochendem Wasser geben und zusammenfallen lassen. Dann mit Salz, Pfeffer und Muskatnuss abschmecken. Backblech mit der Butter einfetten und den Spinat darauf verteilen. Die Sahne mit dem Schmand vermengen und mit Pfeffer und Salz w\u00fcrzen und den geriebenen K\u00e4se unterheben. Das Ganze \u00fcber den Spinat verteilen und dann ca. 15 min. im vorgeheizten Backofen bei ca. 180\u00b0C \u00fcberbacken. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zutaten: 1 kg frischer Spinat 250 ml s\u00fc\u00dfe Sahne 1 Becher Schmand 200 g geriebener K\u00e4se Zubereitung: Vorhandene Stiele entfernen, Spinat in einen Topf mit ein wenig kochendem Wasser geben und zusammenfallen lassen. Dann mit Salz, Pfeffer und Muskatnuss abschmecken. Backblech mit der Butter einfetten und den Spinat darauf verteilen. Die Sahne mit dem Schmand &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/13\/spinat-uberbacken\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[18],"tags":[64],"class_list":["post-1650","post","type-post","status-publish","format-standard","hentry","category-gemuse","tag-spinat","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spinat \u00fcberbacken<\/title>\n<meta name=\"description\" content=\"- Spinat \u00fcberbacken\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/13\/spinat-uberbacken\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spinat \u00fcberbacken\" \/>\n<meta property=\"og:description\" content=\"- Spinat \u00fcberbacken\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/13\/spinat-uberbacken\/\" \/>\n<meta property=\"og:site_name\" content=\"Steffen&#039;s Haushaltsblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:published_time\" content=\"2011-05-13T03:56:22+00:00\" \/>\n<meta name=\"author\" content=\"Steffen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steffen\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/13\\\/spinat-uberbacken\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/13\\\/spinat-uberbacken\\\/\"},\"author\":{\"name\":\"Steffen\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"headline\":\"Spinat \u00fcberbacken\",\"datePublished\":\"2011-05-13T03:56:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/13\\\/spinat-uberbacken\\\/\"},\"wordCount\":86,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"keywords\":[\"Spinat\"],\"articleSection\":[\"Gem\u00fcse &amp; Obst\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/13\\\/spinat-uberbacken\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/13\\\/spinat-uberbacken\\\/\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/13\\\/spinat-uberbacken\\\/\",\"name\":\"Spinat \u00fcberbacken\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\"},\"datePublished\":\"2011-05-13T03:56:22+00:00\",\"description\":\"- Spinat \u00fcberbacken\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/13\\\/spinat-uberbacken\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/13\\\/spinat-uberbacken\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/13\\\/spinat-uberbacken\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spinat \u00fcberbacken\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\",\"name\":\"Steffen&#039;s Haushaltsblog\",\"description\":\"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\\\/ki_kunst \",\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\",\"name\":\"Steffen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"caption\":\"Steffen\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/sthomas.de\",\"https:\\\/\\\/www.facebook.com\\\/steffen.thomas1\",\"https:\\\/\\\/x.com\\\/steto123\"],\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/author\\\/wp_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spinat \u00fcberbacken","description":"- Spinat \u00fcberbacken","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/13\/spinat-uberbacken\/","og_locale":"de_DE","og_type":"article","og_title":"Spinat \u00fcberbacken","og_description":"- Spinat \u00fcberbacken","og_url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/13\/spinat-uberbacken\/","og_site_name":"Steffen&#039;s Haushaltsblog","article_publisher":"https:\/\/www.facebook.com\/steffen.thomas1","article_author":"https:\/\/www.facebook.com\/steffen.thomas1","article_published_time":"2011-05-13T03:56:22+00:00","author":"Steffen","twitter_misc":{"Verfasst von":"Steffen"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/13\/spinat-uberbacken\/#article","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/13\/spinat-uberbacken\/"},"author":{"name":"Steffen","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"headline":"Spinat \u00fcberbacken","datePublished":"2011-05-13T03:56:22+00:00","mainEntityOfPage":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/13\/spinat-uberbacken\/"},"wordCount":86,"commentCount":0,"publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"keywords":["Spinat"],"articleSection":["Gem\u00fcse &amp; Obst"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/13\/spinat-uberbacken\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/13\/spinat-uberbacken\/","url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/13\/spinat-uberbacken\/","name":"Spinat \u00fcberbacken","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website"},"datePublished":"2011-05-13T03:56:22+00:00","description":"- Spinat \u00fcberbacken","breadcrumb":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/13\/spinat-uberbacken\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/13\/spinat-uberbacken\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/13\/spinat-uberbacken\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wissen.science-and-fun.de\/kochen\/"},{"@type":"ListItem","position":2,"name":"Spinat \u00fcberbacken"}]},{"@type":"WebSite","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website","url":"https:\/\/wissen.science-and-fun.de\/kochen\/","name":"Steffen&#039;s Haushaltsblog","description":"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\/ki_kunst ","publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wissen.science-and-fun.de\/kochen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8","name":"Steffen","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","caption":"Steffen"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g"},"sameAs":["https:\/\/sthomas.de","https:\/\/www.facebook.com\/steffen.thomas1","https:\/\/x.com\/steto123"],"url":"https:\/\/wissen.science-and-fun.de\/kochen\/author\/wp_admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p1tRoY-qC","jetpack-related-posts":[{"id":8104,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2021\/12\/03\/lachs-spinat-lasagne\/","url_meta":{"origin":1650,"position":0},"title":"Lachs-Spinat-Lasagne","author":"Steffen","date":"3. Dezember 2021","format":false,"excerpt":"Lachs-Spinat-Lasagne 600 Gramm TK Blattspinat (aufgetaut und abgetropft)400 Gramm Lachsfilet (frisch oder tiefgek\u00fchlt)Oliven\u00f6l2 Knoblauchzehen2 kleine Zwiebel1 Bund Dill (gehackt)1 Bund Petersilie (gehackt)1 Essl. Kr\u00e4uter de Provence3 Essl. Sahne-Meerrettich1 Zitrone (Saft)Parmesank\u00e4seSalz und PfefferEtwas Wei\u00dfwein3 Becher Schmand600 ml Milch12 Lasagnebl\u00e4tter Die Zwiebel und den Knoblauch sch\u00e4len, hacken und in einem Topf in\u2026","rel":"","context":"In &quot;Hauptgerichte&quot;","block_context":{"text":"Hauptgerichte","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1646,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/13\/spinatsuppe\/","url_meta":{"origin":1650,"position":1},"title":"Spinatsuppe","author":"Steffen","date":"13. Mai 2011","format":false,"excerpt":"Zutaten: 500 g frischer Spinat 150 g frische Champions 600 ml H\u00fchnerbr\u00fche 200 ml Sahne 250 ml Wasser 125 g Mascarpone 200 g geriebener K\u00e4se 1 kleine Zwiebel Zubereitung: In einem Topf die Butter schmelzen. die klein gew\u00fcrfelten Zwiebeln zusammen mit den Champions anbraten. Mit H\u00fchnerbr\u00fche, Sahne und Wasser abl\u00f6schen.\u2026","rel":"","context":"In &quot;Suppe&quot;","block_context":{"text":"Suppe","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/suppe\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5016,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2013\/02\/03\/kohlrabi-gratin-mit-blattspinat-und-parmaschinken\/","url_meta":{"origin":1650,"position":2},"title":"Kohlrabi-Gratin mit Blattspinat und Parmaschinken","author":"Steffen","date":"3. Februar 2013","format":false,"excerpt":"Zutaten 4 Kohlrabi a 200 g Salz 200 g Blattspinat 10 g Butter 70 g Parmaschinken 200 ml Schlagsahne Pfeffer Muskatnuss 50 g Gruyere; gerieben Zubereitung Zarte Kohlrabibl\u00e4tter abschneiden, in Streifen schneiden und beiseite stellen. Kohlrabi sch\u00e4len, vierteln, jedes Viertel in 3 Spalten schneiden, in kochendem Salzwasser bissfest garen. Spinat\u2026","rel":"","context":"In &quot;Gem\u00fcse &amp; Obst&quot;","block_context":{"text":"Gem\u00fcse &amp; Obst","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/gemuse\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5275,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2013\/03\/05\/gefullte-kohlrabi-mit-spinat\/","url_meta":{"origin":1650,"position":3},"title":"Gef\u00fcllte Kohlrabi mit Spinat","author":"Steffen","date":"5. M\u00e4rz 2013","format":false,"excerpt":"Zutaten 4 Kohlrabi ohne Bl\u00e4tter (\u00e0 300 g) Salz 500 g Blattspinat 600 g Fest kochende Bio-Kartoffeln 120 g Mittelalter Gouda 3 EL \u00d6l 350 ml Schlagsahne Schwarzer Pfeffer Muskat 1,5 EL Zitronensaft Butter f\u00fcr die Form 1 Zwiebel 2-3 Knoblauchzehen 100 ml Wei\u00dfwein Zucker Zubereitung 1. Kohlrabi sch\u00e4len, in\u2026","rel":"","context":"In &quot;Gem\u00fcse &amp; Obst&quot;","block_context":{"text":"Gem\u00fcse &amp; Obst","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/gemuse\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":437,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/11\/jakobsmuscheln-auf-blattspinat\/","url_meta":{"origin":1650,"position":4},"title":"Jakobsmuscheln auf Blattspinat","author":"Steffen","date":"11. April 2011","format":false,"excerpt":"Zutaten: 500 g junger Blattspinat 8-10 Jakobsmuscheln, tiefgek\u00fchlt oder aus der Dose 2 EL Butter 1 Knoblauchzehe Salz wei\u00dfer Pfeffer 1 Prise geriebene Muskatnu\u00df Saft von 1\/2 Zitrone 100 g Butter 2 Eigelb Zubereitung: Jakobsmuscheln, aufgetaut oder aus der Dose, gut abtropfen lassen und mit etwas Zitronensaft betr\u00e4ufeln. Blattspinat verlesen\u2026","rel":"","context":"In &quot;Fisch&quot;","block_context":{"text":"Fisch","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/fisch\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1989,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/06\/12\/sahnige-pureelocken-auf-schweinelende-gratiniert-mit-edamer\/","url_meta":{"origin":1650,"position":5},"title":"Sahnige P\u00fcreelocken auf Schweinelende, gratiniert mit Edamer","author":"Steffen","date":"12. Juni 2011","format":false,"excerpt":"Zutaten 800 Gramm Mehlige Kartoffeln 60 Gramm Butter 2 Eigelb 150 Gramm Schmand 150 Gramm Deutscher Edamer (feingerieben) Salz und Pfeffer, Muskatnuss 2 Schweinefilets (je 300 bis 350 g) 1,5 l Gem\u00fcsebr\u00fche 500 Gramm Blattspinat 40 Gramm Butterschmalz 2 Feingeschnittene Knoblauchzehen Butter zum Ausfetten der Form Zubereitung Kartoffeln sch\u00e4len, grob\u2026","rel":"","context":"In &quot;Hauptgerichte&quot;","block_context":{"text":"Hauptgerichte","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/1650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/comments?post=1650"}],"version-history":[{"count":1,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/1650\/revisions"}],"predecessor-version":[{"id":1651,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/1650\/revisions\/1651"}],"wp:attachment":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/media?parent=1650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/categories?post=1650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/tags?post=1650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}