{"id":1580,"date":"2011-05-11T20:46:16","date_gmt":"2011-05-11T20:46:16","guid":{"rendered":"https:\/\/wissen.science-and-fun.de\/kochen\/?p=1580"},"modified":"2012-09-14T13:59:12","modified_gmt":"2012-09-14T13:59:12","slug":"bratwurst-mit-tomatenkraut","status":"publish","type":"post","link":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/11\/bratwurst-mit-tomatenkraut\/","title":{"rendered":"Bratwurst mit Tomatenkraut"},"content":{"rendered":"<p>600 g geputztes und gewaschenes Wei\u00dfkraut nach Wegnahme des Rohanteils in Bl\u00e4ttchen (Fleckerln) schneiden, mit 15 g Speckw\u00fcrfeln und 40 g Zwiebelscheiben goldgelb r\u00f6sten, mit etwas Br\u00fche auff\u00fcllen und gard\u00fcnsten Aus dem Bratenfett, ebenfalls 15 g Speckw\u00fcrfel und Mehl (Type W 630) eine helle Schwitze bereiten, darin das Tomatenmark kurz mitr\u00f6sten, Paprika beif\u00fcgen, mit Milch glattr\u00fchren und mit Br\u00fche zu einer dicks\u00e4migen Tunke auff\u00fcllen, durchkochen lassen, unter das Kraut mischen, gemahlenen K\u00fcmmel zugeben und abschmecken.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>600 g geputztes und gewaschenes Wei\u00dfkraut nach Wegnahme des Rohanteils in Bl\u00e4ttchen (Fleckerln) schneiden, mit 15 g Speckw\u00fcrfeln und 40 g Zwiebelscheiben goldgelb r\u00f6sten, mit etwas Br\u00fche auff\u00fcllen und gard\u00fcnsten Aus dem Bratenfett, ebenfalls 15 g Speckw\u00fcrfel und Mehl (Type W 630) eine helle Schwitze bereiten, darin das Tomatenmark kurz mitr\u00f6sten, Paprika beif\u00fcgen, mit Milch &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/11\/bratwurst-mit-tomatenkraut\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6],"tags":[],"class_list":["post-1580","post","type-post","status-publish","format-standard","hentry","category-hauptgerichte","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bratwurst mit Tomatenkraut<\/title>\n<meta name=\"description\" content=\"- Bratwurst mit Tomatenkraut\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/11\/bratwurst-mit-tomatenkraut\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bratwurst mit Tomatenkraut\" \/>\n<meta property=\"og:description\" content=\"- Bratwurst mit Tomatenkraut\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/11\/bratwurst-mit-tomatenkraut\/\" \/>\n<meta property=\"og:site_name\" content=\"Steffen&#039;s Haushaltsblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:published_time\" content=\"2011-05-11T20:46:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-09-14T13:59:12+00:00\" \/>\n<meta name=\"author\" content=\"Steffen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steffen\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/11\\\/bratwurst-mit-tomatenkraut\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/11\\\/bratwurst-mit-tomatenkraut\\\/\"},\"author\":{\"name\":\"Steffen\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"headline\":\"Bratwurst mit Tomatenkraut\",\"datePublished\":\"2011-05-11T20:46:16+00:00\",\"dateModified\":\"2012-09-14T13:59:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/11\\\/bratwurst-mit-tomatenkraut\\\/\"},\"wordCount\":88,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"articleSection\":[\"Hauptgerichte\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/11\\\/bratwurst-mit-tomatenkraut\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/11\\\/bratwurst-mit-tomatenkraut\\\/\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/11\\\/bratwurst-mit-tomatenkraut\\\/\",\"name\":\"Bratwurst mit Tomatenkraut\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\"},\"datePublished\":\"2011-05-11T20:46:16+00:00\",\"dateModified\":\"2012-09-14T13:59:12+00:00\",\"description\":\"- Bratwurst mit Tomatenkraut\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/11\\\/bratwurst-mit-tomatenkraut\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/11\\\/bratwurst-mit-tomatenkraut\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/11\\\/bratwurst-mit-tomatenkraut\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bratwurst mit Tomatenkraut\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\",\"name\":\"Steffen&#039;s Haushaltsblog\",\"description\":\"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\\\/ki_kunst \",\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\",\"name\":\"Steffen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"caption\":\"Steffen\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/sthomas.de\",\"https:\\\/\\\/www.facebook.com\\\/steffen.thomas1\",\"https:\\\/\\\/x.com\\\/steto123\"],\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/author\\\/wp_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bratwurst mit Tomatenkraut","description":"- Bratwurst mit Tomatenkraut","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/11\/bratwurst-mit-tomatenkraut\/","og_locale":"de_DE","og_type":"article","og_title":"Bratwurst mit Tomatenkraut","og_description":"- Bratwurst mit Tomatenkraut","og_url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/11\/bratwurst-mit-tomatenkraut\/","og_site_name":"Steffen&#039;s Haushaltsblog","article_publisher":"https:\/\/www.facebook.com\/steffen.thomas1","article_author":"https:\/\/www.facebook.com\/steffen.thomas1","article_published_time":"2011-05-11T20:46:16+00:00","article_modified_time":"2012-09-14T13:59:12+00:00","author":"Steffen","twitter_misc":{"Verfasst von":"Steffen"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/11\/bratwurst-mit-tomatenkraut\/#article","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/11\/bratwurst-mit-tomatenkraut\/"},"author":{"name":"Steffen","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"headline":"Bratwurst mit Tomatenkraut","datePublished":"2011-05-11T20:46:16+00:00","dateModified":"2012-09-14T13:59:12+00:00","mainEntityOfPage":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/11\/bratwurst-mit-tomatenkraut\/"},"wordCount":88,"commentCount":0,"publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"articleSection":["Hauptgerichte"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/11\/bratwurst-mit-tomatenkraut\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/11\/bratwurst-mit-tomatenkraut\/","url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/11\/bratwurst-mit-tomatenkraut\/","name":"Bratwurst mit Tomatenkraut","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website"},"datePublished":"2011-05-11T20:46:16+00:00","dateModified":"2012-09-14T13:59:12+00:00","description":"- Bratwurst mit Tomatenkraut","breadcrumb":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/11\/bratwurst-mit-tomatenkraut\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/11\/bratwurst-mit-tomatenkraut\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/11\/bratwurst-mit-tomatenkraut\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wissen.science-and-fun.de\/kochen\/"},{"@type":"ListItem","position":2,"name":"Bratwurst mit Tomatenkraut"}]},{"@type":"WebSite","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website","url":"https:\/\/wissen.science-and-fun.de\/kochen\/","name":"Steffen&#039;s Haushaltsblog","description":"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\/ki_kunst ","publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wissen.science-and-fun.de\/kochen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8","name":"Steffen","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","caption":"Steffen"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g"},"sameAs":["https:\/\/sthomas.de","https:\/\/www.facebook.com\/steffen.thomas1","https:\/\/x.com\/steto123"],"url":"https:\/\/wissen.science-and-fun.de\/kochen\/author\/wp_admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p1tRoY-pu","jetpack-related-posts":[{"id":1574,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/11\/tomatenfleisch-mit-makkaroni\/","url_meta":{"origin":1580,"position":0},"title":"Tomatenfleisch mit Makkaroni","author":"Steffen","date":"11. Mai 2011","format":false,"excerpt":"Zubereitung: Von 350 g Schweineschulter mit Knochen, das Fleisch ausl\u00f6sen, in kochendem Salzwasser ansetzen, ann\u00e4hernd garziehen lassen, herausnehmen, portionieren und ger\u00f6stete Zwiebelscheiben dar\u00fcber geben. Von angebratenen Speckw\u00fcrfeln und Mehl eine helle Schwitze bereiten, Tomatenmark kurz mitschwitzen, mit Milch glattr\u00fchren und mit Fleischbr\u00fche zu einer s\u00e4migen Tunke auff\u00fcllen. Mit Thymian und\u2026","rel":"","context":"In &quot;Hauptgerichte&quot;","block_context":{"text":"Hauptgerichte","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1321,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/01\/pikanter-tomateneintopf\/","url_meta":{"origin":1580,"position":1},"title":"Pikanter Tomateneintopf","author":"Steffen","date":"1. Mai 2011","format":false,"excerpt":"Zutaten: 30 g magerer Speck 500 g Kartoffeln 1 Zwiebel 400 g Tomaten oder 1 Flasche Tomatenmark 1\/8 Liter Milch Salz, Zucker, Pfeffer Zubereitung: Die geschnittene Zwiebel in dem gew\u00fcrfelten ausgelassenen Speck anr\u00f6sten, die gesch\u00e4lten Kartoffelw\u00fcrfel dazugeben und mit Wasser auff\u00fcllen, Im geschlossenen Topf 15 Minuten kochen. lassen. Nun die\u2026","rel":"","context":"In &quot;Eintopf&quot;","block_context":{"text":"Eintopf","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/eintopf\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1500,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/08\/pilzsuppe\/","url_meta":{"origin":1580,"position":2},"title":"Pilzsuppe","author":"Steffen","date":"8. Mai 2011","format":false,"excerpt":"Zutaten: 1 Liter Knochenbr\u00fche 15 g getrocknete Pilze 40 g Wurzelgem\u00fcse 25 g Sonja 20 g Zwiebeln 30 g Mehl (Type W630) 3 E\u00dfl\u00f6ffel Milch frische Kr\u00e4uter Zutaten: Die eingeweichten Pilze ausdr\u00fccken, anr\u00f6sten und mit feingeschnittenen Wurzelgem\u00fcse in etwas Br\u00fche zugedeckt gard\u00fcnsten. Aus Sonja, Zwiebeln und Mehl eine helle Schwitze\u2026","rel":"","context":"In &quot;Suppe&quot;","block_context":{"text":"Suppe","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/suppe\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1597,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/12\/gebackene-fischschnitten-in-eierteig-auf-tomatenreis\/","url_meta":{"origin":1580,"position":3},"title":"Gebackene Fischschnitten in Eierteig auf Tomatenreis","author":"Steffen","date":"12. Mai 2011","format":false,"excerpt":"600 g Fischfilet teilen, mit Essig oder Zitrone sowie frischen feingehackten Kr\u00e4utern marinieren und etwa 30 Minuten stehen lassen. Aus 2 Eiern, Milch und Mehl (Type W 630) einen etwas s\u00e4migen Eierkuchenteig bereiten, die Fischschnitten darin eintauchen und im hei\u00dfen Fett schwimmend ausbacken. Tomatenreis: Aus Sonja, Zwiebeln und Mehl eine\u2026","rel":"","context":"In &quot;Fisch&quot;","block_context":{"text":"Fisch","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/fisch\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1041,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/25\/sauerkrautsuppe-mit-kabanossi\/","url_meta":{"origin":1580,"position":4},"title":"Sauerkrautsuppe mit Kabanossi","author":"Steffen","date":"25. April 2011","format":false,"excerpt":"Zutaten: 250 g durchwachsener R\u00e4ucherspeck 1 Zwiebel (70 g) 1 Knoblauchzehe 3\/4 l Fleischbr\u00fche 1\/2 Dose Sauerkraut (ca. 425g) 250 g Kasseler 1 gr\u00fcne Paprikaschote 1 El edels\u00fc\u00dfes Paprikapulver Tabasco Salz 250 g Kabanossi 1 Becher frischer Landrahm Zubereitung: Den R\u00e4ucherspeck fein w\u00fcrfeln und in einem gro\u00dfen Topf anbraten. Die\u2026","rel":"","context":"In &quot;Suppe&quot;","block_context":{"text":"Suppe","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/suppe\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2706,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/08\/25\/brotsuppe-mit-speck\/","url_meta":{"origin":1580,"position":5},"title":"Brotsuppe mit Speck","author":"Steffen","date":"25. August 2011","format":false,"excerpt":"Zutaten 1 kleine Zwiebel 25 g magerer Rauchspeck 100 g \u00e4ltere Schwarz- und Wei\u00dfbrotst\u00fccke 1 Prise K\u00fcmmel 1,5 l leichte Br\u00fche Salz Muskat 1 Ei 50 g Leberk\u00e4se Zubereitung Die Zwiebel hacken, den Speck in W\u00fcrfel schneiden. Beides in einem Topf blond anbraten. Das Brot in W\u00fcrfel schneiden und mitr\u00f6sten.\u2026","rel":"","context":"In &quot;Suppe&quot;","block_context":{"text":"Suppe","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/suppe\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/1580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/comments?post=1580"}],"version-history":[{"count":4,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/1580\/revisions"}],"predecessor-version":[{"id":4315,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/1580\/revisions\/4315"}],"wp:attachment":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/media?parent=1580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/categories?post=1580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/tags?post=1580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}