{"id":1494,"date":"2011-05-08T15:23:21","date_gmt":"2011-05-08T15:23:21","guid":{"rendered":"https:\/\/wissen.science-and-fun.de\/kochen\/?p=1494"},"modified":"2011-05-08T15:23:21","modified_gmt":"2011-05-08T15:23:21","slug":"fruchtauflauf","status":"publish","type":"post","link":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/08\/fruchtauflauf\/","title":{"rendered":"Fruchtauflauf"},"content":{"rendered":"<p><b>Zutaten:<\/b><br \/>\n125 g Sonja<br \/>\n125 g Kuchenmehl (Type W 630)<br \/>\n4 Eier<br \/>\n3\/8 l Milch<br \/>\nca. 500 g gemischte Fr\u00fcchte<\/p>\n<p>\n<b>Zubereitung:<\/b> Sonja r\u00fchrt man schaumig, gibt Mehl, Milch und 4 Eigelb dazu und schl\u00e4gt die Masse t\u00fcchtig durch. Den Eierschnee mischt man zuletzt unter den Teig. Auf den Boden einer mit Sonja ausgefetteten Auflaufform gibt man die gemischten Fr\u00fcchte ohne Saft, f\u00fcllt den Teig dar\u00fcber, gut glattstreichen und b\u00e4ckt den Auflauf ca. eine Stunde bei mittlerer Hitze in der R\u00f6hre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zutaten: 125 g Sonja 125 g Kuchenmehl (Type W 630) 4 Eier 3\/8 l Milch ca. 500 g gemischte Fr\u00fcchte Zubereitung: Sonja r\u00fchrt man schaumig, gibt Mehl, Milch und 4 Eigelb dazu und schl\u00e4gt die Masse t\u00fcchtig durch. Den Eierschnee mischt man zuletzt unter den Teig. Auf den Boden einer mit Sonja ausgefetteten Auflaufform gibt &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/08\/fruchtauflauf\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[190],"tags":[],"class_list":["post-1494","post","type-post","status-publish","format-standard","hentry","category-susspeise","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fruchtauflauf<\/title>\n<meta name=\"description\" content=\"- Fruchtauflauf\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/08\/fruchtauflauf\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fruchtauflauf\" \/>\n<meta property=\"og:description\" content=\"- Fruchtauflauf\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/08\/fruchtauflauf\/\" \/>\n<meta property=\"og:site_name\" content=\"Steffen&#039;s Haushaltsblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:published_time\" content=\"2011-05-08T15:23:21+00:00\" \/>\n<meta name=\"author\" content=\"Steffen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steffen\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/08\\\/fruchtauflauf\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/08\\\/fruchtauflauf\\\/\"},\"author\":{\"name\":\"Steffen\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"headline\":\"Fruchtauflauf\",\"datePublished\":\"2011-05-08T15:23:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/08\\\/fruchtauflauf\\\/\"},\"wordCount\":83,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"articleSection\":[\"S\u00fc\u00dfspeise\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/08\\\/fruchtauflauf\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/08\\\/fruchtauflauf\\\/\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/08\\\/fruchtauflauf\\\/\",\"name\":\"Fruchtauflauf\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\"},\"datePublished\":\"2011-05-08T15:23:21+00:00\",\"description\":\"- Fruchtauflauf\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/08\\\/fruchtauflauf\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/08\\\/fruchtauflauf\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/05\\\/08\\\/fruchtauflauf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fruchtauflauf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\",\"name\":\"Steffen&#039;s Haushaltsblog\",\"description\":\"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\\\/ki_kunst \",\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\",\"name\":\"Steffen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"caption\":\"Steffen\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/sthomas.de\",\"https:\\\/\\\/www.facebook.com\\\/steffen.thomas1\",\"https:\\\/\\\/x.com\\\/steto123\"],\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/author\\\/wp_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fruchtauflauf","description":"- Fruchtauflauf","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/08\/fruchtauflauf\/","og_locale":"de_DE","og_type":"article","og_title":"Fruchtauflauf","og_description":"- Fruchtauflauf","og_url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/08\/fruchtauflauf\/","og_site_name":"Steffen&#039;s Haushaltsblog","article_publisher":"https:\/\/www.facebook.com\/steffen.thomas1","article_author":"https:\/\/www.facebook.com\/steffen.thomas1","article_published_time":"2011-05-08T15:23:21+00:00","author":"Steffen","twitter_misc":{"Verfasst von":"Steffen"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/08\/fruchtauflauf\/#article","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/08\/fruchtauflauf\/"},"author":{"name":"Steffen","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"headline":"Fruchtauflauf","datePublished":"2011-05-08T15:23:21+00:00","mainEntityOfPage":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/08\/fruchtauflauf\/"},"wordCount":83,"commentCount":0,"publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"articleSection":["S\u00fc\u00dfspeise"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/08\/fruchtauflauf\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/08\/fruchtauflauf\/","url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/08\/fruchtauflauf\/","name":"Fruchtauflauf","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website"},"datePublished":"2011-05-08T15:23:21+00:00","description":"- Fruchtauflauf","breadcrumb":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/08\/fruchtauflauf\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/08\/fruchtauflauf\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/08\/fruchtauflauf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wissen.science-and-fun.de\/kochen\/"},{"@type":"ListItem","position":2,"name":"Fruchtauflauf"}]},{"@type":"WebSite","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website","url":"https:\/\/wissen.science-and-fun.de\/kochen\/","name":"Steffen&#039;s Haushaltsblog","description":"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\/ki_kunst ","publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wissen.science-and-fun.de\/kochen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8","name":"Steffen","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","caption":"Steffen"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g"},"sameAs":["https:\/\/sthomas.de","https:\/\/www.facebook.com\/steffen.thomas1","https:\/\/x.com\/steto123"],"url":"https:\/\/wissen.science-and-fun.de\/kochen\/author\/wp_admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p1tRoY-o6","jetpack-related-posts":[{"id":1461,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/07\/wurstchen-in-murbeteig\/","url_meta":{"origin":1494,"position":0},"title":"W\u00fcrstchen in M\u00fcrbeteig","author":"Steffen","date":"7. Mai 2011","format":false,"excerpt":"Auf einem Backbrett verknetet man 125 g Kuchenmehl (Type W 630). 100 g Sonja und 1 Ei mit etwas Salz zu einem festen Teig, den man etwa 1cm dick ausrollt. Man schneidet rechteckige St\u00fccke und rollt in jedes ein W\u00fcrstchen und dr\u00fcckt die Enden gut zu. Man legt die Wurstr\u00f6llchen\u2026","rel":"","context":"In &quot;Snack&quot;","block_context":{"text":"Snack","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/snack\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1510,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/09\/eierragout-mit-pilzen\/","url_meta":{"origin":1494,"position":1},"title":"Eierragout mit Pilzen","author":"Steffen","date":"9. Mai 2011","format":false,"excerpt":"Zutaten 4 harte Eier 200 g Pilze 20 g fette Speckw\u00fcrfel 20 g Sonja 20 g Zwiebeln 30 g Mehl (Type W 630) Milch Wasser oder Br\u00fche Wei\u00dfwein Senf Petersilie Zubereitung Vier harte Eier in Viertel teilen. 200 g Pilze verlesen, putzen und waschen, kleinschneiden und gard\u00fcnsten. Aus 20 g\u2026","rel":"","context":"In &quot;Eiergerichte&quot;","block_context":{"text":"Eiergerichte","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/eiergerichte\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1514,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/09\/selleriesuppe\/","url_meta":{"origin":1494,"position":2},"title":"Selleriesuppe","author":"Steffen","date":"9. Mai 2011","format":false,"excerpt":"Zutaten: 1Liter Knochenbr\u00fche 125 g Sellerieknolle 25 g Sonja 20 g Zwiebeln 30 g Mehl (Type W 630) 6 EL Milch Sellerielaub Koriander (Muskat) Zubereitung: Aus Sonja, Zwiebeln und Mehl eine helle Schwitze bereiten, mit Milch glattr\u00fchren und mit Br\u00fche auff\u00fcllen. Die Sellerieknollen b\u00fcrsten, waschen und sch\u00e4len, die H\u00e4lfte davon\u2026","rel":"","context":"In &quot;Suppe&quot;","block_context":{"text":"Suppe","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/suppe\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1578,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/11\/ei-mit-senftunke-senfei\/","url_meta":{"origin":1494,"position":3},"title":"Ei mit Senftunke (Senfei)","author":"Steffen","date":"11. Mai 2011","format":false,"excerpt":"Zutaten: 25 g Sonja 20 g Zwiebeln 30 g Mehl (Type W 630) 1\/2 l Knochenbr\u00fche 6 EL Milch 40 g Senf Basilikum (Lorbeer) Koriander (Muskat) Essig Zucker Eier Zubereitung: Aus Sonja, Zwiebeln und Mehl eine helle Schwitze bereiten, mit Milch glattr\u00fchren, mit Knochenbr\u00fche auff\u00fcllen und mit Gew\u00fcrzen abschmecken. Den\u2026","rel":"","context":"In &quot;Eiergerichte&quot;","block_context":{"text":"Eiergerichte","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/eiergerichte\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1359,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/02\/haferflockenauflauf\/","url_meta":{"origin":1494,"position":4},"title":"Haferflockenauflauf","author":"Steffen","date":"2. Mai 2011","format":false,"excerpt":"Aus 1\/4 Liter Milch mit 125 g Haferflocken unter Dazugabe von 1 Prise Salz einen Brei kochen. 30 g Margarine mit 50 g Zucker und 3 Eigelb schaumig r\u00fchren und dem ausgek\u00fchlten Haferflockenbrei nach und nach hinzuf\u00fcgen. Die 3 Eiwei\u00df zu Schnee schlagen und unterr\u00fchren. Den Auflauf etwa 45 Minuten\u2026","rel":"","context":"In &quot;Auflauf&quot;","block_context":{"text":"Auflauf","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/auflauf\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1572,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/11\/schweizer-schnitzel-mit-rahmtunke\/","url_meta":{"origin":1494,"position":5},"title":"Schweizer Schnitzel mit Rahmtunke","author":"Steffen","date":"11. Mai 2011","format":false,"excerpt":"Zubereitung: 4 magere Fleischscheiben klopfen und mit etwas Paprika w\u00fcrzen, 125 g in rechteckige, nicht zu starke Scheiben geschnittenen K\u00e4se auf die Fleischscheiben legen, die Seiten zusammenklappen, festdr\u00fccken, in Mehl w\u00e4lzen und in sch\u00e4umender Sonja goldgelb braten. Rahmtunke: Im Bratfett Mehl (Type W 630) anr\u00f6sten; Tomatenmark zugeben, kurz mit angehen\u2026","rel":"","context":"In &quot;Hauptgerichte&quot;","block_context":{"text":"Hauptgerichte","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/1494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/comments?post=1494"}],"version-history":[{"count":1,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/1494\/revisions"}],"predecessor-version":[{"id":1495,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/1494\/revisions\/1495"}],"wp:attachment":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/media?parent=1494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/categories?post=1494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/tags?post=1494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}