{"id":1168,"date":"2011-04-30T10:43:50","date_gmt":"2011-04-30T10:43:50","guid":{"rendered":"https:\/\/wissen.science-and-fun.de\/kochen\/?p=1168"},"modified":"2011-04-30T10:43:50","modified_gmt":"2011-04-30T10:43:50","slug":"karpfen-in-biersosse","status":"publish","type":"post","link":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/30\/karpfen-in-biersosse\/","title":{"rendered":"Karpfen in Biersosse"},"content":{"rendered":"<p><b><i>Zutaten:<\/i><\/b><br \/>\n1 mittelgro\u00dfer Karpfen<br \/>\netwas Salz<br \/>\netwas Essig <br \/>\n2 Zwiebeln<br \/>\nZitronenschale <br \/>\n1 Mohrr\u00fcbe<br \/>\n1 Lorbeerblatt<br \/>\n3\/4 Liter dunkles Bier <br \/>\n100 g Honigkuchen <br \/>\n1 Essl\u00f6ffel Butter<br \/>\n1 Essl\u00f6ffel Mehl<br \/>\netwas Zucker<br \/>\netwas Zitronensaft<\/p>\n<p>\n<b>Zubereitung: <\/b><br \/>Karpfen ausnehmen, schuppen, waschen, in Scheiben schneiden und salzen; beiseite stellen (Wenn m\u00f6glich das Blut des Karpfen auffangen). Zwiebeln sch\u00e4len und in Scheiben schneiden, Zitronenschale grob st\u00fcckeln, Mohrr\u00fcbe schaben und in Scheiben schneiden. Alles auf dem Boden eines Braters verteilen. Fischst\u00fccke auflegen. Lorbeerblatt und Nelke dazu. An der Seite 3\/4 des Bieres hinzugie\u00dfen. Honigkuchen zerkr\u00fcmeln und ebenfalls zugeben. Zugedeckt zum Kochen bringen und etwa 15- 20 Minuten schwach k\u00f6cheln lassen. Inzwischen in der Butter das Mehl dunkel r\u00f6sten. Mit dem restlichen Bier abl\u00f6schen Blut und Essig damit verquirlen und zu den Karpfenst\u00fccken geben mitkochen. Sobald die Fischst\u00fccke gar sind, nimmt man sie heraus und h\u00e4lt sie warm. Sauce durch ein Sieb gie\u00dfen &#8211; bzw. durchpassieren, falls der Honigkuchen noch nicht ganz verkocht sein sollte. Abschmecken mit etwas Zucker. Die Sauce nochmals aufkochen und \u00fcber die Karpfenst\u00fccke gie\u00dfen &#8211; einen Teil der Sauce separat servieren. Zu diesem Gericht werden traditionell Salzkartoffeln gereicht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zutaten: 1 mittelgro\u00dfer Karpfen etwas Salz etwas Essig 2 Zwiebeln Zitronenschale 1 Mohrr\u00fcbe 1 Lorbeerblatt 3\/4 Liter dunkles Bier 100 g Honigkuchen 1 Essl\u00f6ffel Butter 1 Essl\u00f6ffel Mehl etwas Zucker etwas Zitronensaft Zubereitung: Karpfen ausnehmen, schuppen, waschen, in Scheiben schneiden und salzen; beiseite stellen (Wenn m\u00f6glich das Blut des Karpfen auffangen). Zwiebeln sch\u00e4len und in &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/30\/karpfen-in-biersosse\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[19,6],"tags":[110,271],"class_list":["post-1168","post","type-post","status-publish","format-standard","hentry","category-fisch","category-hauptgerichte","tag-bier","tag-karpfen","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Karpfen in Biersosse<\/title>\n<meta name=\"description\" content=\"- Karpfen in Biersosse\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/30\/karpfen-in-biersosse\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Karpfen in Biersosse\" \/>\n<meta property=\"og:description\" content=\"- Karpfen in Biersosse\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/30\/karpfen-in-biersosse\/\" \/>\n<meta property=\"og:site_name\" content=\"Steffen&#039;s Haushaltsblog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/steffen.thomas1\" \/>\n<meta property=\"article:published_time\" content=\"2011-04-30T10:43:50+00:00\" \/>\n<meta name=\"author\" content=\"Steffen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steffen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/04\\\/30\\\/karpfen-in-biersosse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/04\\\/30\\\/karpfen-in-biersosse\\\/\"},\"author\":{\"name\":\"Steffen\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"headline\":\"Karpfen in Biersosse\",\"datePublished\":\"2011-04-30T10:43:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/04\\\/30\\\/karpfen-in-biersosse\\\/\"},\"wordCount\":197,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"keywords\":[\"Bier\",\"Karpfen\"],\"articleSection\":[\"Fisch\",\"Hauptgerichte\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/04\\\/30\\\/karpfen-in-biersosse\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/04\\\/30\\\/karpfen-in-biersosse\\\/\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/04\\\/30\\\/karpfen-in-biersosse\\\/\",\"name\":\"Karpfen in Biersosse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\"},\"datePublished\":\"2011-04-30T10:43:50+00:00\",\"description\":\"- Karpfen in Biersosse\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/04\\\/30\\\/karpfen-in-biersosse\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/04\\\/30\\\/karpfen-in-biersosse\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/2011\\\/04\\\/30\\\/karpfen-in-biersosse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Karpfen in Biersosse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#website\",\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/\",\"name\":\"Steffen&#039;s Haushaltsblog\",\"description\":\"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\\\/ki_kunst \",\"publisher\":{\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/#\\\/schema\\\/person\\\/910dc13be3cb31f39d8707d607e929e8\",\"name\":\"Steffen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\",\"caption\":\"Steffen\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/sthomas.de\",\"https:\\\/\\\/www.facebook.com\\\/steffen.thomas1\",\"https:\\\/\\\/x.com\\\/steto123\"],\"url\":\"https:\\\/\\\/wissen.science-and-fun.de\\\/kochen\\\/author\\\/wp_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Karpfen in Biersosse","description":"- Karpfen in Biersosse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/30\/karpfen-in-biersosse\/","og_locale":"de_DE","og_type":"article","og_title":"Karpfen in Biersosse","og_description":"- Karpfen in Biersosse","og_url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/30\/karpfen-in-biersosse\/","og_site_name":"Steffen&#039;s Haushaltsblog","article_publisher":"https:\/\/www.facebook.com\/steffen.thomas1","article_author":"https:\/\/www.facebook.com\/steffen.thomas1","article_published_time":"2011-04-30T10:43:50+00:00","author":"Steffen","twitter_misc":{"Verfasst von":"Steffen","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/30\/karpfen-in-biersosse\/#article","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/30\/karpfen-in-biersosse\/"},"author":{"name":"Steffen","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"headline":"Karpfen in Biersosse","datePublished":"2011-04-30T10:43:50+00:00","mainEntityOfPage":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/30\/karpfen-in-biersosse\/"},"wordCount":197,"commentCount":0,"publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"keywords":["Bier","Karpfen"],"articleSection":["Fisch","Hauptgerichte"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/30\/karpfen-in-biersosse\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/30\/karpfen-in-biersosse\/","url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/30\/karpfen-in-biersosse\/","name":"Karpfen in Biersosse","isPartOf":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website"},"datePublished":"2011-04-30T10:43:50+00:00","description":"- Karpfen in Biersosse","breadcrumb":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/30\/karpfen-in-biersosse\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/30\/karpfen-in-biersosse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/04\/30\/karpfen-in-biersosse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wissen.science-and-fun.de\/kochen\/"},{"@type":"ListItem","position":2,"name":"Karpfen in Biersosse"}]},{"@type":"WebSite","@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#website","url":"https:\/\/wissen.science-and-fun.de\/kochen\/","name":"Steffen&#039;s Haushaltsblog","description":"Kunst trifft Essen - Viele Bilder sind KI Kreationen und keine realen Abbildungen. - t.me\/ki_kunst ","publisher":{"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wissen.science-and-fun.de\/kochen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/wissen.science-and-fun.de\/kochen\/#\/schema\/person\/910dc13be3cb31f39d8707d607e929e8","name":"Steffen","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g","caption":"Steffen"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/6ff13dd29c0d1b8a17460ca74a1e0eee159c14d00728cf5e1a7ee30f8ffdf195?s=96&d=mm&r=g"},"sameAs":["https:\/\/sthomas.de","https:\/\/www.facebook.com\/steffen.thomas1","https:\/\/x.com\/steto123"],"url":"https:\/\/wissen.science-and-fun.de\/kochen\/author\/wp_admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p1tRoY-iQ","jetpack-related-posts":[{"id":1604,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/12\/karpfen-auf-budapester-art\/","url_meta":{"origin":1168,"position":0},"title":"Karpfen auf Budapester Art","author":"Steffen","date":"12. Mai 2011","format":false,"excerpt":"Zutaten: 1 kg Karpfen 125 g Sonja 1\/4 Flasche Wei\u00dfwein 25 g M\u00f6hren 25 g Sellerie 25 g Porree 25 g Kohlrabi (wenn vorhanden) 50 g Zwiebeln Wurzelwerk Petersilie Lorbeerblatt Salz Zitrone Gew\u00fcrzk\u00f6rner Zubereitung: Das Gem\u00fcse wird in Streifen geschnitten oder geraspelt und in Sonja angeschwitzt. Den gereinigten und in\u2026","rel":"","context":"In &quot;Fisch&quot;","block_context":{"text":"Fisch","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/fisch\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1611,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/12\/karpfensuppe\/","url_meta":{"origin":1168,"position":1},"title":"Karpfensuppe","author":"Steffen","date":"12. Mai 2011","format":false,"excerpt":"Man legt Kopf und Schwanz eines 1,5 kg schweren Karpfens in eine Kasserolle mit 11\/2 l Wasser gibt 200 g in Scheiben geschnittene Zwiebeln und Salz je nach Geschmack hinzu und l\u00e4sst alles 11\/2 Stunden kochen. Hierauf wird das Ganze durchgeseiht, wieder aufs Feuer gestellt, und nachdem es anf\u00e4ngt zu\u2026","rel":"","context":"In &quot;Suppe&quot;","block_context":{"text":"Suppe","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/suppe\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3723,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/02\/04\/pilze-auf-wild-art-z\/","url_meta":{"origin":1168,"position":2},"title":"Pilze auf Wild-Art zubereitet","author":"Steffen","date":"4. Februar 2012","format":false,"excerpt":"Zutaten 500 g Pilze 2 Mohrr\u00fcben 2 Zwiebeln 1 Petersilienwurzel Salz Lorbeerblatt Pfefferk\u00f6rner Essig 3 W\u00fcrfelzucker 2 EL Fett 2 EL Mehl 1\/2 Zitrone 200 ml saure Sahne Zubereitung Die Mohrr\u00fcben werden mit den Zwiebeln, Salz, Lorbeerblatt, Pfeffer, ein paar Tropfen Essig und soviel Wasser, dass alles eben bedeckt ist,\u2026","rel":"","context":"In &quot;Gem\u00fcse &amp; Obst&quot;","block_context":{"text":"Gem\u00fcse &amp; Obst","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/gemuse\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1286,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2011\/05\/01\/karpfen-gebacken-auf-franzosische-art\/","url_meta":{"origin":1168,"position":3},"title":"Karpfen gebacken auf franz\u00f6sische Art","author":"Steffen","date":"1. Mai 2011","format":false,"excerpt":"Den geschuppten Karpfen spalten, in St\u00fccke schneiden, dieselben in einer Marinade aus Weinessig, Lorbeerbl\u00e4ttern, Pfeffer- und Gew\u00fcrzk\u00f6rnern eine Stunde marinieren, dann herausnehmen, salzen, in Mehl wenden und in siedendem \u00d6l backen. Mit gehackter Petersilie bestreuen und mit Kartoffelsalat zu Tisch geben.","rel":"","context":"In &quot;Fisch&quot;","block_context":{"text":"Fisch","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/fisch\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5107,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2013\/02\/19\/panierte-schweinebacken\/","url_meta":{"origin":1168,"position":4},"title":"Panierte Schweinebacken","author":"Steffen","date":"19. Februar 2013","format":false,"excerpt":"Zutaten P\u00f6keln 50 g P\u00f6kelsalz 1 Prise Zucker 1-2 Knoblauchzehen 5 Korianderk\u00f6rner 1 Prise Ganzer K\u00fcmmel 1-2 Angedr\u00fcckte Wacholderbeeren 1 Lorbeerblatt 2 Scheiben Frischer Ingwer 1 Streifen Unbehandelte Zitronenschale 4 Schweinebacken (ausgel\u00f6st) Sud 1 M\u00f6hre 150 g Knollensellerie 1\/2 Zwiebel 1 Lorbeerblatt 2 Nelken 3\/4 l Gem\u00fcsebr\u00fche 2 Pimentk\u00f6rner Panade\u2026","rel":"","context":"In &quot;Hauptgerichte&quot;","block_context":{"text":"Hauptgerichte","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/hauptgerichte\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4317,"url":"https:\/\/wissen.science-and-fun.de\/kochen\/2012\/09\/14\/gedampfter-fluskarpfen\/","url_meta":{"origin":1168,"position":5},"title":"Ged\u00e4mpfter Flu\u00dfkarpfen","author":"Steffen","date":"14. September 2012","format":false,"excerpt":"Zutaten 1 kleine Karpfen ca. 900 g, ersatzweise Graskarpfen Salz Pfeffer f.a.d.M. 2 Tl. Reiswein 40 g M\u00f6hren 40 g Gurke 1 rote Paprikaschote 40 g Lauch nur wei\u00dfe Teile 30 g Ingwerwurzel 20 - 30 g 150 ml H\u00fchnerbr\u00fche Salatbl\u00e4tter zum Anrichten Zubereitung Den Karpfen gegebenenfalls ausnehmen. Dazu den\u2026","rel":"","context":"In &quot;Asiatisch&quot;","block_context":{"text":"Asiatisch","link":"https:\/\/wissen.science-and-fun.de\/kochen\/category\/asiatisch\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/1168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/comments?post=1168"}],"version-history":[{"count":1,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/1168\/revisions"}],"predecessor-version":[{"id":1169,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/posts\/1168\/revisions\/1169"}],"wp:attachment":[{"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/media?parent=1168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/categories?post=1168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wissen.science-and-fun.de\/kochen\/wp-json\/wp\/v2\/tags?post=1168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}